{"id":2317,"date":"2025-06-29T20:25:32","date_gmt":"2025-06-30T03:25:32","guid":{"rendered":"https:\/\/fshualinkeji.com\/?page_id=2317"},"modified":"2025-06-29T23:26:04","modified_gmt":"2025-06-30T06:26:04","slug":"%d8%a7%d9%84%d8%a3%d9%86%d8%a7%d8%a8%d9%8a%d8%a8-%d8%a7%d9%84%d8%a8%d9%84%d8%a7%d8%b3%d8%aa%d9%8a%d9%83%d9%8a%d8%a9","status":"publish","type":"page","link":"https:\/\/fshualinkeji.com\/ar\/%d8%a7%d9%84%d8%a3%d9%86%d8%a7%d8%a8%d9%8a%d8%a8-%d8%a7%d9%84%d8%a8%d9%84%d8%a7%d8%b3%d8%aa%d9%8a%d9%83%d9%8a%d8%a9\/","title":{"rendered":"\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-90c2c68b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-42e0e8e6\">\n<div class=\"wp-block-uagb-container uagb-block-3de41139\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1f746054\"><h2 class=\"uagb-heading-text\">\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629<\/h2><\/div>\n\n\n\n<p class=\"has-ast-global-color-5-color has-text-color has-link-color wp-elements-f7b831727cc3ccda7ae20bb8f767f4e9\" style=\"font-size:16px\">\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0647\u064a \u0623\u0646\u0627\u0628\u064a\u0628 \u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0645\u0635\u0646\u0648\u0639\u0629 \u0645\u0646 \u0631\u0627\u062a\u0646\u062c \u0643\u0644\u0648\u0631\u064a\u062f \u0627\u0644\u0628\u0648\u0644\u064a\u0641\u064a\u0646\u064a\u0644 \u0643\u0645\u0627\u062f\u0629 \u062e\u0627\u0645 \u0631\u0626\u064a\u0633\u064a\u0629 \u0648\u064a\u062a\u0645 \u062a\u0634\u0643\u064a\u0644\u0647\u0627 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0628\u062b\u0642.<\/p>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-ccbe86b2 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-ccbe86b2 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8d2e6c49\"><h2 class=\"uagb-heading-text\">\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/h2><\/div>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_1\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_input_text' id='label_ff_2_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_email' id='label_ff_2_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_phone' id='label_ff_2_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_description' id='label_ff_2_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_description\" name=\"description\" id=\"ff_2_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_1 ff-form-loading_errors ff_form_instance_2_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_1 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_1\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f0aa5aa3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-421ce500\"><h2 class=\"uagb-heading-text\">\u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0645\u0635\u0646\u0639\u0629 \u0644\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0641\u064a \u0627\u0644\u0635\u064a\u0646<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">\u062a\u064f\u0635\u0646\u0639 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0645\u0646 \u0631\u0627\u062a\u0646\u062c \u0627\u0644\u0628\u0648\u0644\u064a \u0641\u064a\u0646\u064a\u0644 \u0643\u0644\u0648\u0631\u064a\u062f \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0641\u064a\u0646\u064a\u0644 \u0648\u0645\u0648\u0627\u062f \u0645\u0636\u0627\u0641\u0629 \u0645\u062e\u062a\u0644\u0641\u0629\u060c \u0648\u064a\u062a\u0645 \u0628\u062b\u0642\u0647\u0627 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0643\u0628\u0633 \u0639\u0644\u0649 \u0627\u0644\u0633\u0627\u062e\u0646\u060c \u062b\u0645 \u062a\u0645\u0631 \u0628\u0633\u0644\u0633\u0644\u0629 \u0645\u0646 \u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0645\u062b\u0644 \u0627\u0644\u062a\u0628\u0631\u064a\u062f \u0648\u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0629 \u0648\u0627\u0644\u062a\u0634\u0643\u064a\u0644 \u0648\u0627\u0644\u0641\u062d\u0635 \u0648\u0627\u0644\u062a\u0639\u0628\u0626\u0629 \u0642\u0628\u0644 \u0623\u0646 \u062a\u0635\u0628\u062d \u0641\u064a \u0627\u0644\u0646\u0647\u0627\u064a\u0629 \u0623\u0646\u0627\u0628\u064a\u0628.<\/p>\n\n\n\n<p style=\"font-size:16px\">\u0641\u064a HUALIN\u060c \u064a\u0645\u0643\u0646\u0646\u0627 \u0641\u064a HUALIN \u0623\u0646 \u0646\u0635\u0646\u0639 \u0623\u0646\u0627\u0628\u064a\u0628 PVC \u062d\u0633\u0628 \u0627\u0644\u0637\u0644\u0628 \u0648\u0641\u0642\u064b\u0627 \u0644\u0645\u0648\u0627\u0635\u0641\u0627\u062a\u0643 \u0627\u0644\u062f\u0642\u064a\u0642\u0629. \u064a\u0645\u0643\u0646\u0646\u0627 \u062a\u062e\u0635\u064a\u0635 \u0623\u0644\u0648\u0627\u0646 \u0623\u0648 \u0627\u0631\u062a\u0641\u0627\u0639\u0627\u062a \u0623\u0648 \u0639\u0631\u0648\u0636 \u0623\u0648 \u0623\u0639\u0645\u0627\u0642 \u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u062a\u0646\u0627\u0633\u0628 \u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0648\u0645\u062a\u0637\u0644\u0628\u0627\u062a \u0645\u062d\u062f\u062f\u0629. \u0643\u0645\u0627 \u0646\u0642\u062f\u0645 \u0623\u064a\u0636\u064b\u0627 \u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u062a\u0646\u0648\u0639\u0629 \u0645\u0646 \u062e\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0645\u0648\u0627\u062f \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0648\u0627\u0644\u0628\u0648\u0644\u064a \u0641\u064a\u0646\u064a\u0644 \u0643\u0644\u0648\u0631\u064a\u062f \u0648\u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646 \u0648\u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646 \u0639\u0627\u0644\u064a \u0627\u0644\u0643\u062b\u0627\u0641\u0629 \u0648\u0627\u0644\u0628\u0648\u0644\u064a \u0628\u0631\u0648\u0628\u064a\u0644\u064a\u0646 \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0643\u0644\u0648\u0631 \u0648\u063a\u064a\u0631\u0647\u0627.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b31ce7bf alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7499abf3\"><h2 class=\"uagb-heading-text\">\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ed0f7e26\">\n<div class=\"wp-block-uagb-container uagb-block-dd817a82\">\n<div class=\"wp-block-uagb-container uagb-block-5c073af6\">\n<div class=\"wp-block-uagb-image uagb-block-a4d3fb33 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg\" alt=\"\" class=\"uag-image-2321\" width=\"600\" height=\"400\" title=\"\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0645\u064a\u0627\u0647 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5860e71a\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7c1dd511\"><p class=\"uagb-heading-text\">\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0645\u064a\u0627\u0647 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-048f0bfe uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-048f0bfe uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_2 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_2\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_2_input_text' id='label_ff_2_2_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_2_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_2_email' id='label_ff_2_2_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_2_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_2_phone' id='label_ff_2_2_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_2_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_2_description' id='label_ff_2_2_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_2_description\" name=\"description\" id=\"ff_2_2_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_2 ff-form-loading_errors ff_form_instance_2_2_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_2 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_2\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e8342395\">\n<div class=\"wp-block-uagb-container uagb-block-5f80ca2c\">\n<div class=\"wp-block-uagb-image uagb-block-1fea2c99 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-C-Fire-Hose.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-C-Fire-Hose.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-C-Fire-Hose.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-C-Fire-Hose.jpg\" alt=\"\" class=\"uag-image-2324\" width=\"600\" height=\"400\" title=\"\u062e\u0631\u0637\u0648\u0645 \u0627\u0644\u062d\u0631\u064a\u0642 PVC-C\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a1a2f46d\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8b077f06\"><p class=\"uagb-heading-text\">\u062e\u0631\u0637\u0648\u0645 \u0627\u0644\u062d\u0631\u064a\u0642 PVC-C<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-dd0fd90b uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-dd0fd90b uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_3 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_3\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_3_input_text' id='label_ff_2_3_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_3_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_3_email' id='label_ff_2_3_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_3_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_3_phone' id='label_ff_2_3_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_3_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_3_description' id='label_ff_2_3_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_3_description\" name=\"description\" id=\"ff_2_3_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_3 ff-form-loading_errors ff_form_instance_2_3_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_3 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_3\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8b4134ba\">\n<div class=\"wp-block-uagb-container uagb-block-c415eb6d\">\n<div class=\"wp-block-uagb-image uagb-block-eac8718a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-irrigation-pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-irrigation-pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-irrigation-pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-irrigation-pipe.jpg\" alt=\"\" class=\"uag-image-2326\" width=\"600\" height=\"400\" title=\"\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0631\u064a \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-44ca3756\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-49a103f3\"><p class=\"uagb-heading-text\">\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0631\u064a \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-fce33136 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-fce33136 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_4 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_4\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_4_input_text' id='label_ff_2_4_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_4_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_4_email' id='label_ff_2_4_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_4_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_4_phone' id='label_ff_2_4_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_4_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_4_description' id='label_ff_2_4_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_4_description\" name=\"description\" id=\"ff_2_4_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_4 ff-form-loading_errors ff_form_instance_2_4_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_4 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_4\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-888e8130\">\n<div class=\"wp-block-uagb-container uagb-block-bfe84470\">\n<div class=\"wp-block-uagb-container uagb-block-faee79c9\">\n<div class=\"wp-block-uagb-image uagb-block-9e35ac0a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-power-protection-tube.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-power-protection-tube.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-power-protection-tube.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-power-protection-tube.jpg\" alt=\"\" class=\"uag-image-2329\" width=\"600\" height=\"400\" title=\"\u0623\u0646\u0628\u0648\u0628 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0637\u0627\u0642\u0629 PVC\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ef654185\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0425b1ba\"><p class=\"uagb-heading-text\">\u0623\u0646\u0628\u0648\u0628 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0637\u0627\u0642\u0629 PVC<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-01a9aad7 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-01a9aad7 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_5 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_5\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_5_input_text' id='label_ff_2_5_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_5_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_5_email' id='label_ff_2_5_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_5_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_5_phone' id='label_ff_2_5_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_5_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_5_description' id='label_ff_2_5_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_5_description\" name=\"description\" id=\"ff_2_5_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_5 ff-form-loading_errors ff_form_instance_2_5_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_5 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_5\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9a24f401\">\n<div class=\"wp-block-uagb-container uagb-block-fcc017ed\">\n<div class=\"wp-block-uagb-image uagb-block-6f089be0 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-perforated-pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-perforated-pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-perforated-pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-perforated-pipe.jpg\" alt=\"\" class=\"uag-image-2331\" width=\"600\" height=\"400\" title=\"\u0623\u0646\u0627\u0628\u064a\u0628 PVC \u0627\u0644\u0645\u062b\u0642\u0628\u0629\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-92766771\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d9cdac4f\"><p class=\"uagb-heading-text\">\u0623\u0646\u0627\u0628\u064a\u0628 PVC \u0627\u0644\u0645\u062b\u0642\u0628\u0629<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-11964555 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-11964555 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_6 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_6\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_6_input_text' id='label_ff_2_6_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_6_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_6_email' id='label_ff_2_6_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_6_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_6_phone' id='label_ff_2_6_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_6_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_6_description' id='label_ff_2_6_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_6_description\" name=\"description\" id=\"ff_2_6_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_6 ff-form-loading_errors ff_form_instance_2_6_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_6 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_6\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b283be7b\">\n<div class=\"wp-block-uagb-container uagb-block-eeaba153\">\n<div class=\"wp-block-uagb-image uagb-block-056687a0 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-sewage-pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-sewage-pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-sewage-pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-sewage-pipe.jpg\" alt=\"\" class=\"uag-image-2334\" width=\"600\" height=\"400\" title=\"\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0635\u0631\u0641 \u0627\u0644\u0635\u062d\u064a \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-fefed838\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5ae07438\"><p class=\"uagb-heading-text\">\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0635\u0631\u0641 \u0627\u0644\u0635\u062d\u064a \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-7b2caf4a uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-7b2caf4a uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_7 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_7\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_7_input_text' id='label_ff_2_7_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_7_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_7_email' id='label_ff_2_7_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_7_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_7_phone' id='label_ff_2_7_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_7_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_7_description' id='label_ff_2_7_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_7_description\" name=\"description\" id=\"ff_2_7_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_7 ff-form-loading_errors ff_form_instance_2_7_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_7 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_7\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-bf8bfd11\">\n<div class=\"wp-block-uagb-container uagb-block-8a494c20\">\n<div class=\"wp-block-uagb-container uagb-block-ee716a0b\">\n<div class=\"wp-block-uagb-image uagb-block-ea1fb0fa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-cable-protection-tube.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-cable-protection-tube.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-cable-protection-tube.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-cable-protection-tube.jpg\" alt=\"\" class=\"uag-image-2345\" width=\"600\" height=\"400\" title=\"\u0623\u0646\u0628\u0648\u0628 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0643\u0627\u0628\u0644\u0627\u062a \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9414a69a\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-071dea48\"><p class=\"uagb-heading-text\">\u0623\u0646\u0628\u0648\u0628 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0643\u0627\u0628\u0644\u0627\u062a \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-3705820d uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-3705820d uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_8 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_8\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_8_input_text' id='label_ff_2_8_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_8_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_8_email' id='label_ff_2_8_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_8_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_8_phone' id='label_ff_2_8_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_8_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_8_description' id='label_ff_2_8_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_8_description\" name=\"description\" id=\"ff_2_8_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_8 ff-form-loading_errors ff_form_instance_2_8_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_8 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_8\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ad29aca7\">\n<div class=\"wp-block-uagb-container uagb-block-bfb6dbe1\">\n<div class=\"wp-block-uagb-image uagb-block-4a496e62 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/White-PVC-pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/White-PVC-pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/White-PVC-pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/White-PVC-pipe.jpg\" alt=\"\" class=\"uag-image-2365\" width=\"600\" height=\"400\" title=\"\u0623\u0646\u0627\u0628\u064a\u0628 \u0628\u064a\u0636\u0627\u0621-\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629-\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-18ba2212\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4c5c8765\"><p class=\"uagb-heading-text\">\u0623\u0646\u0628\u0648\u0628 PVC \u0623\u0628\u064a\u0636<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-f7727bc4 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-f7727bc4 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_9 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_9\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_9_input_text' id='label_ff_2_9_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_9_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_9_email' id='label_ff_2_9_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_9_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_9_phone' id='label_ff_2_9_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_9_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_9_description' id='label_ff_2_9_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_9_description\" name=\"description\" id=\"ff_2_9_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_9 ff-form-loading_errors ff_form_instance_2_9_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_9 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_9\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ef797863\">\n<div class=\"wp-block-uagb-container uagb-block-dfc50cce\">\n<div class=\"wp-block-uagb-image uagb-block-41177162 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-threading-pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-threading-pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-threading-pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/PVC-threading-pipe.jpg\" alt=\"\" class=\"uag-image-2367\" width=\"600\" height=\"400\" title=\"\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u062e\u064a\u0648\u0637 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0627\u0644\u0645\u0644\u0648\u0644\u0628\u0629\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f57a0b8e\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-48c1b815\"><p class=\"uagb-heading-text\">\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u062e\u064a\u0648\u0637 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0627\u0644\u0645\u0644\u0648\u0644\u0628\u0629<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-58d8d430 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-58d8d430 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_10 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_10\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_10_input_text' id='label_ff_2_10_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_10_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_10_email' id='label_ff_2_10_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_10_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_10_phone' id='label_ff_2_10_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_10_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_10_description' id='label_ff_2_10_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_10_description\" name=\"description\" id=\"ff_2_10_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_10 ff-form-loading_errors ff_form_instance_2_10_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_10 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_10\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1e782373 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-729e4697\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0d76f773\"><h2 class=\"uagb-heading-text\">\u0627\u0644\u0645\u064a\u0632\u0627\u062a \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629 \u0644\u0623\u0646\u0627\u0628\u064a\u0628 HUALIN PVC<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">\u0627\u0644\u062e\u0635\u0627\u0626\u0635 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0644\u0640 <a href=\"https:\/\/fshualinkeji.com\/ar\/%d8%a7%d9%84%d8%a3%d9%86%d8%a7%d8%a8%d9%8a%d8%a8-%d8%a7%d9%84%d8%a8%d9%84%d8%a7%d8%b3%d8%aa%d9%8a%d9%83%d9%8a%d8%a9\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0623\u0646\u0627\u0628\u064a\u0628 PVC<\/a> \u062d\u0627\u0632\u062a \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0639\u0644\u0649 \u0627\u0639\u062a\u0631\u0627\u0641 \u0648\u0627\u0633\u0639 \u0641\u064a \u0627\u0644\u0633\u0648\u0642 \u0644\u0645\u0642\u0627\u0648\u0645\u062a\u0647\u0627 \u0627\u0644\u0645\u0645\u062a\u0627\u0632\u0629 \u0644\u0644\u062a\u0622\u0643\u0644\u060c \u0648\u0645\u0642\u0627\u0648\u0645\u062a\u0647\u0627 \u0644\u0644\u062d\u0631\u0627\u0631\u0629\u060c \u0648\u0635\u0644\u0627\u0628\u062a\u0647\u0627 \u0648\u0644\u064a\u0648\u0646\u062a\u0647\u0627. \u0648\u0633\u0648\u0627\u0621 \u0643\u0627\u0646\u062a \u062a\u0648\u0627\u062c\u0647 \u062a\u0622\u0643\u0644 \u0627\u0644\u0645\u062d\u0627\u0644\u064a\u0644 \u0627\u0644\u062d\u0645\u0636\u064a\u0629 \u0648\u0627\u0644\u0642\u0644\u0648\u064a\u0629 \u0623\u0648 \u062a\u062a\u062d\u0645\u0644 \u0627\u062e\u062a\u0628\u0627\u0631 \u062f\u0631\u062c\u0627\u062a \u0627\u0644\u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u0639\u0627\u0644\u064a\u0629 \u0648\u0627\u0644\u0636\u063a\u0637 \u0627\u0644\u0639\u0627\u0644\u064a\u060c \u064a\u0645\u0643\u0646 \u0644\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0627\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u0649 \u0623\u062f\u0627\u0621 \u0645\u0633\u062a\u0642\u0631 \u0648\u0636\u0645\u0627\u0646 \u0627\u0644\u062a\u0634\u063a\u064a\u0644 \u0627\u0644\u0622\u0645\u0646 \u0644\u0646\u0638\u0627\u0645 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628. \u0648\u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0630\u0644\u0643\u060c \u062a\u062a\u0645\u062a\u0639 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0623\u064a\u0636\u064b\u0627 \u0628\u0642\u0648\u0629 \u0636\u063a\u0637 \u062c\u064a\u062f\u0629\u060c \u0648\u0644\u064a\u0633 \u0645\u0646 \u0627\u0644\u0633\u0647\u0644 \u062a\u0634\u0642\u0642\u0647\u0627 \u0648\u062a\u0622\u0643\u0644\u0647\u0627\u060c \u0648\u0644\u0647\u0627 \u0639\u0645\u0631 \u062e\u062f\u0645\u0629 \u0637\u0648\u064a\u0644. \u0625\u0646\u0647\u0627 \u0645\u0627\u062f\u0629 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0645\u0641\u0636\u0644\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629.<\/p>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-674e1289 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-674e1289 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-173df8c8\"><h2 class=\"uagb-heading-text\">\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/h2><\/div>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_11 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_11\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_11_input_text' id='label_ff_2_11_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_11_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_11_email' id='label_ff_2_11_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_11_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_11_phone' id='label_ff_2_11_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_11_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_11_description' id='label_ff_2_11_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_11_description\" name=\"description\" id=\"ff_2_11_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_11 ff-form-loading_errors ff_form_instance_2_11_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_11 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_11\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6fe57f65\">\n<div class=\"wp-block-uagb-image uagb-block-afa9aabc wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Polyethylene-Pipes.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Polyethylene-Pipes.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Polyethylene-Pipes.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Polyethylene-Pipes.jpg\" alt=\"\" class=\"uag-image-361\" width=\"750\" height=\"500\" title=\"\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646-\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-27ec6df1 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-d4b3ee1c\">\n<div class=\"wp-block-uagb-image uagb-block-da368a29 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Custom-Of-PVC-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Custom-Of-PVC-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Custom-Of-PVC-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Custom-Of-PVC-Pipe.jpg\" alt=\"\" class=\"uag-image-2376\" width=\"750\" height=\"500\" title=\"\u0645\u062e\u0635\u0635-\u0623\u0648\u0641-\u0628\u0648\u0644\u064a \u0643\u0644\u0648\u0631\u064a\u062f \u0627\u0644\u0641\u064a\u0646\u064a\u0644 \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0641\u064a\u0646\u064a\u0644\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2bd96d48\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9855b031\"><h2 class=\"uagb-heading-text\">\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0627\u0644\u0645\u062e\u0635\u0635\u0629<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">\u064a\u0645\u0643\u0646 \u0644\u0641\u0631\u064a\u0642\u0646\u0627 \u0627\u0644\u0641\u0646\u064a \u062a\u062e\u0635\u064a\u0635 \u0645\u0648\u0627\u0635\u0641\u0627\u062a \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0648\u0627\u0644\u0623\u0644\u0648\u0627\u0646 \u0648\u0627\u0644\u0623\u0637\u0648\u0627\u0644 \u0648\u0637\u0631\u0642 \u0627\u0644\u062a\u0648\u0635\u064a\u0644 \u0648\u0641\u0642\u064b\u0627 \u0644\u0645\u062a\u0637\u0644\u0628\u0627\u062a\u0643 \u0627\u0644\u062e\u0627\u0635\u0629. \u0646\u062d\u0646 \u0646\u0633\u062a\u062e\u062f\u0645 \u0645\u0648\u0627\u062f \u062e\u0627\u0645 \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0639\u0645\u0644\u064a\u0627\u062a \u0625\u0646\u062a\u0627\u062c \u0645\u062a\u0642\u062f\u0645\u0629 \u0644\u0636\u0645\u0627\u0646 \u0623\u0646 \u0643\u0644 \u0642\u0633\u0645 \u0645\u0646 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u064a\u062a\u0645\u062a\u0639 \u0628\u0645\u0642\u0627\u0648\u0645\u0629 \u062c\u064a\u062f\u0629 \u0644\u0644\u0636\u063a\u0637 \u0648\u0645\u0642\u0627\u0648\u0645\u0629 \u0644\u0644\u062a\u0622\u0643\u0644 \u0648\u0639\u0645\u0631 \u062e\u062f\u0645\u0629 \u0637\u0648\u064a\u0644. \u0648\u0641\u064a \u0627\u0644\u0648\u0642\u062a \u0646\u0641\u0633\u0647\u060c \u0646\u062f\u0639\u0645 \u0637\u0644\u0628\u0627\u062a \u0627\u0644\u062f\u0641\u0639\u0627\u062a \u0627\u0644\u0635\u063a\u064a\u0631\u0629 \u0648\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u062f\u0642\u064a\u0642 \u0627\u0644\u0633\u0631\u064a\u0639 \u0644\u0645\u0633\u0627\u0639\u062f\u062a\u0643 \u0639\u0644\u0649 \u0627\u0644\u062a\u062d\u0643\u0645 \u0641\u064a \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641 \u0648\u062a\u062d\u0633\u064a\u0646 \u0643\u0641\u0627\u0621\u0629 \u0627\u0644\u0645\u0634\u0631\u0648\u0639.<\/p>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-f858eb1f uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">\u0623\u0631\u0633\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0627\u0644\u0622\u0646<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-f858eb1f uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8d8acc87\"><h2 class=\"uagb-heading-text\">\u0623\u0631\u0633\u0644 \u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0643 \u0627\u0644\u064a\u0648\u0645<\/h2><\/div>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_12 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_12\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">\u0646\u0645\u0648\u0630\u062c \u0645\u0646\u0628\u062b\u0642<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2317' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/2317\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_12_input_text' id='label_ff_2_12_input_text' aria-label=\"\u0627\u0644\u0627\u0633\u0645\">\u0627\u0644\u0627\u0633\u0645<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"\u0627\u0644\u0627\u0633\u0645\" data-name=\"input_text\" id=\"ff_2_12_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_12_email' id='label_ff_2_12_email' aria-label=\"\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\">\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_12_email\" class=\"ff-el-form-control\" placeholder=\"\u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_12_phone' id='label_ff_2_12_phone' aria-label=\"\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP\">\u0627\u0644\u0647\u0627\u062a\u0641\/hatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\" data-name=\"phone\" id=\"ff_2_12_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_12_description' id='label_ff_2_12_description' aria-label=\"\u0631\u0633\u0627\u0626\u0644\u0643\">\u0631\u0633\u0627\u0626\u0644\u0643<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_12_description\" name=\"description\" id=\"ff_2_12_description\" class=\"ff-el-form-control\" placeholder=\"\u0631\u0633\u0627\u0626\u0644\u0643\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"\u0625\u0631\u0633\u0627\u0644\">\u0625\u0631\u0633\u0627\u0644<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_12 ff-form-loading_errors ff_form_instance_2_12_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_12 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_12\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"\u0625\u063a\u0644\u0627\u0642 \u0645\u0634\u0631\u0648\u0637\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e3e2b8f2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-7eacc968\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1ebe5639\"><h2 class=\"uagb-heading-text\">\u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u062a \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0623\u0646\u0627\u0628\u064a\u0628 HUALIN PVC<\/h2><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6076012b\">\n<div class=\"wp-block-uagb-container uagb-block-1c74a02f\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-5f66276d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Applications-of-HUALIN-PVC-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Applications-of-HUALIN-PVC-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Applications-of-HUALIN-PVC-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Applications-of-HUALIN-PVC-Pipe.jpg\" alt=\"\" class=\"uag-image-2370\" width=\"750\" height=\"500\" title=\"\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0623\u0646\u0627\u0628\u064a\u0628 HUALIN PVC\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-435fd273\">\n<div class=\"wp-block-uagb-image uagb-block-07cc6c1b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Applications-of-HUALIN-PVC-Pipe-1.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Applications-of-HUALIN-PVC-Pipe-1.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Applications-of-HUALIN-PVC-Pipe-1.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/Applications-of-HUALIN-PVC-Pipe-1.jpg\" alt=\"\" class=\"uag-image-2372\" width=\"750\" height=\"500\" title=\"\u062a\u0637\u0628\u064a\u0642\u0627\u062a-\u0647\u0648\u0627\u0644\u064a\u0646-\u0628\u0648\u0644\u064a \u0643\u0644\u0648\u0631\u064a\u062f \u0627\u0644\u0641\u064a\u0646\u064a\u0644-\u0628\u0648\u0644\u064a \u0643\u0644\u0648\u0631\u064a\u062f \u0627\u0644\u0641\u064a\u0646\u064a\u0644-1\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<p style=\"font-size:16px\">\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0641\u064a \u0625\u0645\u062f\u0627\u062f\u0627\u062a \u0627\u0644\u0645\u064a\u0627\u0647 \u0641\u064a \u0627\u0644\u0645\u0628\u0627\u0646\u064a: \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0647\u064a \u0645\u0648\u0627\u062f \u0623\u0646\u0627\u0628\u064a\u0628 \u0634\u0627\u0626\u0639\u0629 \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0641\u064a \u0623\u0646\u0638\u0645\u0629 \u0625\u0645\u062f\u0627\u062f\u0627\u062a \u0627\u0644\u0645\u064a\u0627\u0647 \u0641\u064a \u0627\u0644\u0645\u0628\u0627\u0646\u064a\u060c \u0648\u062a\u0633\u062a\u062e\u062f\u0645 \u0644\u0646\u0642\u0644 \u0627\u0644\u0645\u064a\u0627\u0647 \u0627\u0644\u0633\u0627\u062e\u0646\u0629 \u0648\u0627\u0644\u0628\u0627\u0631\u062f\u0629 \u0648\u0645\u064a\u0627\u0647 \u0627\u0644\u0623\u0645\u0637\u0627\u0631 \u0648\u0627\u0644\u0635\u0631\u0641 \u0627\u0644\u0635\u062d\u064a\u060c \u0625\u0644\u062e. \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629: \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u062a\u0633\u062a\u062e\u062f\u0645 \u0639\u0644\u0649 \u0646\u0637\u0627\u0642 \u0648\u0627\u0633\u0639 \u0641\u064a \u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0641\u064a \u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u060c \u0648\u062a\u0633\u062a\u062e\u062f\u0645 \u0644\u0646\u0642\u0644 \u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u062e\u0627\u0645 \u0627\u0644\u0643\u064a\u0645\u064a\u0627\u0626\u064a\u0629\u060c \u0648\u0645\u0639\u0627\u0644\u062c\u0629 \u0645\u064a\u0627\u0647 \u0627\u0644\u0635\u0631\u0641 \u0627\u0644\u0635\u062d\u064a \u0648\u0633\u0648\u0627\u0626\u0644 \u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0629\u060c \u0625\u0644\u062e. \u0627\u0644\u0631\u064a \u0627\u0644\u0632\u0631\u0627\u0639\u064a: \u062a\u0644\u0639\u0628 \u0623\u0646\u0627\u0628\u064a\u0628 PVC \u062f\u0648\u0631\u064b\u0627 \u0645\u0647\u0645\u064b\u0627 \u0641\u064a \u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u0631\u064a \u0627\u0644\u0632\u0631\u0627\u0639\u064a\u060c \u0648\u062a\u0633\u062a\u062e\u062f\u0645 \u0644\u0646\u0642\u0644 \u0645\u064a\u0627\u0647 \u0627\u0644\u0631\u064a \u0625\u0644\u0649 \u0627\u0644\u062d\u0642\u0648\u0644 \u0648\u0645\u0646\u0627\u0637\u0642 \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0645\u062d\u0627\u0635\u064a\u0644. \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0628\u0644\u062f\u064a\u0629: \u062a\u0633\u062a\u062e\u062f\u0645 \u0623\u0646\u0627\u0628\u064a\u0628 PVC \u0639\u0644\u0649 \u0646\u0637\u0627\u0642 \u0648\u0627\u0633\u0639 \u0641\u064a \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0628\u0644\u062f\u064a\u0629 \u0627\u0644\u062d\u0636\u0631\u064a\u0629\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u0635\u0631\u0641 \u0627\u0644\u0635\u062d\u064a \u0648\u0645\u062d\u0637\u0627\u062a \u0645\u0639\u0627\u0644\u062c\u0629 \u0645\u064a\u0627\u0647 \u0627\u0644\u0635\u0631\u0641 \u0627\u0644\u0635\u062d\u064a \u0648\u0645\u0631\u0627\u0641\u0642 \u062a\u062c\u0645\u064a\u0639 \u0645\u064a\u0627\u0647 \u0627\u0644\u0623\u0645\u0637\u0627\u0631.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Juntong Technology!#hdpe #P5Tpipe #pipe #pipe\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/2E_gVP3it3o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-112d9740 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-bd9af255\"><h2 class=\"uagb-heading-text\">\u0627\u0644\u0623\u0633\u0626\u0644\u0629 \u0627\u0644\u0634\u0627\u0626\u0639\u0629<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a9f51d0\"><div class=\"wp-block-uagb-faq uagb-faq__outer-wrap uagb-block-3e8de48a uagb-faq-icon-row-reverse uagb-faq-layout-accordion uagb-faq-expand-first-true uagb-faq-inactive-other-true uagb-faq__wrap uagb-buttons-layout-wrap uagb-faq-equal-height\" data-faqtoggle=\"true\" role=\"tablist\"><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-937ccc12\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">\u0646\u0637\u0627\u0642 \u0627\u0644\u062d\u062c\u0645 \u0627\u0644\u0634\u0627\u0626\u0639 \u0644\u0623\u0646\u0627\u0628\u064a\u0628 PVC\u061f<\/span><\/div><div class=\"uagb-faq-content\"><p>\u0641\u064a\u0645\u0627 \u064a\u0644\u064a \u0646\u0637\u0627\u0642\u0627\u062a \u0627\u0644\u0623\u062d\u062c\u0627\u0645 \u0627\u0644\u0634\u0627\u0626\u0639\u0629 \u0644\u0623\u0646\u0627\u0628\u064a\u0628 PVC:<br>1- \u0623\u0646\u0628\u0648\u0628 \u0625\u0645\u062f\u0627\u062f \u0627\u0644\u0645\u064a\u0627\u0647 PVC (\u0646\u0638\u0627\u0645 \u0625\u0645\u062f\u0627\u062f \u0627\u0644\u0645\u064a\u0627\u0647)<br>\u0646\u0637\u0627\u0642 \u0642\u0637\u0631 \u0627\u0644\u0623\u0646\u0628\u0648\u0628: 20 \u0645\u0645 - 400 \u0645\u0645 2525<br>\u0627\u0644\u0645\u0648\u0627\u0635\u0641\u0627\u062a \u0627\u0644\u0634\u0627\u0626\u0639\u0629: DN20\u060c DN25\u060c DN25\u060c DN32\u060c DN40\u060c DN50\u060c DN63\u060c DN80\u060c DN10025<br>\u0633\u064f\u0645\u0643 \u0627\u0644\u062c\u062f\u0627\u0631: 2.3 \u0645\u0645\u060c 3.2 \u0645\u0645\u060c 4 \u0645\u0645\u060c 5 \u0645\u0645 (\u064a\u0632\u062f\u0627\u062f \u0627\u0644\u0633\u064f\u0645\u0643 \u0643\u0644\u0645\u0627 \u0632\u0627\u062f \u0642\u0637\u0631 \u0627\u0644\u0623\u0646\u0628\u0648\u0628)23<br>\u0627\u0644\u0637\u0648\u0644: \u0639\u0627\u062f\u0629\u064b 4 \u0623\u0645\u062a\u0627\u0631 \u0623\u0648 6 \u0623\u0645\u062a\u0627\u063125<br><br>2- \u0623\u0646\u0628\u0648\u0628 \u0627\u0644\u0635\u0631\u0641 PVC (\u062a\u0635\u0631\u064a\u0641 \u0645\u064a\u0627\u0647 \u0627\u0644\u0635\u0631\u0641 \u0627\u0644\u0635\u062d\u064a\/\u0645\u064a\u0627\u0647 \u0627\u0644\u0623\u0645\u0637\u0627\u0631)<br>\u0646\u0637\u0627\u0642 \u0642\u0637\u0631 \u0627\u0644\u0623\u0646\u0628\u0648\u0628: 32 \u0645\u0645 - 630 \u0645\u0645<br>\u0645\u0648\u0627\u0635\u0641\u0627\u062a \u0645\u0634\u062a\u0631\u0643\u0629:<br>DN32\u060c DN40\u060c DN50 (\u0642\u0637\u0631 \u0635\u063a\u064a\u0631\u060c \u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0633\u0643\u0646\u064a)<br>DN110\u060c DN160\u060c DN200 (\u0633\u064a\u0646\u0627\u0631\u064a\u0648\u0647\u0627\u062a \u0627\u0644\u062a\u062f\u0641\u0642 \u0627\u0644\u0643\u0628\u064a\u0631)<br>\u0627\u0644\u0637\u0648\u0644: 4 \u0623\u0645\u062a\u0627\u0631 \u0623\u0648 6 \u0623\u0645\u062a\u0627\u0631\u060c \u0628\u0639\u0636 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0645\u062e\u0635\u0635\u0629 \u0644\u0640 8 \u0623\u0645\u062a\u0627\u0631<br><br>3- \u0623\u0646\u0628\u0648\u0628 \u0633\u0644\u0643 PVC (\u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0643\u0627\u0628\u0644\u0627\u062a)<br>\u0646\u0637\u0627\u0642 \u0627\u0644\u0642\u0637\u0631: 16 \u0645\u0645 - 63 \u0645\u06452<br>\u0627\u0644\u0645\u0648\u0627\u0635\u0641\u0627\u062a \u0627\u0644\u0634\u0627\u0626\u0639\u0629: DN16\u060c DN20\u060c DN25\u060c DN3226<br>\u0633\u064f\u0645\u0643 \u0627\u0644\u062c\u062f\u0627\u0631: 1.8 \u0645\u0645\u060c 2.0 \u0645\u0645\u060c 2.3 \u0645\u0645 (\u0645\u062a\u0637\u0644\u0628\u0627\u062a \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0639\u0632\u0644)<\/p><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-75d67f4d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0d421be9\"><h2 class=\"uagb-heading-text\">\u0645\u0642\u0627\u0644\u0629 \u0630\u0627\u062a \u0635\u0644\u0629 \u0639\u0646 \u0647\u0648\u0627\u0644\u064a\u0646<\/h2><\/div>\n\n\n\n\t\t\t<div class=\"wp-block-uagb-post-grid uagb-post-grid  uagb-post__image-position-top uagb-post__image-enabled uagb-block-47dc8831     uagb-post__items uagb-post__columns-3 is-grid uagb-post__columns-tablet-2 uagb-post__columns-mobile-1 uagb-post__equal-height\" data-total=\"20\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fshualinkeji.com\/ar\/%d9%85%d8%a7-%d9%87%d9%88-%d9%84%d8%ad%d8%a7%d9%85-%d8%a7%d9%84%d9%84%d8%ad%d8%a7%d9%85-%d8%a8%d8%a7%d9%84%d8%b5%d9%87%d8%b1-%d8%a7%d9%84%d9%83%d9%87%d8%b1%d8%a8%d8%a7%d8%a6%d9%8a\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-inherit'><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"499\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/PE-Electrofusion-Welding-2.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/PE-Electrofusion-Welding-2.jpg 750w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/PE-Electrofusion-Welding-2-300x200.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/PE-Electrofusion-Welding-2-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/fshualinkeji.com\/ar\/%d9%85%d8%a7-%d9%87%d9%88-%d9%84%d8%ad%d8%a7%d9%85-%d8%a7%d9%84%d9%84%d8%ad%d8%a7%d9%85-%d8%a8%d8%a7%d9%84%d8%b5%d9%87%d8%b1-%d8%a7%d9%84%d9%83%d9%87%d8%b1%d8%a8%d8%a7%d8%a6%d9%8a\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u0645\u0627 \u0647\u0648 \u0644\u062d\u0627\u0645 \u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646 \u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646 \u0628\u0627\u0644\u0635\u0647\u0631 \u0627\u0644\u0643\u0647\u0631\u0628\u0627\u0626\u064a\u061f<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t\t<time datetime=\"2025-12-24T23:35:31-07:00\" class=\"uagb-post__date\">\n\t\t\t\t<span class=\"dashicons-calendar dashicons\"><\/span>\t\t\t\t\t\u062f\u064a\u0633\u0645\u0628\u0631 24, 2025\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\t<p>\u062a\u062a\u0636\u0645\u0646 \u0637\u0631\u0642 \u062a\u0648\u0635\u064a\u0644 \u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646 PE \u0627\u0644\u0623\u0643\u062b\u0631 \u0634\u064a\u0648\u0639\u064b\u0627 \u0641\u064a \u062a\u0631\u0643\u064a\u0628 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628: \u062a\u0648\u0635\u064a\u0644 \u0627\u0644\u0627\u0646\u0635\u0647\u0627\u0631 \u0627\u0644\u062d\u0631\u0627\u0631\u064a\u060c \u0648\u0627\u0644\u0635\u0647\u0631 \u0627\u0644\u0643\u0647\u0631\u0628\u0627\u0626\u064a...\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/fshualinkeji.com\/ar\/%d9%85%d8%a7-%d9%87%d9%88-%d9%84%d8%ad%d8%a7%d9%85-%d8%a7%d9%84%d9%84%d8%ad%d8%a7%d9%85-%d8%a8%d8%a7%d9%84%d8%b5%d9%87%d8%b1-%d8%a7%d9%84%d9%83%d9%87%d8%b1%d8%a8%d8%a7%d8%a6%d9%8a\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fshualinkeji.com\/ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b4%d8%a8%d9%83%d8%a9-%d8%a3%d8%b3%d9%84%d8%a7%d9%83-%d8%a7%d9%84%d9%81%d9%88%d9%84%d8%a7%d8%b0-%d8%a7%d9%84%d9%85%d8%b1%d9%83%d8%a8%d8%a9-%d9%85%d9%86-%d8%a7%d9%84%d9%81\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-inherit'><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"517\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/PE-steel-wire-mesh-composite-pipe-1.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/PE-steel-wire-mesh-composite-pipe-1.jpg 750w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/PE-steel-wire-mesh-composite-pipe-1-300x207.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/PE-steel-wire-mesh-composite-pipe-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/fshualinkeji.com\/ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b4%d8%a8%d9%83%d8%a9-%d8%a3%d8%b3%d9%84%d8%a7%d9%83-%d8%a7%d9%84%d9%81%d9%88%d9%84%d8%a7%d8%b0-%d8%a7%d9%84%d9%85%d8%b1%d9%83%d8%a8%d8%a9-%d9%85%d9%86-%d8%a7%d9%84%d9%81\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u0645\u0627 \u0647\u064a \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0645\u0631\u0643\u0628\u0629 \u0645\u0646 \u0634\u0628\u0643\u0629 \u0623\u0633\u0644\u0627\u0643 \u0627\u0644\u0641\u0648\u0644\u0627\u0630 PE\u061f<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t\t<time datetime=\"2025-12-24T01:35:37-07:00\" class=\"uagb-post__date\">\n\t\t\t\t<span class=\"dashicons-calendar dashicons\"><\/span>\t\t\t\t\t\u062f\u064a\u0633\u0645\u0628\u0631 24, 2025\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\t<p>\u0647\u0644 \u062a\u0628\u062d\u062b \u0639\u0646 \u0645\u0648\u0627\u062f \u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0645\u0646\u0627\u0633\u0628\u0629 \u0644\u0625\u0645\u062f\u0627\u062f\u0627\u062a \u0627\u0644\u0645\u064a\u0627\u0647 \u0627\u0644\u0628\u0644\u062f\u064a\u0629 \u0648\u0627\u0644\u0635\u0631\u0641 \u0627\u0644\u0635\u062d\u064a\u061f \u0623\u0633\u0644\u0627\u0643 \u0627\u0644\u0641\u0648\u0644\u0627\u0630 PE...\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/fshualinkeji.com\/ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b4%d8%a8%d9%83%d8%a9-%d8%a3%d8%b3%d9%84%d8%a7%d9%83-%d8%a7%d9%84%d9%81%d9%88%d9%84%d8%a7%d8%b0-%d8%a7%d9%84%d9%85%d8%b1%d9%83%d8%a8%d8%a9-%d9%85%d9%86-%d8%a7%d9%84%d9%81\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fshualinkeji.com\/ar\/%d8%a7%d9%84%d8%af%d9%84%d9%8a%d9%84-%d8%a7%d9%84%d8%b4%d8%a7%d9%85%d9%84-%d9%84%d8%aa%d9%82%d9%86%d9%8a%d8%a9-%d8%a7%d9%84%d8%a3%d9%86%d8%a7%d8%a8%d9%8a%d8%a8-%d8%a7%d9%84%d8%ae%d8%b1%d8%b3%d8%a7\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-inherit'><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"562\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/Trenchless-technology-for-PE-pipelines-1.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/Trenchless-technology-for-PE-pipelines-1.jpg 750w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/Trenchless-technology-for-PE-pipelines-1-300x225.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/Trenchless-technology-for-PE-pipelines-1-16x12.jpg 16w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/fshualinkeji.com\/ar\/%d8%a7%d9%84%d8%af%d9%84%d9%8a%d9%84-%d8%a7%d9%84%d8%b4%d8%a7%d9%85%d9%84-%d9%84%d8%aa%d9%82%d9%86%d9%8a%d8%a9-%d8%a7%d9%84%d8%a3%d9%86%d8%a7%d8%a8%d9%8a%d8%a8-%d8%a7%d9%84%d8%ae%d8%b1%d8%b3%d8%a7\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u0627\u0644\u062f\u0644\u064a\u0644 \u0627\u0644\u0634\u0627\u0645\u0644 \u0644\u062a\u0642\u0646\u064a\u0629 \u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646 \u0627\u0644\u0628\u0648\u0644\u064a \u0625\u064a\u062b\u064a\u0644\u064a\u0646 \u063a\u064a\u0631 \u0627\u0644\u0645\u0642\u0637\u0648\u0639\u0629<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t\t<time datetime=\"2025-12-22T23:33:03-07:00\" class=\"uagb-post__date\">\n\t\t\t\t<span class=\"dashicons-calendar dashicons\"><\/span>\t\t\t\t\t\u062f\u064a\u0633\u0645\u0628\u0631 22, 2025\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\t<p>\u0645\u0639 \u062a\u0633\u0627\u0631\u0639 \u0648\u062a\u064a\u0631\u0629 \u0627\u0644\u062a\u0648\u0633\u0651\u0639 \u0627\u0644\u062d\u0636\u0631\u064a \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u060c \u064a\u062a\u0637\u0644\u0628 \u0627\u0644\u0628\u0646\u0627\u0621 \u0627\u0644\u0628\u0644\u062f\u064a \u0648\u0636\u0639 \u0648\u0627\u0633\u062a\u0628\u062f\u0627\u0644...\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/fshualinkeji.com\/ar\/%d8%a7%d9%84%d8%af%d9%84%d9%8a%d9%84-%d8%a7%d9%84%d8%b4%d8%a7%d9%85%d9%84-%d9%84%d8%aa%d9%82%d9%86%d9%8a%d8%a9-%d8%a7%d9%84%d8%a3%d9%86%d8%a7%d8%a8%d9%8a%d8%a8-%d8%a7%d9%84%d8%ae%d8%b1%d8%b3%d8%a7\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>PVC Pipe PVC pipe is a plastic pipe made of polyvinyl chloride resin as the main raw material and formed [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2317","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PVC Pipe - Hualin Pipe Technology<\/title>\n<meta name=\"description\" content=\"PVC pipe is a plastic pipe made of polyvinyl chloride resin as the main raw material and formed by extrusion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fshualinkeji.com\/ar\/\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628-\u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PVC Pipe - Hualin Pipe Technology\" \/>\n<meta property=\"og:description\" content=\"PVC pipe is a plastic pipe made of polyvinyl chloride resin as the main raw material and formed by extrusion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fshualinkeji.com\/ar\/\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628-\u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\/\" \/>\n<meta property=\"og:site_name\" content=\"Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T06:26:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/pvc-pipe\\\/\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/pvc-pipe\\\/\",\"name\":\"PVC Pipe - Hualin Pipe Technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/pvc-pipe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/pvc-pipe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pvc-water-pipe.jpg\",\"datePublished\":\"2025-06-30T03:25:32+00:00\",\"dateModified\":\"2025-06-30T06:26:04+00:00\",\"description\":\"PVC pipe is a plastic pipe made of polyvinyl chloride resin as the main raw material and formed by extrusion.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/pvc-pipe\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fshualinkeji.com\\\/pvc-pipe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/pvc-pipe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pvc-water-pipe.jpg\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pvc-water-pipe.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/pvc-pipe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fshualinkeji.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PVC Pipe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#website\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/\",\"name\":\"Hualin Pipe Technology\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fshualinkeji.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\",\"name\":\"Hualin Pipe Technology\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-logo-1.png\",\"width\":156,\"height\":40,\"caption\":\"Hualin Pipe Technology\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0648\u0644\u064a \u0641\u064a\u0646\u064a\u0644 \u0643\u0644\u0648\u0631\u064a\u062f \u0627\u0644\u0641\u064a\u0646\u064a\u0644 \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0643\u0644\u0648\u0631\u064a\u062f - Hualin PVC","description":"\u0623\u0646\u0628\u0648\u0628 PVC \u0639\u0628\u0627\u0631\u0629 \u0639\u0646 \u0623\u0646\u0628\u0648\u0628 \u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a \u0645\u0635\u0646\u0648\u0639 \u0645\u0646 \u0631\u0627\u062a\u0646\u062c \u0627\u0644\u0628\u0648\u0644\u064a \u0641\u064a\u0646\u064a\u0644 \u0643\u0644\u0648\u0631\u064a\u062f \u0643\u0645\u0627\u062f\u0629 \u062e\u0627\u0645 \u0631\u0626\u064a\u0633\u064a\u0629 \u0648\u064a\u062a\u0645 \u062a\u0634\u0643\u064a\u0644\u0647 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0628\u062b\u0642.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fshualinkeji.com\/ar\/\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628-\u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\/","og_locale":"ar_AR","og_type":"article","og_title":"PVC Pipe - Hualin Pipe Technology","og_description":"PVC pipe is a plastic pipe made of polyvinyl chloride resin as the main raw material and formed by extrusion.","og_url":"https:\/\/fshualinkeji.com\/ar\/\u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628-\u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629\/","og_site_name":"Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology","article_modified_time":"2025-06-30T06:26:04+00:00","og_image":[{"url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"5 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fshualinkeji.com\/pvc-pipe\/","url":"https:\/\/fshualinkeji.com\/pvc-pipe\/","name":"\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0628\u0648\u0644\u064a \u0641\u064a\u0646\u064a\u0644 \u0643\u0644\u0648\u0631\u064a\u062f \u0627\u0644\u0641\u064a\u0646\u064a\u0644 \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0643\u0644\u0648\u0631\u064a\u062f - Hualin PVC","isPartOf":{"@id":"https:\/\/fshualinkeji.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fshualinkeji.com\/pvc-pipe\/#primaryimage"},"image":{"@id":"https:\/\/fshualinkeji.com\/pvc-pipe\/#primaryimage"},"thumbnailUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg","datePublished":"2025-06-30T03:25:32+00:00","dateModified":"2025-06-30T06:26:04+00:00","description":"\u0623\u0646\u0628\u0648\u0628 PVC \u0639\u0628\u0627\u0631\u0629 \u0639\u0646 \u0623\u0646\u0628\u0648\u0628 \u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a \u0645\u0635\u0646\u0648\u0639 \u0645\u0646 \u0631\u0627\u062a\u0646\u062c \u0627\u0644\u0628\u0648\u0644\u064a \u0641\u064a\u0646\u064a\u0644 \u0643\u0644\u0648\u0631\u064a\u062f \u0643\u0645\u0627\u062f\u0629 \u062e\u0627\u0645 \u0631\u0626\u064a\u0633\u064a\u0629 \u0648\u064a\u062a\u0645 \u062a\u0634\u0643\u064a\u0644\u0647 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0628\u062b\u0642.","breadcrumb":{"@id":"https:\/\/fshualinkeji.com\/pvc-pipe\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fshualinkeji.com\/pvc-pipe\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/fshualinkeji.com\/pvc-pipe\/#primaryimage","url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/pvc-water-pipe.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fshualinkeji.com\/pvc-pipe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fshualinkeji.com\/"},{"@type":"ListItem","position":2,"name":"PVC Pipe"}]},{"@type":"WebSite","@id":"https:\/\/fshualinkeji.com\/#website","url":"https:\/\/fshualinkeji.com\/","name":"\u0647\u0648\u0627\u0644\u064a\u0646 \u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628","description":"","publisher":{"@id":"https:\/\/fshualinkeji.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fshualinkeji.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/fshualinkeji.com\/#organization","name":"\u0647\u0648\u0627\u0644\u064a\u0646 \u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628","url":"https:\/\/fshualinkeji.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/fshualinkeji.com\/#\/schema\/logo\/image\/","url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/cropped-cropped-logo-1.png","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/cropped-cropped-logo-1.png","width":156,"height":40,"caption":"Hualin Pipe Technology"},"image":{"@id":"https:\/\/fshualinkeji.com\/#\/schema\/logo\/image\/"}}]}},"spectra_custom_meta":{"_edit_lock":["1753952026:1"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":["disabled"],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_edit_last":["1"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["5"],"_oembed_875c8858e48ca3f5744f4fb5f52a10cd":["<iframe title=\"Juntong Technology!#hdpe #pipe #pepipe\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/2E_gVP3it3o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_875c8858e48ca3f5744f4fb5f52a10cd":["1753952002"],"_oembed_d88c1851e0b03be51af3e633ea992adf":["<iframe title=\"Juntong Technology!#hdpe #pipe #pepipe\" width=\"1290\" height=\"726\" src=\"https:\/\/www.youtube.com\/embed\/2E_gVP3it3o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_d88c1851e0b03be51af3e633ea992adf":["1751261241"],"_yoast_wpseo_focuskw":["PVC pipe"],"_yoast_wpseo_metadesc":["PVC pipe is a plastic pipe made of polyvinyl chloride resin as the main raw material and formed by extrusion."],"_yoast_wpseo_linkdex":["41"],"_uag_css_file_name":["uag-css-2317.css"],"_uag_js_file_name":["uag-js-2317.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:285255:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}body.hide-scroll{overflow:hidden}body .uagb-modal-popup-wrap .wp-block{max-width:none !important;margin:0 !important}.uagb-modal-popup{visibility:hidden;position:fixed}.uagb-modal-popup.active{top:0;bottom:0;justify-content:center;align-items:center;background:rgba(0,0,0,.7);left:0;right:0;display:flex;visibility:visible}.uagb-modal-popup.active .uagb-modal-popup-close{opacity:1;display:flex;align-items:center;position:absolute;text-align:center;cursor:pointer;fill:#fff}.uagb-modal-popup.active .uagb-modal-popup-close svg{-webkit-transition-property:filter,transform;-moz-transition-property:filter,transform;-o-transition-property:filter,transform;transition-property:filter,transform;-webkit-transition-duration:250ms;-moz-transition-duration:250ms;-o-transition-duration:250ms;transition-duration:250ms}.uagb-modal-popup.active .uagb-modal-popup-close:focus svg{transform:scale(1.2)}.uagb-modal-popup .uagb-modal-popup-close{display:none;border:none;background:rgba(0,0,0,0);padding:0}.uagb-modal-popup .uagb-modal-popup-content{padding:35px 35px;overflow-x:hidden;overflow-y:overlay;height:100%}.uagb-modal-popup .uagb-modal-popup-wrap{display:flex;flex-direction:column;justify-content:flex-start;width:700px;height:450px;max-width:100%;box-sizing:border-box;background:#fff;color:#333;position:relative}.uagb-modal-popup .uagb-modal-popup-wrap .uagb-modal-popup-content::-webkit-scrollbar{width:5px}.uagb-modal-popup .uagb-modal-popup-wrap .uagb-modal-popup-content::-webkit-scrollbar-thumb{box-shadow:inset 0 0 6px rgba(0,0,0,.3);border-radius:100px}.wp-block-uagb-modal{width:100%}.entry .entry-content a.uagb-modal-button-link{text-decoration:inherit;align-items:center}.entry .entry-content a.uagb-modal-button-link:hover{color:inherit}.uagb-modal-trigger:not(img){display:flex}.uagb-modal-trigger:not(img) svg{font-size:30px;width:30px;height:30px;line-height:30px;cursor:pointer}img.uagb-modal-trigger{cursor:pointer;height:auto;max-width:100%}div.uagb-spectra-button-wrapper{line-height:1}div.uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{display:inline-flex;align-items:center;cursor:pointer}div.uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{fill:currentColor;font-style:normal;vertical-align:top;width:15px;height:15px;font-size:15px}.block-editor-block-popover.components-popover{z-index:99999999}.uagb-effect-default .uagb-modal-popup-wrap{opacity:0}.uagb-effect-default.active .uagb-modal-popup-wrap{opacity:1;-webkit-transition:all .3s;transition:all .3s}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-faq{width:100%}.wp-block-uagb-faq.uagb-faq-layout-accordion .uagb-faq-child__outer-wrap .uagb-faq-questions-button{cursor:pointer}.wp-block-uagb-faq .uagb-faq-content{margin-bottom:0}.wp-block-uagb-faq .uagb-faq-content p{margin:auto}.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-child__outer-wrap,.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-item{height:100%}body[class*=astra] .uagb-faq-questions{line-height:normal}.uagb-faq-item{overflow:hidden}.wp-block-uagb-faq-child .uagb-faq-questions-button{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-faq-icon-wrap{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-question{width:100%;margin-top:0;margin-bottom:0}.wp-block-uagb-faq-child .uagb-icon svg,.wp-block-uagb-faq-child .uagb-icon-active svg{width:15px;height:15px;font-size:15px}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon{display:none;width:0;padding:0;height:0;margin:0}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:flex;width:auto;height:auto}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}\ufeff.uagb-post-grid{margin:0 auto;position:relative}.uagb-post-grid:not(.is-grid) .uagb-post__inner-wrap{background-clip:content-box !important}.uagb-post-grid .uagb-post__inner-wrap{transition:box-shadow .2s ease;overflow:hidden}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.default{margin:5px 5px 5px 0}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{background:#444;color:#fff;border-radius:2px;flex-direction:row;align-items:flex-end;padding:6px 8px;line-height:1;margin-right:5px;margin-bottom:20px}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color:#fff}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy a{text-decoration:none;color:inherit}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__image .uagb-post__image-equal-height{display:block;height:0;padding-bottom:66.67%;overflow:hidden}.uagb-post-grid .uagb-post__load-more-wrap{width:100%;position:absolute;bottom:-30px}.uagb-post-grid .uagb-post__load-more-wrap .uagb-post-pagination-button{cursor:pointer}.uagb-post-grid .uagb-post__load-more-wrap a{color:inherit}.uagb-post-grid.is-grid article{float:left;display:inline-block}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:nth-last-child(2){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:last-child{position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(3){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(2){position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__inner-wrap,.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a{display:block;height:0;overflow:hidden;position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-2-3{padding-bottom:66%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-9-16{padding-bottom:56.25%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-2{padding-bottom:50%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-1{padding-bottom:67%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit{padding-bottom:0;height:auto}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit img{position:unset !important}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a[class^=uagb-image-ratio-]>img{position:absolute;height:100%}.uagb-post-grid.uagb-post__items.is-masonry{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap}.uagb-post-grid.uagb-post__items.is-carousel{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap;width:100%;visibility:hidden}.uagb-post-grid.is-grid .uagb-post__inner-wrap{height:max-content}.uagb-post-grid.is-grid.uagb-post__equal-height .uagb-post__inner-wrap{height:auto}.uagb-post-grid.is-masonry .uagb-post__inner-wrap{height:auto}.uagb-post-grid .uagb-post__author span,.uagb-post-grid .uagb-post__comment span,.uagb-post-grid .uagb-post__taxonomy span,.uagb-post-grid .uagb-post__date span{font-size:inherit;line-height:inherit;width:inherit;height:inherit;margin-right:4px;vertical-align:bottom}.uagb-post-grid.uagb-post__columns-8:not(.is-grid) article{width:12.5%}.uagb-post-grid.uagb-post__columns-7:not(.is-grid) article{width:14.28%}.uagb-post-grid.uagb-post__columns-6:not(.is-grid) article{width:16.66%}.uagb-post-grid.uagb-post__columns-5:not(.is-grid) article{width:20%}.uagb-post-grid.uagb-post__columns-4:not(.is-grid) article{width:25%}.uagb-post-grid.uagb-post__columns-3:not(.is-grid) article{width:33.33%}.uagb-post-grid.uagb-post__columns-2:not(.is-grid) article{width:50%}.uagb-post-grid.uagb-post__columns-1:not(.is-grid) article{width:100%}@media only screen and (max-width: 600px){.uagb-post-grid div[class*=columns].is-grid{grid-template-columns:1fr}}.uagb-post-grid .uagb-post__image img{display:block;width:100%;height:auto;max-width:100%}.uagb-post-grid .uagb-post__title{margin-top:0;margin-bottom:0;word-break:break-word}.uagb-post-grid .uagb-post__title a{color:inherit;box-shadow:none;transition:.3s ease;text-decoration:none}.uagb-post-grid .uagb-post__title a:hover{text-decoration:none}.uagb-post-grid .uagb-post__title a:focus{text-decoration:none}.uagb-post-grid .uagb-post__title a:active{text-decoration:none}.uagb-post-grid .uagb-post-grid-byline>*{margin-right:10px}.uagb-post-grid .uagb-post-grid-byline,.uagb-post-grid .uagb-post__taxonomy{text-transform:capitalize;font-size:14px;font-weight:500;line-height:23px;text-decoration:none}.uagb-post-grid .uagb-post-grid-byline a,.uagb-post-grid .uagb-post-grid-byline a:focus,.uagb-post-grid .uagb-post-grid-byline a:active{color:inherit;font-size:inherit;text-decoration:none}.uagb-post-grid .uagb-post__title a,.uagb-post-grid .uagb-post__title a:focus,.uagb-post-grid .uagb-post__title a:active{color:inherit;font-size:inherit}.uagb-post-grid .uagb-post__author,.uagb-post-grid .uagb-post__date,.uagb-post-grid .uagb-post__comment{display:inline-block;word-break:break-all}.uagb-post-grid .uagb-post__author:not(:last-child)::after,.uagb-post-grid .uagb-post__date:not(:last-child)::after,.uagb-post-grid .uagb-post__comment:not(:last-child)::after{content:\"\u00b7\";vertical-align:middle;align-self:center;margin:0 5px;line-height:1}.uagb-post-grid .uagb-post__comment,.uagb-post-grid .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__author a{box-shadow:none}.uagb-post-grid .uagb-post__author a:hover{color:inherit;box-shadow:0 -1px 0 inset}.uagb-post-grid .uagb-post__excerpt{word-break:break-word}.uagb-post-grid .uagb-post__inner-wrap p:last-of-type{margin-bottom:0}.uagb-post-grid .uagb-post__cta{border:none;display:inline-block;background:none}.uagb-post-grid .uagb-post__cta .ast-outline-button{display:inline-flex}.uagb-post-grid .uagb-post__excerpt p{color:inherit}.is-grid.uagb-post__items{display:grid}.wp-block-uagb-post-grid .uagb-post-pagination-wrap{grid-column:1\/-1}.uagb-post__image-position-background .uagb-post__link-complete-box{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.uagb-post__image-position-background.uagb-post__image-enabled .uagb-post__text{color:#fff}.uagb-post__image-position-background .uagb-post__text{opacity:1;position:relative;z-index:10;overflow:hidden}.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative;width:100%}.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted,.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.default{position:relative;z-index:999}.uagb-post__image-position-background .uagb-post__image img{position:absolute;width:auto;height:auto;min-width:100%;max-width:none;left:50%;top:50%;transform:translate(-50%, -50%);min-height:100%}.uagb-post__image-position-background .uagb-post__image{background-size:cover;background-repeat:no-repeat;background-position:center;overflow:hidden;text-align:center;position:absolute;left:0;top:0;width:100%;height:100%;z-index:2}.uagb-post__image-position-background .uagb-post__image::before{content:\"\";position:absolute;left:0;top:0;width:100%;height:100%;z-index:1;background-color:hsla(0,0%,100%,.5)}.uagb-slick-carousel .is-carousel{padding:0}.uagb-slick-carousel ul.slick-dots{transform:unset;position:relative;padding:unset}.uagb-slick-carousel .slick-prev:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel .slick-next:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel ul.slick-dots li button:not(:hover):not(:active):not(.has-background){background-color:unset}.uagb-post-grid[data-equal-height=yes] .uagb-post__inner-wrap{display:inline-block;height:100%}.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;right:auto}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:-45px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:auto;right:-45px}.uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:25px;z-index:1}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:auto;right:25px}.uagb-post__arrow-inside.uagb-post-grid .slick-next{right:25px}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-next{left:25px;right:auto}.uagb-post-grid.is-grid article,.uagb-post-grid.is-masonry article,.uagb-post-grid.is-carousel article{box-sizing:border-box}@media(max-width: 976px){.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:15px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:auto;right:15px}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:15px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:15px;right:auto}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-8 article{width:12.5%}}@media(max-width: 767px){:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-8 article{width:12.5%}}.entry .entry-content .uagb-post-grid a{text-decoration:none}.uagb-post-pagination-wrap{display:flex;width:100%;flex-wrap:wrap}.uagb-post-pagination-wrap a.page-numbers,.uagb-post-pagination-wrap span.page-numbers.current{padding:5px 10px;margin:0;display:flex;margin-right:4px;margin-bottom:5px}.uagb-post-grid .uagb-post-inf-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.uagb-post-grid .uagb-post-inf-loader div{width:18px;height:18px;background-color:#0085ba;-webkit-border-radius:100%;border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-next{right:0}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__video-wrap video{opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-90c2c68b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-90c2c68b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-90c2c68b{min-height: 550px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/hdpe-pipe-1.jpg);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-90c2c68b::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-8);opacity: 0.2;}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42e0e8e6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42e0e8e6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-42e0e8e6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-42e0e8e6.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-42e0e8e6.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3de41139{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3de41139 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3de41139{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1f746054 .uagb-heading-text{font-size: 48px;}.uagb-block-ccbe86b2.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-ccbe86b2 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-ccbe86b2 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-ccbe86b2.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-ccbe86b2 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-ccbe86b2 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ccbe86b2.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-ccbe86b2.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 32px;padding-right: 32px;padding-top: 14px;padding-bottom: 14px;color: var(--ast-global-color-5);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{fill: var(--ast-global-color-5);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-ccbe86b2.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-ccbe86b2 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-ccbe86b2.uagb-modal-wrapper{text-align: left;}.uagb-block-ccbe86b2 .wp-block-button__link{width: unset;}.uagb-block-ccbe86b2 .uagb-modal-trigger{justify-content: flex-start;}.uagb-block-ccbe86b2 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-heading-text{color: #060a12;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49 .uagb-heading-text{font-weight: 600;font-size: 22px;}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0aa5aa3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0aa5aa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f0aa5aa3{box-shadow: 0px 0px   #00000070 ;padding-top: 75px;padding-bottom: 65px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f4f6f9;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-421ce500.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-421ce500.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-421ce500.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-421ce500.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b31ce7bf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b31ce7bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b31ce7bf{box-shadow: 0px 0px   #00000070 ;padding-top: 75px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading {text-align: center;padding-bottom: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3 .uagb-heading-text{font-size: 40px;}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed0f7e26{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed0f7e26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ed0f7e26{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd817a82{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd817a82 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd817a82{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5c073af6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5c073af6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5c073af6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5860e71a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5860e71a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5860e71a{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511 .uagb-heading-text{font-size: 18px;}.uagb-block-048f0bfe.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-048f0bfe .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-048f0bfe .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-048f0bfe.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-048f0bfe .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-048f0bfe .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-048f0bfe.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-048f0bfe.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-048f0bfe.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-048f0bfe .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-048f0bfe.uagb-modal-wrapper{text-align: center;}.uagb-block-048f0bfe .wp-block-button__link{width: unset;}.uagb-block-048f0bfe .uagb-modal-trigger{justify-content: center;}.uagb-block-048f0bfe .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8342395{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8342395 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e8342395{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f80ca2c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f80ca2c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5f80ca2c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a1a2f46d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a1a2f46d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a1a2f46d{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06 .uagb-heading-text{font-size: 18px;}.uagb-block-dd0fd90b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-dd0fd90b .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-dd0fd90b .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-dd0fd90b.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-dd0fd90b .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-dd0fd90b .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-dd0fd90b.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-dd0fd90b.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-dd0fd90b.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-dd0fd90b .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-dd0fd90b.uagb-modal-wrapper{text-align: center;}.uagb-block-dd0fd90b .wp-block-button__link{width: unset;}.uagb-block-dd0fd90b .uagb-modal-trigger{justify-content: center;}.uagb-block-dd0fd90b .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b4134ba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b4134ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8b4134ba{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c415eb6d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c415eb6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c415eb6d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-eac8718a.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-eac8718a.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44ca3756{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44ca3756 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-44ca3756{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3 .uagb-heading-text{font-size: 18px;}.uagb-block-fce33136.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-fce33136 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-fce33136 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-fce33136.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-fce33136 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-fce33136 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fce33136.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fce33136.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-fce33136.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-fce33136 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-fce33136.uagb-modal-wrapper{text-align: center;}.uagb-block-fce33136 .wp-block-button__link{width: unset;}.uagb-block-fce33136 .uagb-modal-trigger{justify-content: center;}.uagb-block-fce33136 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-888e8130 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-888e8130 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-888e8130 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-888e8130 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-888e8130 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-888e8130{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-888e8130 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-888e8130{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bfe84470 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bfe84470 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bfe84470 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bfe84470 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bfe84470 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bfe84470{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bfe84470 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bfe84470{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-faee79c9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-faee79c9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-faee79c9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-faee79c9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-faee79c9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-faee79c9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-faee79c9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-faee79c9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9e35ac0a.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9e35ac0a.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9e35ac0a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-9e35ac0a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9e35ac0a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9e35ac0a.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-ef654185 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ef654185 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ef654185 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ef654185 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ef654185 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ef654185{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ef654185 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ef654185{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0425b1ba.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-0425b1ba.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0425b1ba.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0425b1ba.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0425b1ba.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0425b1ba .uagb-heading-text{font-size: 18px;}.uagb-block-01a9aad7.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-01a9aad7 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-01a9aad7 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-01a9aad7.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-01a9aad7 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-01a9aad7 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01a9aad7.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-01a9aad7 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-01a9aad7.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-01a9aad7 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-01a9aad7 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-01a9aad7 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-01a9aad7 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-01a9aad7 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-01a9aad7.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-01a9aad7 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-01a9aad7.uagb-modal-wrapper{text-align: center;}.uagb-block-01a9aad7 .wp-block-button__link{width: unset;}.uagb-block-01a9aad7 .uagb-modal-trigger{justify-content: center;}.uagb-block-01a9aad7 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-9a24f401 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9a24f401 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9a24f401 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9a24f401 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9a24f401 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a24f401{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a24f401 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9a24f401{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fcc017ed .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fcc017ed .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fcc017ed .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fcc017ed .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fcc017ed .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fcc017ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fcc017ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fcc017ed{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-6f089be0.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6f089be0.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-6f089be0.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6f089be0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-6f089be0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-6f089be0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-6f089be0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-6f089be0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-6f089be0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-6f089be0.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-6f089be0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-6f089be0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-6f089be0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-6f089be0.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6f089be0.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-92766771 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92766771 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92766771 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92766771 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92766771 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92766771{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92766771 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-92766771{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-d9cdac4f.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-d9cdac4f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d9cdac4f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9cdac4f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9cdac4f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9cdac4f .uagb-heading-text{font-size: 18px;}.uagb-block-11964555.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-11964555 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-11964555 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-11964555.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-11964555 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-11964555 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-11964555.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-11964555 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-11964555.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-11964555 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-11964555 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-11964555 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-11964555 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-11964555 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-11964555.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-11964555 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-11964555.uagb-modal-wrapper{text-align: center;}.uagb-block-11964555 .wp-block-button__link{width: unset;}.uagb-block-11964555 .uagb-modal-trigger{justify-content: center;}.uagb-block-11964555 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-b283be7b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b283be7b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b283be7b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b283be7b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b283be7b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b283be7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b283be7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b283be7b{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eeaba153 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eeaba153 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eeaba153 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eeaba153 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eeaba153 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eeaba153{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eeaba153 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eeaba153{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-056687a0.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-056687a0.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-056687a0.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-056687a0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-056687a0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-056687a0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-056687a0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-056687a0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-056687a0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-056687a0.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-056687a0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-056687a0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-056687a0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-056687a0.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-056687a0.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-fefed838 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fefed838 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fefed838 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fefed838 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fefed838 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fefed838{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fefed838 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fefed838{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-5ae07438.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-5ae07438.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5ae07438.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5ae07438.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5ae07438.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5ae07438 .uagb-heading-text{font-size: 18px;}.uagb-block-7b2caf4a.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-7b2caf4a .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-7b2caf4a .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-7b2caf4a.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-7b2caf4a .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-7b2caf4a .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7b2caf4a.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-7b2caf4a .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-7b2caf4a.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-7b2caf4a .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-7b2caf4a .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-7b2caf4a .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-7b2caf4a .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-7b2caf4a .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-7b2caf4a.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-7b2caf4a .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-7b2caf4a.uagb-modal-wrapper{text-align: center;}.uagb-block-7b2caf4a .wp-block-button__link{width: unset;}.uagb-block-7b2caf4a .uagb-modal-trigger{justify-content: center;}.uagb-block-7b2caf4a .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-bf8bfd11 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bf8bfd11 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bf8bfd11 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bf8bfd11 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bf8bfd11 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf8bfd11{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bf8bfd11 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bf8bfd11{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8a494c20 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8a494c20 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8a494c20 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8a494c20 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8a494c20 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8a494c20{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8a494c20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8a494c20{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ee716a0b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ee716a0b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ee716a0b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ee716a0b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ee716a0b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ee716a0b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ee716a0b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ee716a0b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ea1fb0fa.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-ea1fb0fa.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-ea1fb0fa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-ea1fb0fa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-ea1fb0fa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ea1fb0fa.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-9414a69a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9414a69a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9414a69a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9414a69a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9414a69a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9414a69a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9414a69a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9414a69a{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-071dea48.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-071dea48.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-071dea48.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-071dea48.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-071dea48.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-071dea48 .uagb-heading-text{font-size: 18px;}.uagb-block-3705820d.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-3705820d .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-3705820d .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-3705820d.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-3705820d .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-3705820d .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3705820d.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-3705820d .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-3705820d.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-3705820d .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-3705820d .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-3705820d .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-3705820d .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-3705820d .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-3705820d.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-3705820d .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-3705820d.uagb-modal-wrapper{text-align: center;}.uagb-block-3705820d .wp-block-button__link{width: unset;}.uagb-block-3705820d .uagb-modal-trigger{justify-content: center;}.uagb-block-3705820d .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-ad29aca7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ad29aca7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ad29aca7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ad29aca7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ad29aca7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad29aca7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad29aca7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ad29aca7{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bfb6dbe1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bfb6dbe1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bfb6dbe1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bfb6dbe1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bfb6dbe1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bfb6dbe1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bfb6dbe1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bfb6dbe1{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-4a496e62.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4a496e62.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4a496e62.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4a496e62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-4a496e62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4a496e62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4a496e62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4a496e62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4a496e62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4a496e62.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4a496e62.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-4a496e62.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4a496e62.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4a496e62.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4a496e62.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-18ba2212 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-18ba2212 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-18ba2212 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-18ba2212 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-18ba2212 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-18ba2212{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-18ba2212 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-18ba2212{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-4c5c8765.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-4c5c8765.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4c5c8765.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4c5c8765.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4c5c8765.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4c5c8765 .uagb-heading-text{font-size: 18px;}.uagb-block-f7727bc4.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-f7727bc4 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-f7727bc4 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-f7727bc4.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-f7727bc4 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-f7727bc4 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f7727bc4.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-f7727bc4 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-f7727bc4.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-f7727bc4 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-f7727bc4 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-f7727bc4 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-f7727bc4 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-f7727bc4 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-f7727bc4.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-f7727bc4 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-f7727bc4.uagb-modal-wrapper{text-align: center;}.uagb-block-f7727bc4 .wp-block-button__link{width: unset;}.uagb-block-f7727bc4 .uagb-modal-trigger{justify-content: center;}.uagb-block-f7727bc4 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-ef797863 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ef797863 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ef797863 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ef797863 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ef797863 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ef797863{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ef797863 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ef797863{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dfc50cce .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dfc50cce .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dfc50cce .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dfc50cce .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dfc50cce .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dfc50cce{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dfc50cce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dfc50cce{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-41177162.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-41177162.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-41177162.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-41177162.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-41177162.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-41177162.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-41177162.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-41177162.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-41177162.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-41177162.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-41177162.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-41177162.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-41177162.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-41177162.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-41177162.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-f57a0b8e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f57a0b8e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f57a0b8e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f57a0b8e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f57a0b8e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f57a0b8e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f57a0b8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f57a0b8e{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-48c1b815.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-48c1b815.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-48c1b815.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-48c1b815.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-48c1b815.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-48c1b815 .uagb-heading-text{font-size: 18px;}.uagb-block-58d8d430.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-58d8d430 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-58d8d430 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-58d8d430.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-58d8d430 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-58d8d430 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-58d8d430.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-58d8d430 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-58d8d430.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-58d8d430 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-58d8d430 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-58d8d430 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-58d8d430 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-58d8d430 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-58d8d430.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-58d8d430 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-58d8d430.uagb-modal-wrapper{text-align: center;}.uagb-block-58d8d430 .wp-block-button__link{width: unset;}.uagb-block-58d8d430 .uagb-modal-trigger{justify-content: center;}.uagb-block-58d8d430 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e782373{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e782373 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1e782373{box-shadow: 0px 0px   #00000070 ;padding-top: 75px;padding-bottom: 75px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-729e4697{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-729e4697 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-729e4697{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773 .uagb-heading-text{font-size: 30px;}.uagb-block-674e1289.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-674e1289 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-674e1289 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-674e1289.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-674e1289 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-674e1289 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-674e1289.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-674e1289.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 32px;padding-right: 32px;padding-top: 14px;padding-bottom: 14px;color: var(--ast-global-color-5);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{fill: var(--ast-global-color-5);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-674e1289.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-674e1289 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-674e1289.uagb-modal-wrapper{text-align: left;}.uagb-block-674e1289 .wp-block-button__link{width: unset;}.uagb-block-674e1289 .uagb-modal-trigger{justify-content: flex-start;}.uagb-block-674e1289 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-heading-text{color: #060a12;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8 .uagb-heading-text{font-weight: 600;font-size: 22px;}.wp-block-uagb-container.uagb-block-6fe57f65 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6fe57f65 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6fe57f65 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6fe57f65 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6fe57f65 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fe57f65{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fe57f65 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6fe57f65{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-afa9aabc.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-afa9aabc.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-afa9aabc.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-afa9aabc.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-afa9aabc.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-afa9aabc.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27ec6df1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27ec6df1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-27ec6df1{box-shadow: 0px 0px   #00000070 ;padding-top: 75px;padding-bottom: 75px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f6f6f6;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4b3ee1c{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4b3ee1c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d4b3ee1c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-da368a29.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-da368a29.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bd96d48{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bd96d48 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2bd96d48{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-9855b031.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9855b031.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9855b031.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9855b031.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9855b031 .uagb-heading-text{font-size: 30px;}.uagb-block-f858eb1f.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 95vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-f858eb1f .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-f858eb1f .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-f858eb1f.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-f858eb1f .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-f858eb1f .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f858eb1f.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-f858eb1f.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 32px;padding-right: 32px;padding-top: 14px;padding-bottom: 14px;color: var(--ast-global-color-5);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{fill: var(--ast-global-color-5);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-f858eb1f.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-f858eb1f .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-f858eb1f.uagb-modal-wrapper{text-align: left;}.uagb-block-f858eb1f .wp-block-button__link{width: unset;}.uagb-block-f858eb1f .uagb-modal-trigger{justify-content: flex-start;}.uagb-block-f858eb1f .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-heading-text{color: #060a12;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87 .uagb-heading-text{font-weight: 600;font-size: 22px;}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3e2b8f2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3e2b8f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e3e2b8f2{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7eacc968{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7eacc968 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7eacc968{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6076012b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6076012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 50px;}.wp-block-uagb-container.uagb-block-6076012b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 50px;}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c74a02f{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c74a02f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1c74a02f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-5f66276d.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5f66276d .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-5f66276d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: px;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5f66276d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-435fd273{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-435fd273 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-435fd273{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-112d9740{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-112d9740 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-112d9740{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: ;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a9f51d0{max-width: 85%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a9f51d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6a9f51d0{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-3e8de48a .uagb-icon svg{width: 12px;height: 12px;font-size: 12px;fill: var(--ast-global-color-8);}.uagb-block-3e8de48a .uagb-icon-active svg{width: 12px;height: 12px;font-size: 12px;}.uagb-block-3e8de48a .uagb-faq-child__outer-wrap{margin-bottom: 10px;}.uagb-block-3e8de48a .uagb-faq-item{background-color: #f6f6f6;border-top-left-radius: 2px;border-top-right-radius: 2px;border-bottom-left-radius: 2px;border-bottom-right-radius: 2px;border-color: #D2D2D2;border-style: none;}.uagb-block-3e8de48a .uagb-faq-item .uagb-question{color: var(--ast-global-color-8);}.uagb-block-3e8de48a .uagb-faq-questions-button{padding-top: 15px;padding-bottom: 15px;padding-right: 15px;padding-left: 15px;}.uagb-block-3e8de48a .uagb-faq-content{padding-top: 0px;padding-bottom: 15px;padding-right: 15px;padding-left: 15px;}.uagb-block-3e8de48a .uagb-faq-content span{margin-top: 0px;margin-bottom: 15px;margin-right: 15px;margin-left: 15px;}.uagb-block-3e8de48a.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-3e8de48a.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-3e8de48a .uagb-faq-item .uagb-faq-questions-button.uagb-faq-questions{flex-direction: row-reverse;}.uagb-block-3e8de48a .uagb-faq-item .uagb-faq-content{font-size: 14px;color: #858a93;}.uagb-block-3e8de48a .wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-content {display: none;}.uagb-block-3e8de48a .uagb-faq-questions-button .uagb-question{font-weight: 600;font-size: 16px;}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75d67f4d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75d67f4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-75d67f4d{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9 .uagb-heading-text{font-size: 40px;}.uagb-block-47dc8831.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-47dc8831.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-47dc8831:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-47dc8831:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-47dc8831:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-47dc8831:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-47dc8831:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-47dc8831:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-47dc8831 .uagb-post__inner-wrap{background: #f6f6f6;text-align: left;}.uagb-block-47dc8831 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-47dc8831 .uagb-post__image {padding-bottom: 15px;}.uagb-block-47dc8831 .uagb-post__title{padding-bottom: 15px;}.uagb-block-47dc8831 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-47dc8831 .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-47dc8831 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-47dc8831.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-47dc8831.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(3 , minmax(0, 1fr));}.uagb-block-47dc8831.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-47dc8831 .uagb-post__text.uagb-post__title{font-size: 20px;}.uagb-block-47dc8831 .uagb-post__text.uagb-post__title a{font-size: 20px;}.uagb-block-47dc8831 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-47dc8831 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-47dc8831 .uagb-post__text.uagb-post__excerpt{font-size: 16px;}.uagb-block-47dc8831.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {color: var(--ast-global-color-5);0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: none;border-style: none;}.uagb-block-47dc8831.uagb-post-grid .uagb-post__inner-wrap .wp-block-button.uagb-post__text.uagb-post__cta a{color: var(--ast-global-color-5);}.uagb-block-47dc8831 .uagb-post-pagination-wrap{margin-top: 20px;justify-content: left;margin-left: 10px;}.uagb-block-47dc8831 .uagb-post-pagination-wrap .page-numbers.current{background-color: #e4e4e4;color: #333333;}.uagb-block-47dc8831 .uagb-post-pagination-wrap a{background-color: #e4e4e4;color: #777777;}.uagb-block-47dc8831.uagb-equal_height_inline-read-more-buttons .uagb-post__inner-wrap .uagb-post__text:last-child{left: 20px;right: 20px;}.uagb-block-47dc8831.wp-block-uagb-post-grid .uag-post-grid-wrapper{padding-right: 20px;padding-left: 20px;width: 100%;display: flex;flex-direction: column;justify-content: center;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-90c2c68b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-90c2c68b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-90c2c68b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/hdpe-pipe-1.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-90c2c68b::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-8);opacity: 0.2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42e0e8e6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42e0e8e6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-42e0e8e6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3de41139{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3de41139 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3de41139{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-ccbe86b2.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-ccbe86b2 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-ccbe86b2 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0aa5aa3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0aa5aa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f0aa5aa3{padding-top: 75px;padding-bottom: 65px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f4f6f9;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b31ce7bf{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b31ce7bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b31ce7bf{padding-top: 75px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed0f7e26{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed0f7e26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ed0f7e26{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd817a82{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd817a82 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dd817a82{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5c073af6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5c073af6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5c073af6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5860e71a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5860e71a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5860e71a{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-048f0bfe.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-048f0bfe .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-048f0bfe .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8342395{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8342395 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e8342395{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f80ca2c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f80ca2c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5f80ca2c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a1a2f46d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a1a2f46d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a1a2f46d{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-dd0fd90b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-dd0fd90b .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-dd0fd90b .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b4134ba{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b4134ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8b4134ba{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c415eb6d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c415eb6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c415eb6d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44ca3756{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44ca3756 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-44ca3756{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-fce33136.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fce33136 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-fce33136 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-888e8130{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-888e8130 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-888e8130{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bfe84470{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bfe84470 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bfe84470{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-faee79c9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-faee79c9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-faee79c9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-9e35ac0a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ef654185{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ef654185 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ef654185{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-01a9aad7.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-01a9aad7 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-01a9aad7 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-01a9aad7 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a24f401{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a24f401 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9a24f401{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fcc017ed{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fcc017ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-fcc017ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-6f089be0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92766771{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92766771 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-92766771{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-11964555.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-11964555 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-11964555 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-11964555 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b283be7b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b283be7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b283be7b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eeaba153{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eeaba153 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eeaba153{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-056687a0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fefed838{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fefed838 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-fefed838{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-7b2caf4a.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-7b2caf4a .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-7b2caf4a .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-7b2caf4a .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf8bfd11{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bf8bfd11 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bf8bfd11{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8a494c20{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8a494c20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8a494c20{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ee716a0b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ee716a0b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ee716a0b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-ea1fb0fa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9414a69a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9414a69a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9414a69a{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-3705820d.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-3705820d .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-3705820d .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-3705820d .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad29aca7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad29aca7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ad29aca7{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bfb6dbe1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bfb6dbe1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bfb6dbe1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-4a496e62.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-18ba2212{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-18ba2212 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-18ba2212{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-f7727bc4.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-f7727bc4 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-f7727bc4 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-f7727bc4 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ef797863{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ef797863 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ef797863{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dfc50cce{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dfc50cce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dfc50cce{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-41177162.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f57a0b8e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f57a0b8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f57a0b8e{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-58d8d430.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-58d8d430 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-58d8d430 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-58d8d430 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e782373{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e782373 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1e782373{padding-top: 75px;padding-bottom: 75px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-729e4697{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-729e4697 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-729e4697{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-674e1289.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-674e1289 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-674e1289 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fe57f65{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fe57f65 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6fe57f65{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-afa9aabc.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27ec6df1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27ec6df1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-27ec6df1{padding-top: 75px;padding-bottom: 75px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f6f6f6;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4b3ee1c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4b3ee1c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d4b3ee1c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bd96d48{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bd96d48 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2bd96d48{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-f858eb1f.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-f858eb1f .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-f858eb1f .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3e2b8f2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3e2b8f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e3e2b8f2{padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7eacc968{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7eacc968 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7eacc968{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6076012b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6076012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6076012b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c74a02f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c74a02f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1c74a02f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-435fd273{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-435fd273 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-435fd273{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-112d9740{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-112d9740 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-112d9740{padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a9f51d0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a9f51d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6a9f51d0{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-3e8de48a.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-3e8de48a.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-3e8de48a .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-3e8de48a .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-3e8de48a .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.uagb-block-3e8de48a .uagb-faq-item{border-style: none;border-color: #D2D2D2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75d67f4d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75d67f4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-75d67f4d{padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-47dc8831.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-47dc8831.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-47dc8831:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-47dc8831:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-47dc8831.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-47dc8831.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-47dc8831 .uagb-post__cta a{border-style: none;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-90c2c68b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-90c2c68b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-90c2c68b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/hdpe-pipe-1.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-90c2c68b::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-8);opacity: 0.2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42e0e8e6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42e0e8e6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-42e0e8e6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3de41139{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3de41139 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3de41139{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-1f746054 .uagb-heading-text{font-size: 25px;}.uagb-block-ccbe86b2.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-ccbe86b2 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-ccbe86b2 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-ccbe86b2 .wp-block-button__link{width: unset;}.uagb-block-ccbe86b2 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0aa5aa3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0aa5aa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f0aa5aa3{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f4f6f9;;}.wp-block-uagb-advanced-heading.uagb-block-421ce500 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b31ce7bf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b31ce7bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b31ce7bf{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed0f7e26{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed0f7e26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ed0f7e26{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd817a82{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd817a82 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dd817a82{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5c073af6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5c073af6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5c073af6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5860e71a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5860e71a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5860e71a{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-048f0bfe.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-048f0bfe .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-048f0bfe .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-048f0bfe .wp-block-button__link{width: unset;}.uagb-block-048f0bfe .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8342395{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8342395 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e8342395{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f80ca2c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f80ca2c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5f80ca2c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a1a2f46d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a1a2f46d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a1a2f46d{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-dd0fd90b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-dd0fd90b .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-dd0fd90b .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-dd0fd90b .wp-block-button__link{width: unset;}.uagb-block-dd0fd90b .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b4134ba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b4134ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8b4134ba{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c415eb6d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c415eb6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c415eb6d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44ca3756{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44ca3756 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-44ca3756{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-fce33136.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-fce33136 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fce33136 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-fce33136 .wp-block-button__link{width: unset;}.uagb-block-fce33136 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-888e8130{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-888e8130 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-888e8130{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bfe84470{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bfe84470 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bfe84470{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-faee79c9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-faee79c9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-faee79c9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-9e35ac0a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ef654185{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ef654185 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ef654185{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-01a9aad7.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-01a9aad7 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-01a9aad7 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-01a9aad7 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-01a9aad7 .wp-block-button__link{width: unset;}.uagb-block-01a9aad7 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a24f401{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a24f401 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9a24f401{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fcc017ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fcc017ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fcc017ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-6f089be0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92766771{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92766771 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-92766771{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-11964555.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-11964555 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-11964555 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-11964555 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-11964555 .wp-block-button__link{width: unset;}.uagb-block-11964555 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b283be7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b283be7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b283be7b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eeaba153{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eeaba153 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-eeaba153{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-056687a0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fefed838{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fefed838 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fefed838{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-7b2caf4a.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-7b2caf4a .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-7b2caf4a .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-7b2caf4a .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-7b2caf4a .wp-block-button__link{width: unset;}.uagb-block-7b2caf4a .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf8bfd11{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bf8bfd11 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bf8bfd11{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8a494c20{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8a494c20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8a494c20{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ee716a0b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ee716a0b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ee716a0b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-ea1fb0fa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9414a69a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9414a69a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9414a69a{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-3705820d.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-3705820d .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-3705820d .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-3705820d .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-3705820d .wp-block-button__link{width: unset;}.uagb-block-3705820d .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad29aca7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad29aca7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ad29aca7{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bfb6dbe1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bfb6dbe1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bfb6dbe1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-4a496e62.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-18ba2212{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-18ba2212 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-18ba2212{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-f7727bc4.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-f7727bc4 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-f7727bc4 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-f7727bc4 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-f7727bc4 .wp-block-button__link{width: unset;}.uagb-block-f7727bc4 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ef797863{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ef797863 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ef797863{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dfc50cce{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dfc50cce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dfc50cce{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-41177162.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f57a0b8e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f57a0b8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f57a0b8e{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-58d8d430.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-58d8d430 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-58d8d430 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-58d8d430 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-58d8d430 .wp-block-button__link{width: unset;}.uagb-block-58d8d430 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e782373{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e782373 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1e782373{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-729e4697{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-729e4697 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-729e4697{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773 .uagb-heading-text{font-size: 25px;}.uagb-block-674e1289.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-674e1289 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-674e1289 .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-674e1289 .wp-block-button__link{width: unset;}.uagb-block-674e1289 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fe57f65{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fe57f65 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6fe57f65{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-afa9aabc.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27ec6df1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27ec6df1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-27ec6df1{padding-top: 75px;padding-bottom: 75px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f6f6f6;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4b3ee1c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4b3ee1c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d4b3ee1c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bd96d48{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bd96d48 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2bd96d48{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-9855b031 .uagb-heading-text{font-size: 25px;}.uagb-block-f858eb1f.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;max-height: 90vh;border-style: none;border-color: none;}.uagb-block-f858eb1f .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-f858eb1f .uagb-modal-button-link svg {margin-right: 5px;}.uagb-block-f858eb1f .wp-block-button__link{width: unset;}.uagb-block-f858eb1f .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3e2b8f2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3e2b8f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e3e2b8f2{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7eacc968{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7eacc968 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7eacc968{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6076012b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6076012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6076012b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c74a02f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c74a02f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1c74a02f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-435fd273{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-435fd273 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-435fd273{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-112d9740{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-112d9740 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-112d9740{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a9f51d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a9f51d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6a9f51d0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-3e8de48a.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-3e8de48a .uagb-faq-item{border-style: none;border-color: #D2D2D2;}.uagb-block-3e8de48a.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-3e8de48a .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-3e8de48a .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-3e8de48a .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75d67f4d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75d67f4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-75d67f4d{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9 .uagb-heading-text{font-size: 25px;}.uagb-block-47dc8831.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-47dc8831.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-47dc8831:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-47dc8831:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-47dc8831.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-47dc8831.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-47dc8831.wp-block-uagb-post-grid .uag-post-grid-wrapper{width: unset;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd25c91f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6cdf3e7d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-83d25a5b{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dd25c91f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6cdf3e7d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-83d25a5b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dd25c91f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6cdf3e7d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-83d25a5b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-83d25a5b.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-83d25a5b.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-92b3da43{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2 .uagb-heading-text{font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;font-family: \"Poppins\";text-decoration: !important;line-height: em;color: #727579;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child{font-family: \"Poppins\";text-decoration: !important;font-size: 14px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-32ea5357.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-32ea5357.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-e403deab.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-e403deab.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-767efdcf.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-767efdcf.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c9e2a33c.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c9e2a33c.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0ce47b4.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0ce47b4.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c374f4a6.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c374f4a6.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-92b3da43{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-92b3da43{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-15aa5f8a{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d .uagb-heading-text{font-family: \"Poppins\";font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;text-decoration: !important;line-height: em;color: #727579;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 14px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-2a807afe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2a807afe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4b5bca07.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4b5bca07.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4f7e8fc.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4f7e8fc.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-3899fefe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-3899fefe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-29ce129e.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-29ce129e.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-15aa5f8a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-15aa5f8a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ca12eada{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33 .uagb-heading-text{font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 16px;text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 16px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ca12eada{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ca12eada{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{box-shadow: 0px 4px 12px 0px #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-style: solid;border-color: #dadbdd;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #dadbdd;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #dadbdd;}}\";s:2:\"js\";s:3794:\"document.addEventListener(\"DOMContentLoaded\", function(){ \t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-ccbe86b2', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-048f0bfe', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-dd0fd90b', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-fce33136', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-01a9aad7', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-11964555', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-7b2caf4a', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-3705820d', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-f7727bc4', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-58d8d430', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-674e1289', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-f858eb1f', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t });\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"uagb\/container\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:14:\"core\/paragraph\";i:5;s:10:\"uagb\/modal\";i:6;s:21:\"fluentfom\/guten-block\";i:10;s:10:\"uagb\/image\";i:11;s:10:\"core\/embed\";i:13;s:8:\"uagb\/faq\";i:14;s:14:\"uagb\/faq-child\";i:15;s:14:\"uagb\/post-grid\";i:18;s:10:\"core\/image\";i:19;s:14:\"uagb\/icon-list\";i:20;s:20:\"uagb\/icon-list-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1778638141;s:6:\"gfonts\";a:1:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:1;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Hualinpipe","author_link":"https:\/\/fshualinkeji.com\/ar\/author\/juntongtechoutlook-com\/"},"uagb_comment_info":0,"uagb_excerpt":"PVC Pipe PVC pipe is a plastic pipe made of polyvinyl chloride resin as the main raw material and formed [&hellip;]","_links":{"self":[{"href":"https:\/\/fshualinkeji.com\/ar\/wp-json\/wp\/v2\/pages\/2317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fshualinkeji.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fshualinkeji.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/ar\/wp-json\/wp\/v2\/comments?post=2317"}],"version-history":[{"count":29,"href":"https:\/\/fshualinkeji.com\/ar\/wp-json\/wp\/v2\/pages\/2317\/revisions"}],"predecessor-version":[{"id":2463,"href":"https:\/\/fshualinkeji.com\/ar\/wp-json\/wp\/v2\/pages\/2317\/revisions\/2463"}],"wp:attachment":[{"href":"https:\/\/fshualinkeji.com\/ar\/wp-json\/wp\/v2\/media?parent=2317"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}