{"id":832,"date":"2025-05-26T02:38:39","date_gmt":"2025-05-26T09:38:39","guid":{"rendered":"https:\/\/fshualinkeji.com\/?page_id=832"},"modified":"2025-06-15T23:54:26","modified_gmt":"2025-06-16T06:54:26","slug":"tuberia-de-hdpe-de-8-pulgadas","status":"publish","type":"page","link":"https:\/\/fshualinkeji.com\/es\/tuberia-de-hdpe-de-8-pulgadas\/","title":{"rendered":"Tubo de Hdpe de 8 pulgadas"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-90c2c68b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-42e0e8e6\">\n<div class=\"wp-block-uagb-container uagb-block-3de41139\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1f746054\"><h2 class=\"uagb-heading-text\">Tubo de Hdpe de 8 pulgadas<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-84140f4c\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-2bc49334\"><span class=\"uagb-icon-list__label\">-Ligero, f\u00e1cil de instalar y puede utilizarse de forma estable en diversos entornos complejos.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-b196174a\"><span class=\"uagb-icon-list__label\">-Fuerte resistencia a los impactos<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-48a7ce62\"><span class=\"uagb-icon-list__label\">-Larga vida \u00fatil<\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-ccbe86b2 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Solicite nuestro \u00faltimo precio<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-ccbe86b2 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8d2e6c49\"><h2 class=\"uagb-heading-text\">Env\u00ede su consulta hoy mismo<\/h2><\/div>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_1\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_input_text' id='label_ff_2_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_email' id='label_ff_2_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_phone' id='label_ff_2_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_description' id='label_ff_2_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_description\" name=\"description\" id=\"ff_2_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_1 ff-form-loading_errors ff_form_instance_2_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_1 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_1\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f0aa5aa3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-421ce500\"><h2 class=\"uagb-heading-text\">Fabricante de tubos Hdpe de 8 pulgadas en China<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">El tubo HDPE de 8 pulgadas es un tubo fabricado con polietileno de alta densidad (HDPE) como materia prima principal y producido mediante el proceso de moldeo por extrusi\u00f3n. Su di\u00e1metro nominal es de aproximadamente 203 mm (1 pulgada \u2248 25,4 mm). Su pared interior es lisa y la resistencia al fluido es peque\u00f1a, lo que puede reducir eficazmente el consumo de energ\u00eda del transporte. Al mismo tiempo, tiene una buena resistencia a las bajas temperaturas y un buen rendimiento antienvejecimiento, y tiene una larga vida \u00fatil. Es uno de los tubos de pl\u00e1stico m\u00e1s utilizados en la construcci\u00f3n de ingenier\u00eda moderna.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b31ce7bf alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7499abf3\"><h2 class=\"uagb-heading-text\">Tubo de Hdpe de 8 pulgadas<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ed0f7e26\">\n<div class=\"wp-block-uagb-container uagb-block-dd817a82\">\n<div class=\"wp-block-uagb-container uagb-block-5c073af6\">\n<div class=\"wp-block-uagb-image uagb-block-a4d3fb33 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg\" alt=\"\" class=\"uag-image-612\" width=\"600\" height=\"400\" title=\"tuber\u00edas de abastecimiento y evacuaci\u00f3n de agua de polietileno de alta densidad\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5860e71a\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7c1dd511\"><p class=\"uagb-heading-text\">Tubos de suministro de agua de Hdpe<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-048f0bfe uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Enviar consulta ahora<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-048f0bfe uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>Env\u00ede su consulta hoy mismo<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_2 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_2\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_2_input_text' id='label_ff_2_2_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_2_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_2_email' id='label_ff_2_2_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_2_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_2_phone' id='label_ff_2_2_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_2_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_2_description' id='label_ff_2_2_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_2_description\" name=\"description\" id=\"ff_2_2_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_2 ff-form-loading_errors ff_form_instance_2_2_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_2 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_2\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e8342395\">\n<div class=\"wp-block-uagb-container uagb-block-5f80ca2c\">\n<div class=\"wp-block-uagb-image uagb-block-1fea2c99 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Perforated-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Perforated-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Perforated-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Perforated-Pipe.jpg\" alt=\"\" class=\"uag-image-614\" width=\"600\" height=\"400\" title=\"Tubo perforado de HDPE\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a1a2f46d\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8b077f06\"><p class=\"uagb-heading-text\">Tubos perforados de Hdpe<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-dd0fd90b uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Enviar consulta ahora<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-dd0fd90b uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>Env\u00ede su consulta hoy mismo<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_3 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_3\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_3_input_text' id='label_ff_2_3_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_3_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_3_email' id='label_ff_2_3_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_3_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_3_phone' id='label_ff_2_3_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_3_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_3_description' id='label_ff_2_3_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_3_description\" name=\"description\" id=\"ff_2_3_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_3 ff-form-loading_errors ff_form_instance_2_3_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_3 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_3\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8b4134ba\">\n<div class=\"wp-block-uagb-container uagb-block-c415eb6d\">\n<div class=\"wp-block-uagb-image uagb-block-eac8718a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Cable-Tube.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Cable-Tube.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Cable-Tube.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Cable-Tube.jpg\" alt=\"\" class=\"uag-image-616\" width=\"600\" height=\"400\" title=\"HDPE-Cable-Tubo\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-44ca3756\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-49a103f3\"><p class=\"uagb-heading-text\">Tubo de cable HDPE<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-fce33136 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Enviar consulta ahora<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-fce33136 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>Env\u00ede su consulta hoy mismo<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_4 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_4\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_4_input_text' id='label_ff_2_4_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_4_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_4_email' id='label_ff_2_4_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_4_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_4_phone' id='label_ff_2_4_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_4_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_4_description' id='label_ff_2_4_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_4_description\" name=\"description\" id=\"ff_2_4_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_4 ff-form-loading_errors ff_form_instance_2_4_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_4 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_4\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b7caf453\">\n<div class=\"wp-block-uagb-container uagb-block-9b4749ab\">\n<div class=\"wp-block-uagb-container uagb-block-6a39079c\">\n<div class=\"wp-block-uagb-image uagb-block-b336b693 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Sewage-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Sewage-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Sewage-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Sewage-Pipe.jpg\" alt=\"\" class=\"uag-image-620\" width=\"600\" height=\"400\" title=\"Tuber\u00eda de HDPE\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0939215b\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-23d928ee\"><p class=\"uagb-heading-text\">Tubos de Hdpe para alcantarillado<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-fadde365 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Enviar consulta ahora<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-fadde365 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>Env\u00ede su consulta hoy mismo<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_5 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_5\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_5_input_text' id='label_ff_2_5_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_5_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_5_email' id='label_ff_2_5_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_5_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_5_phone' id='label_ff_2_5_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_5_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_5_description' id='label_ff_2_5_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_5_description\" name=\"description\" id=\"ff_2_5_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_5 ff-form-loading_errors ff_form_instance_2_5_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_5 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_5\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2101e8e0\">\n<div class=\"wp-block-uagb-container uagb-block-75914977\">\n<div class=\"wp-block-uagb-image uagb-block-f70f66dd wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Siphon.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Siphon.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Siphon.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/HDPE-Siphon.jpg\" alt=\"\" class=\"uag-image-622\" width=\"600\" height=\"400\" title=\"HDPE-Sif\u00f3n\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-73a2f6f7\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-695ce6b8\"><p class=\"uagb-heading-text\">Sif\u00f3n HDPE<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-6bd32ea0 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Enviar consulta ahora<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-6bd32ea0 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>Env\u00ede su consulta hoy mismo<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_6 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_6\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_6_input_text' id='label_ff_2_6_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_6_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_6_email' id='label_ff_2_6_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_6_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_6_phone' id='label_ff_2_6_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_6_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_6_description' id='label_ff_2_6_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_6_description\" name=\"description\" id=\"ff_2_6_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_6 ff-form-loading_errors ff_form_instance_2_6_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_6 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_6\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8ad04471\">\n<div class=\"wp-block-uagb-container uagb-block-603a8411\">\n<div class=\"wp-block-uagb-image uagb-block-33497584 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Roll-Core-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Roll-Core-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Roll-Core-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Roll-Core-Pipe.jpg\" alt=\"\" class=\"uag-image-624\" width=\"600\" height=\"400\" title=\"Tubo con alma de tubo de polietileno de alta densidad\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-96ae324f\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4ebc0289\"><p class=\"uagb-heading-text\">Tubos en rollo de Hdpe<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-3dbf021b uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Enviar consulta ahora<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-3dbf021b uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<p class=\"has-text-align-center\" style=\"font-size:22px\"><strong>Env\u00ede su consulta hoy mismo<\/strong><\/p>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_7 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_7\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_7_input_text' id='label_ff_2_7_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_7_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_7_email' id='label_ff_2_7_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_7_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_7_phone' id='label_ff_2_7_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_7_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_7_description' id='label_ff_2_7_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_7_description\" name=\"description\" id=\"ff_2_7_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_7 ff-form-loading_errors ff_form_instance_2_7_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_7 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_7\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1e782373 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-729e4697\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0d76f773\"><h2 class=\"uagb-heading-text\">Caracter\u00edsticas principales de los tubos HDPE HUALIN de 8 pulgadas<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">El tubo de HDPE de 8 pulgadas tiene una excelente estabilidad qu\u00edmica. Con su estructura molecular de polietileno de alta densidad, puede resistir eficazmente la erosi\u00f3n de \u00e1cidos, \u00e1lcalis, soluciones salinas y diversos medios qu\u00edmicos, y evitar que la tuber\u00eda se corroa y da\u00f1e. Tiene excelentes propiedades f\u00edsicas, alta resistencia y alta tenacidad, y no es f\u00e1cil de romper o deformar ante el asentamiento del suelo, el impacto externo y otras condiciones. El cuerpo liso de la tuber\u00eda y la baja rugosidad de la pared interior reducen en gran medida la resistencia a la transmisi\u00f3n de fluidos y mejoran la eficiencia de transmisi\u00f3n del medio. En t\u00e9rminos de instalaci\u00f3n y uso, la tuber\u00eda es de peso ligero, lo que reduce en gran medida la carga de construcci\u00f3n y transporte. Los m\u00e9todos de conexi\u00f3n, como la soldadura por fusi\u00f3n en caliente, son f\u00e1ciles de operar, tienen un sellado fuerte y una excelente resistencia a las bajas temperaturas. Incluso en ambientes fr\u00edos, puede mantener una buena tenacidad. Tiene una excelente resistencia a los rayos UV y al envejecimiento, lo que puede garantizar una vida \u00fatil de m\u00e1s de 50 a\u00f1os, proporcionando soluciones de tuber\u00edas duraderas y estables para diversos proyectos.<\/p>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-674e1289 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Enviar consulta ahora<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-674e1289 uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-173df8c8\"><h2 class=\"uagb-heading-text\">Env\u00ede su consulta hoy mismo<\/h2><\/div>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_8 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_8\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_8_input_text' id='label_ff_2_8_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_8_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_8_email' id='label_ff_2_8_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_8_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_8_phone' id='label_ff_2_8_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_8_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_8_description' id='label_ff_2_8_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_8_description\" name=\"description\" id=\"ff_2_8_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_8 ff-form-loading_errors ff_form_instance_2_8_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_8 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_8\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-42c090bc\">\n<div class=\"wp-block-uagb-image uagb-block-8aa82a32 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Features-of-Hdpe-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Features-of-Hdpe-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Features-of-Hdpe-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Features-of-Hdpe-Pipe.jpg\" alt=\"\" class=\"uag-image-628\" width=\"750\" height=\"500\" title=\"Caracter\u00edsticas de las tuber\u00edas de HDPE\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-27ec6df1 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-d4b3ee1c\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-da368a29 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Why-Choose-Our-Hdpe-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Why-Choose-Our-Hdpe-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Why-Choose-Our-Hdpe-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Why-Choose-Our-Hdpe-Pipe.jpg\" alt=\"\" class=\"uag-image-633\" width=\"750\" height=\"500\" title=\"Por qu\u00e9 elegir nuestras tuber\u00edas de HDPE\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2bd96d48\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9855b031\"><h2 class=\"uagb-heading-text\">Consideraciones sobre los tubos HDPE de 8 pulgadas<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">Antes de utilizar los tubos HDPE de 8 pulgadas para la construcci\u00f3n, compruebe cuidadosamente el aspecto de los tubos para asegurarse de que no presentan defectos como grietas, deformaciones, ara\u00f1azos, etc. Al mismo tiempo, verifique si las especificaciones de los tubos y los niveles de presi\u00f3n son adecuados de acuerdo con los requisitos del proyecto; cuando los almacene, evite la luz solar directa, mant\u00e9ngalos alejados de fuentes de calor y objetos afilados para evitar que los tubos aceleren su envejecimiento o se da\u00f1en. Durante el proceso de instalaci\u00f3n, es necesario controlar estrictamente el proceso de conexi\u00f3n por fusi\u00f3n en caliente o fusi\u00f3n el\u00e9ctrica, controlar la temperatura de soldadura, el tiempo y los par\u00e1metros de presi\u00f3n, asegurarse de que la interfaz est\u00e1 firmemente sellada, y el fondo de la ranura donde se coloca la tuber\u00eda debe ser plano y s\u00f3lido para evitar que el asentamiento desigual provoque la rotura de la tuber\u00eda. Durante la fase de funcionamiento, es necesario prestar atenci\u00f3n a que la temperatura del medio de transporte no supere los 60\u00b0C durante mucho tiempo para evitar que el rendimiento de la tuber\u00eda se vea afectado por una temperatura excesiva. Tambi\u00e9n es necesario inspeccionar la tuber\u00eda regularmente para prestar atenci\u00f3n a si hay deformaciones anormales, fugas y otros problemas para garantizar la estabilidad y el funcionamiento seguro del sistema de tuber\u00edas de HDPE.<\/p>\n\n\n\n<div class=\"wp-block-uagb-modal uagb-block-f858eb1f uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">Enviar consulta ahora<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-f858eb1f uagb-modal-type-popup uagb-modal-position-centered\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8d8acc87\"><h2 class=\"uagb-heading-text\">Env\u00ede su consulta hoy mismo<\/h2><\/div>\n\n\n<div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_9 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_9\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulario emergente<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='832' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"7aec08204b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/832\" \/><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_9_input_text' id='label_ff_2_9_input_text' aria-label=\"Nombre\">Nombre<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nombre\" data-name=\"input_text\" id=\"ff_2_9_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_9_email' id='label_ff_2_9_email' aria-label=\"Correo electr\u00f3nico\">Correo electr\u00f3nico<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_9_email\" class=\"ff-el-form-control\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_9_phone' id='label_ff_2_9_phone' aria-label=\"Tel\u00e9fono\/WhatsAPP\">Tel\u00e9fono\/WhatsAPP<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"N\u00famero de m\u00f3vil\" data-name=\"phone\" id=\"ff_2_9_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"false\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_9_description' id='label_ff_2_9_description' aria-label=\"Mensajes\">Mensajes<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_2_9_description\" name=\"description\" id=\"ff_2_9_description\" class=\"ff-el-form-control\" placeholder=\"Mensajes\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_9 ff-form-loading_errors ff_form_instance_2_9_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_9 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_9\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global_message\":\"\\u6b64\\u5b57\\u6bb5\\u5fc5\\u987b\\u5305\\u542b\\u6709\\u6548\\u7684\\u7535\\u5b50\\u90ae\\u7bb1\\u5730\\u5740\",\"global\":true}},\"phone\":{\"required\":{\"value\":false,\"global\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"\\u7535\\u8bdd\\u53f7\\u7801\\u65e0\\u6548\"}},\"description\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"\\u8fd9\\u662f\\u5fc5\\u586b\\u680f\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Cerrar Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e3e2b8f2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-7eacc968\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1ebe5639\"><h2 class=\"uagb-heading-text\">Exploraci\u00f3n de las aplicaciones de los tubos HDPE HUALIN de 8 pulgadas<\/h2><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6076012b\">\n<div class=\"wp-block-uagb-container uagb-block-1c74a02f\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-5f66276d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/PE-Pipe-Applications.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/PE-Pipe-Applications.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/PE-Pipe-Applications.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/PE-Pipe-Applications.jpg\" alt=\"\" class=\"uag-image-482\" width=\"750\" height=\"500\" title=\"Aplicaciones de tuber\u00edas de PE\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-435fd273\">\n<div class=\"wp-block-uagb-image uagb-block-07cc6c1b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/PE-Pipe-Applications-2.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/PE-Pipe-Applications-2.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/PE-Pipe-Applications-2.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/PE-Pipe-Applications-2.jpg\" alt=\"\" class=\"uag-image-484\" width=\"750\" height=\"500\" title=\"PE-Tuber\u00edas-Aplicaciones-2\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<p style=\"font-size:16px\">El tubo HDPE de 8 pulgadas tiene un excelente rendimiento. En proyectos de suministro de agua y drenaje, puede utilizarse como red municipal de suministro de agua para garantizar un suministro de agua seguro y estable, y tambi\u00e9n puede utilizarse en sistemas de descarga de aguas residuales para resistir la erosi\u00f3n por sustancias corrosivas en las aguas residuales; en el riego agr\u00edcola, su resistencia a la intemperie y su capacidad antiobstrucci\u00f3n garantizan un suministro uniforme del agua de riego y ayudan a un riego preciso; adem\u00e1s, en las industrias de comunicaciones y energ\u00eda, el tubo HDPE de 8 pulgadas se utiliza a menudo como manguito de protecci\u00f3n de cables. Con su alta resistencia y resistencia al impacto, proporciona una protecci\u00f3n fiable para los cables subterr\u00e1neos. Al mismo tiempo, tiene un buen rendimiento en la tecnolog\u00eda de construcci\u00f3n sin zanjas, reduciendo los da\u00f1os al suelo y reduciendo los costes y ciclos de construcci\u00f3n.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-112d9740 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-bd9af255\"><h2 class=\"uagb-heading-text\">PREGUNTAS FRECUENTES<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a9f51d0\"><div class=\"wp-block-uagb-faq uagb-faq__outer-wrap uagb-block-3e8de48a uagb-faq-icon-row-reverse uagb-faq-layout-accordion uagb-faq-expand-first-true uagb-faq-inactive-other-true uagb-faq__wrap uagb-buttons-layout-wrap uagb-faq-equal-height\" data-faqtoggle=\"true\" role=\"tablist\"><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-937ccc12\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">\u00bfC\u00f3mo elegir el tubo de polietileno adecuado?<\/span><\/div><div class=\"uagb-faq-content\"><p>\u4e00\u3001Clarificar par\u00e1metros b\u00e1sicos<br>1.Selecci\u00f3n de la calidad del material<br>PE80: Adecuado para situaciones de media y baja presi\u00f3n (gas, suministro de agua), rentable25<br>PE100: Mayor resistencia (resistencia m\u00ednima requerida 10MPa), adecuado para gas a alta presi\u00f3n o suministro de agua a larga distancia27<br>2.Adaptaci\u00f3n de la temperatura y la presi\u00f3n<br>Las tuber\u00edas de PE ordinarias tienen un rango de temperatura de -20\u2103~60\u2103, y los escenarios de alta temperatura (como la calefacci\u00f3n por suelo radiante) requieren tuber\u00edas de polietileno reticulado PEX con una resistencia a la temperatura de 110\u210378.<br>Elija el grosor de la pared en funci\u00f3n de la presi\u00f3n de trabajo: tubo de PE de baja densidad (0,2-0,6MPa), tubo de PE de alta densidad (1,0 -1,6MPa)7<br>\u4e8c\u3001Selecci\u00f3n basada en escenarios<br>1.Ingenier\u00eda municipal y civil<br>Tuber\u00edas de agua potable: Seleccionar tuber\u00edas de HDPE que cumplan las normas sanitarias (iones met\u00e1licos &lt;0,1ppb), y dar prioridad a las conexiones termofusibles56<br>Gasoductos: Deben utilizarse tubos PE100 especiales negros, los tubos SDR11 de pared gruesa son adecuados para tramos de alta presi\u00f3n25<br>2.Industria y escenarios especiales<br>Industria minera\/qu\u00edmica: Dar prioridad a los tubos de UHMWPE (m\u00e1s resistentes al desgaste que los met\u00e1licos) o a los tubos corrugados de PFA resistentes a los \u00e1cidos17.<br>Protecci\u00f3n el\u00e9ctrica: Elija tubos de PE ordinarios para el paso de cables de baja tensi\u00f3n, y elija tubos MPP con mayor resistencia a la presi\u00f3n para geolog\u00eda compleja.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-b201d7e1\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">\u00bfC\u00f3mo elegir el tubo de polietileno adecuado?<\/span><\/div><div class=\"uagb-faq-content\"><p>\u4e00\u3001Clarificar par\u00e1metros b\u00e1sicos<br>1.Selecci\u00f3n de la calidad del material<br>PE80: Adecuado para situaciones de media y baja presi\u00f3n (gas, suministro de agua), rentable25<br>PE100: Mayor resistencia (resistencia m\u00ednima requerida 10MPa), adecuado para gas a alta presi\u00f3n o suministro de agua a larga distancia27<br>2.Adaptaci\u00f3n de la temperatura y la presi\u00f3n<br>Las tuber\u00edas de PE ordinarias tienen un rango de temperatura de -20\u2103~60\u2103, y los escenarios de alta temperatura (como la calefacci\u00f3n por suelo radiante) requieren tuber\u00edas de polietileno reticulado PEX con una resistencia a la temperatura de 110\u210378.<br>Elija el grosor de la pared en funci\u00f3n de la presi\u00f3n de trabajo: tubo de PE de baja densidad (0,2-0,6MPa), tubo de PE de alta densidad (1,0 -1,6MPa)7<br>\u4e8c\u3001Selecci\u00f3n basada en escenarios<br>1.Ingenier\u00eda municipal y civil<br>Tuber\u00edas de agua potable: Seleccionar tuber\u00edas de HDPE que cumplan las normas sanitarias (iones met\u00e1licos &lt;0,1ppb), y dar prioridad a las conexiones termofusibles56<br>Gasoductos: Deben utilizarse tubos PE100 especiales negros, los tubos SDR11 de pared gruesa son adecuados para tramos de alta presi\u00f3n25<br>2.Industria y escenarios especiales<br>Industria minera\/qu\u00edmica: Dar prioridad a los tubos de UHMWPE (m\u00e1s resistentes al desgaste que los met\u00e1licos) o a los tubos corrugados de PFA resistentes a los \u00e1cidos17.<br>Protecci\u00f3n el\u00e9ctrica: Elija tubos de PE ordinarios para el paso de cables de baja tensi\u00f3n, y elija tubos MPP con mayor resistencia a la presi\u00f3n para geolog\u00eda compleja.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-1cfc4469\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">\u00bfC\u00f3mo elegir el tubo de polietileno adecuado?<\/span><\/div><div class=\"uagb-faq-content\"><p>\u4e00\u3001Clarificar par\u00e1metros b\u00e1sicos<br>1.Selecci\u00f3n de la calidad del material<br>PE80: Adecuado para situaciones de media y baja presi\u00f3n (gas, suministro de agua), rentable25<br>PE100: Mayor resistencia (resistencia m\u00ednima requerida 10MPa), adecuado para gas a alta presi\u00f3n o suministro de agua a larga distancia27<br>2.Adaptaci\u00f3n de la temperatura y la presi\u00f3n<br>Las tuber\u00edas de PE ordinarias tienen un rango de temperatura de -20\u2103~60\u2103, y los escenarios de alta temperatura (como la calefacci\u00f3n por suelo radiante) requieren tuber\u00edas de polietileno reticulado PEX con una resistencia a la temperatura de 110\u210378.<br>Elija el grosor de la pared en funci\u00f3n de la presi\u00f3n de trabajo: tubo de PE de baja densidad (0,2-0,6MPa), tubo de PE de alta densidad (1,0 -1,6MPa)7<br>\u4e8c\u3001Selecci\u00f3n basada en escenarios<br>1.Ingenier\u00eda municipal y civil<br>Tuber\u00edas de agua potable: Seleccionar tuber\u00edas de HDPE que cumplan las normas sanitarias (iones met\u00e1licos &lt;0,1ppb), y dar prioridad a las conexiones termofusibles56<br>Gasoductos: Deben utilizarse tubos PE100 especiales negros, los tubos SDR11 de pared gruesa son adecuados para tramos de alta presi\u00f3n25<br>2.Industria y escenarios especiales<br>Industria minera\/qu\u00edmica: Dar prioridad a los tubos de UHMWPE (m\u00e1s resistentes al desgaste que los met\u00e1licos) o a los tubos corrugados de PFA resistentes a los \u00e1cidos17.<br>Protecci\u00f3n el\u00e9ctrica: Elija tubos de PE ordinarios para el paso de cables de baja tensi\u00f3n, y elija tubos MPP con mayor resistencia a la presi\u00f3n para geolog\u00eda compleja.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-17f37f9a\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">\u00bfC\u00f3mo elegir el tubo de polietileno adecuado?<\/span><\/div><div class=\"uagb-faq-content\"><p>\u4e00\u3001Clarificar par\u00e1metros b\u00e1sicos<br>1.Selecci\u00f3n de la calidad del material<br>PE80: Adecuado para situaciones de media y baja presi\u00f3n (gas, suministro de agua), rentable25<br>PE100: Mayor resistencia (resistencia m\u00ednima requerida 10MPa), adecuado para gas a alta presi\u00f3n o suministro de agua a larga distancia27<br>2.Adaptaci\u00f3n de la temperatura y la presi\u00f3n<br>Las tuber\u00edas de PE ordinarias tienen un rango de temperatura de -20\u2103~60\u2103, y los escenarios de alta temperatura (como la calefacci\u00f3n por suelo radiante) requieren tuber\u00edas de polietileno reticulado PEX con una resistencia a la temperatura de 110\u210378.<br>Elija el grosor de la pared en funci\u00f3n de la presi\u00f3n de trabajo: tubo de PE de baja densidad (0,2-0,6MPa), tubo de PE de alta densidad (1,0 -1,6MPa)7<br>\u4e8c\u3001Selecci\u00f3n basada en escenarios<br>1.Ingenier\u00eda municipal y civil<br>Tuber\u00edas de agua potable: Seleccionar tuber\u00edas de HDPE que cumplan las normas sanitarias (iones met\u00e1licos &lt;0,1ppb), y dar prioridad a las conexiones termofusibles56<br>Gasoductos: Deben utilizarse tubos PE100 especiales negros, los tubos SDR11 de pared gruesa son adecuados para tramos de alta presi\u00f3n25<br>2.Industria y escenarios especiales<br>Industria minera\/qu\u00edmica: Dar prioridad a los tubos de UHMWPE (m\u00e1s resistentes al desgaste que los met\u00e1licos) o a los tubos corrugados de PFA resistentes a los \u00e1cidos17.<br>Protecci\u00f3n el\u00e9ctrica: Elija tubos de PE ordinarios para el paso de cables de baja tensi\u00f3n, y elija tubos MPP con mayor resistencia a la presi\u00f3n para geolog\u00eda compleja.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-a3582ecd\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">\u00bfC\u00f3mo elegir el tubo de polietileno adecuado?<\/span><\/div><div class=\"uagb-faq-content\"><p>\u4e00\u3001Clarificar par\u00e1metros b\u00e1sicos<br>1.Selecci\u00f3n de la calidad del material<br>PE80: Adecuado para situaciones de media y baja presi\u00f3n (gas, suministro de agua), rentable25<br>PE100: Mayor resistencia (resistencia m\u00ednima requerida 10MPa), adecuado para gas a alta presi\u00f3n o suministro de agua a larga distancia27<br>2.Adaptaci\u00f3n de la temperatura y la presi\u00f3n<br>Las tuber\u00edas de PE ordinarias tienen un rango de temperatura de -20\u2103~60\u2103, y los escenarios de alta temperatura (como la calefacci\u00f3n por suelo radiante) requieren tuber\u00edas de polietileno reticulado PEX con una resistencia a la temperatura de 110\u210378.<br>Elija el grosor de la pared en funci\u00f3n de la presi\u00f3n de trabajo: tubo de PE de baja densidad (0,2-0,6MPa), tubo de PE de alta densidad (1,0 -1,6MPa)7<br>\u4e8c\u3001Selecci\u00f3n basada en escenarios<br>1.Ingenier\u00eda municipal y civil<br>Tuber\u00edas de agua potable: Seleccionar tuber\u00edas de HDPE que cumplan las normas sanitarias (iones met\u00e1licos &lt;0,1ppb), y dar prioridad a las conexiones termofusibles56<br>Gasoductos: Deben utilizarse tubos PE100 especiales negros, los tubos SDR11 de pared gruesa son adecuados para tramos de alta presi\u00f3n25<br>2.Industria y escenarios especiales<br>Industria minera\/qu\u00edmica: Dar prioridad a los tubos de UHMWPE (m\u00e1s resistentes al desgaste que los met\u00e1licos) o a los tubos corrugados de PFA resistentes a los \u00e1cidos17.<br>Protecci\u00f3n el\u00e9ctrica: Elija tubos de PE ordinarios para el paso de cables de baja tensi\u00f3n, y elija tubos MPP con mayor resistencia a la presi\u00f3n para geolog\u00eda compleja.<\/p><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-75d67f4d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0d421be9\"><h2 class=\"uagb-heading-text\">Productos relacionados<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0cb7afd2\">\n<div class=\"wp-block-uagb-slider uagb-block-2eb68df8 uagb-slider-container\"><div class=\"uagb-slides uagb-swiper\"><div class=\"swiper-wrapper\">\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-74d5b89b\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-80f374fe\">\n<div class=\"wp-block-uagb-image uagb-block-cb6f0ef5 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/MPP-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/MPP-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/MPP-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/MPP-Pipe.jpg\" alt=\"\" class=\"uag-image-341\" width=\"600\" height=\"450\" title=\"MPP-Pipe\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-8-color has-text-color has-link-color wp-elements-cf99ef6fb3168754304961f2bcb4e7fc\" style=\"font-size:22px\">Tuber\u00eda MPP<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-0193fd5c\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-b7ac77bc\">\n<div class=\"wp-block-uagb-image uagb-block-b0090c05 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Communications-Pipe.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Communications-Pipe.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Communications-Pipe.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Communications-Pipe.jpg\" alt=\"\" class=\"uag-image-327\" width=\"600\" height=\"450\" title=\"Comunicaciones-Tuber\u00eda\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-8-color has-text-color has-link-color wp-elements-2032c308a213fc6aa5fa71f29986d305\" style=\"font-size:22px\">Tuber\u00eda el\u00e9ctrica<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-79e5c090\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-1de8ecd5\">\n<div class=\"wp-block-uagb-image uagb-block-5bb01e7c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Sewage-Pipe-1.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Sewage-Pipe-1.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Sewage-Pipe-1.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Sewage-Pipe-1.jpg\" alt=\"\" class=\"uag-image-324\" width=\"600\" height=\"450\" title=\"Tuber\u00eda de aguas residuales\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-8-color has-text-color has-link-color wp-elements-a757e01f0caa4110e59c633ef6d1e78a\" style=\"font-size:22px\">Tuber\u00edas de alcantarillado<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-30324553\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-46079279\">\n<div class=\"wp-block-uagb-image uagb-block-75915fab wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Pipe-2.jpg ,https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Pipe-2.jpg 780w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Pipe-2.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Pipe-2.jpg\" alt=\"\" class=\"uag-image-335\" width=\"600\" height=\"450\" title=\"Tuber\u00eda de Hdpe\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-8-color has-text-color has-link-color wp-elements-164c27b05b7ac5cb36eee9da21e1ae4b\" style=\"font-size:22px\">Tuber\u00eda de suministro de agua<\/p>\n<\/div>\n<\/div><\/div>\n<\/div><\/div><div class=\"swiper-pagination\"><\/div><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>8 Inch Hdpe Pipe 8 Inch Hdpe Pipe Manufacturer in China \u200c8 inch HDPE pipe is a pipe made of [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-832","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8 Inch Hdpe Pipe - Hualin Pipe Technology<\/title>\n<meta name=\"description\" content=\"8 inch HDPE pipe is a pipe made of high-density polyethylene (HDPE) as the main raw material and produced by extrusion molding process.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fshualinkeji.com\/es\/tuberia-de-hdpe-de-8-pulgadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 Inch Hdpe Pipe - Hualin Pipe Technology\" \/>\n<meta property=\"og:description\" content=\"8 inch HDPE pipe is a pipe made of high-density polyethylene (HDPE) as the main raw material and produced by extrusion molding process.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fshualinkeji.com\/es\/tuberia-de-hdpe-de-8-pulgadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-16T06:54:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/8-inch-hdpe-pipe\\\/\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/8-inch-hdpe-pipe\\\/\",\"name\":\"8 Inch Hdpe Pipe - Hualin Pipe Technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/8-inch-hdpe-pipe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/8-inch-hdpe-pipe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hdpe-water-supply-and-drainage-pipe.jpg\",\"datePublished\":\"2025-05-26T09:38:39+00:00\",\"dateModified\":\"2025-06-16T06:54:26+00:00\",\"description\":\"8 inch HDPE pipe is a pipe made of high-density polyethylene (HDPE) as the main raw material and produced by extrusion molding process.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/8-inch-hdpe-pipe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fshualinkeji.com\\\/8-inch-hdpe-pipe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/8-inch-hdpe-pipe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hdpe-water-supply-and-drainage-pipe.jpg\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hdpe-water-supply-and-drainage-pipe.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/8-inch-hdpe-pipe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fshualinkeji.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8 Inch Hdpe Pipe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#website\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/\",\"name\":\"Hualin Pipe Technology\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fshualinkeji.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\",\"name\":\"Hualin Pipe Technology\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-logo-1.png\",\"width\":156,\"height\":40,\"caption\":\"Hualin Pipe Technology\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tubo Hdpe de 8 pulgadas - Tecnolog\u00eda de tubos Hualin","description":"El tubo HDPE de 8 pulgadas es un tubo hecho de polietileno de alta densidad (HDPE) como materia prima principal y producido por el proceso de moldeo por extrusi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fshualinkeji.com\/es\/tuberia-de-hdpe-de-8-pulgadas\/","og_locale":"es_ES","og_type":"article","og_title":"8 Inch Hdpe Pipe - Hualin Pipe Technology","og_description":"8 inch HDPE pipe is a pipe made of high-density polyethylene (HDPE) as the main raw material and produced by extrusion molding process.","og_url":"https:\/\/fshualinkeji.com\/es\/tuberia-de-hdpe-de-8-pulgadas\/","og_site_name":"Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology","article_modified_time":"2025-06-16T06:54:26+00:00","og_image":[{"url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fshualinkeji.com\/8-inch-hdpe-pipe\/","url":"https:\/\/fshualinkeji.com\/8-inch-hdpe-pipe\/","name":"Tubo Hdpe de 8 pulgadas - Tecnolog\u00eda de tubos Hualin","isPartOf":{"@id":"https:\/\/fshualinkeji.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fshualinkeji.com\/8-inch-hdpe-pipe\/#primaryimage"},"image":{"@id":"https:\/\/fshualinkeji.com\/8-inch-hdpe-pipe\/#primaryimage"},"thumbnailUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg","datePublished":"2025-05-26T09:38:39+00:00","dateModified":"2025-06-16T06:54:26+00:00","description":"El tubo HDPE de 8 pulgadas es un tubo hecho de polietileno de alta densidad (HDPE) como materia prima principal y producido por el proceso de moldeo por extrusi\u00f3n.","breadcrumb":{"@id":"https:\/\/fshualinkeji.com\/8-inch-hdpe-pipe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fshualinkeji.com\/8-inch-hdpe-pipe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fshualinkeji.com\/8-inch-hdpe-pipe\/#primaryimage","url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-water-supply-and-drainage-pipe.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fshualinkeji.com\/8-inch-hdpe-pipe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fshualinkeji.com\/"},{"@type":"ListItem","position":2,"name":"8 Inch Hdpe Pipe"}]},{"@type":"WebSite","@id":"https:\/\/fshualinkeji.com\/#website","url":"https:\/\/fshualinkeji.com\/","name":"Tecnolog\u00eda de tuber\u00edas Hualin","description":"","publisher":{"@id":"https:\/\/fshualinkeji.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fshualinkeji.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fshualinkeji.com\/#organization","name":"Tecnolog\u00eda de tuber\u00edas Hualin","url":"https:\/\/fshualinkeji.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fshualinkeji.com\/#\/schema\/logo\/image\/","url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/cropped-cropped-logo-1.png","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/cropped-cropped-logo-1.png","width":156,"height":40,"caption":"Hualin Pipe Technology"},"image":{"@id":"https:\/\/fshualinkeji.com\/#\/schema\/logo\/image\/"}}]}},"spectra_custom_meta":{"_edit_lock":["1750056867:1"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":[""],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":["disabled"],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_edit_last":["1"],"_oembed_3214a3c664a2d013ff992b65d7eb55b6":["<iframe title=\"Juntong Technology!#hdpe #pipe #pepipe\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/2E_gVP3it3o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_3214a3c664a2d013ff992b65d7eb55b6":["1749108584"],"_oembed_3c7952766139013ee7ac7272db6840bf":["<iframe title=\"Juntong Technology!#hdpe #pipe #pepipe\" width=\"1290\" height=\"726\" src=\"https:\/\/www.youtube.com\/embed\/2E_gVP3it3o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_3c7952766139013ee7ac7272db6840bf":["1749108589"],"_yoast_wpseo_focuskw":["8 Inch Hdpe Pipe"],"_yoast_wpseo_metadesc":["8 inch HDPE pipe is a pipe made of high-density polyethylene (HDPE) as the main raw material and produced by extrusion molding process."],"_yoast_wpseo_linkdex":["70"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":["6"],"_uag_css_file_name":["uag-css-832.css"],"_uag_js_file_name":["uag-js-832.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:252955:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}body.hide-scroll{overflow:hidden}body .uagb-modal-popup-wrap .wp-block{max-width:none !important;margin:0 !important}.uagb-modal-popup{visibility:hidden;position:fixed}.uagb-modal-popup.active{top:0;bottom:0;justify-content:center;align-items:center;background:rgba(0,0,0,.7);left:0;right:0;display:flex;visibility:visible}.uagb-modal-popup.active .uagb-modal-popup-close{opacity:1;display:flex;align-items:center;position:absolute;text-align:center;cursor:pointer;fill:#fff}.uagb-modal-popup.active .uagb-modal-popup-close svg{-webkit-transition-property:filter,transform;-moz-transition-property:filter,transform;-o-transition-property:filter,transform;transition-property:filter,transform;-webkit-transition-duration:250ms;-moz-transition-duration:250ms;-o-transition-duration:250ms;transition-duration:250ms}.uagb-modal-popup.active .uagb-modal-popup-close:focus svg{transform:scale(1.2)}.uagb-modal-popup .uagb-modal-popup-close{display:none;border:none;background:rgba(0,0,0,0);padding:0}.uagb-modal-popup .uagb-modal-popup-content{padding:35px 35px;overflow-x:hidden;overflow-y:overlay;height:100%}.uagb-modal-popup .uagb-modal-popup-wrap{display:flex;flex-direction:column;justify-content:flex-start;width:700px;height:450px;max-width:100%;box-sizing:border-box;background:#fff;color:#333;position:relative}.uagb-modal-popup .uagb-modal-popup-wrap .uagb-modal-popup-content::-webkit-scrollbar{width:5px}.uagb-modal-popup .uagb-modal-popup-wrap .uagb-modal-popup-content::-webkit-scrollbar-thumb{box-shadow:inset 0 0 6px rgba(0,0,0,.3);border-radius:100px}.wp-block-uagb-modal{width:100%}.entry .entry-content a.uagb-modal-button-link{text-decoration:inherit;align-items:center}.entry .entry-content a.uagb-modal-button-link:hover{color:inherit}.uagb-modal-trigger:not(img){display:flex}.uagb-modal-trigger:not(img) svg{font-size:30px;width:30px;height:30px;line-height:30px;cursor:pointer}img.uagb-modal-trigger{cursor:pointer;height:auto;max-width:100%}div.uagb-spectra-button-wrapper{line-height:1}div.uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{display:inline-flex;align-items:center;cursor:pointer}div.uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{fill:currentColor;font-style:normal;vertical-align:top;width:15px;height:15px;font-size:15px}.block-editor-block-popover.components-popover{z-index:99999999}.uagb-effect-default .uagb-modal-popup-wrap{opacity:0}.uagb-effect-default.active .uagb-modal-popup-wrap{opacity:1;-webkit-transition:all .3s;transition:all .3s}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-faq{width:100%}.wp-block-uagb-faq.uagb-faq-layout-accordion .uagb-faq-child__outer-wrap .uagb-faq-questions-button{cursor:pointer}.wp-block-uagb-faq .uagb-faq-content{margin-bottom:0}.wp-block-uagb-faq .uagb-faq-content p{margin:auto}.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-child__outer-wrap,.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-item{height:100%}body[class*=astra] .uagb-faq-questions{line-height:normal}.uagb-faq-item{overflow:hidden}.wp-block-uagb-faq-child .uagb-faq-questions-button{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-faq-icon-wrap{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-question{width:100%;margin-top:0;margin-bottom:0}.wp-block-uagb-faq-child .uagb-icon svg,.wp-block-uagb-faq-child .uagb-icon-active svg{width:15px;height:15px;font-size:15px}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon{display:none;width:0;padding:0;height:0;margin:0}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:flex;width:auto;height:auto}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.uagb-swiper{position:relative;overflow:hidden}.uagb-slider-container{position:relative;width:100%;min-width:0;transition:box-shadow .2s ease}.uagb-slider-container .swiper-notification{left:0;opacity:0;pointer-events:none;position:absolute;top:0;z-index:-1000}.uagb-slider-container .swiper-button-next.swiper-button-disabled,.uagb-slider-container .swiper-button-prev.swiper-button-disabled{pointer-events:all}.uagb-slider-container .swiper-pagination.swiper-pagination-bullets{max-width:100%}.uagb-slider-container .swiper-button-prev,.uagb-slider-container .swiper-button-next{border-style:none;background:#efefef}.uagb-slider-container.slider-focus-mode .swiper-slide::before{content:\"\";position:absolute;left:0;right:0;top:0;bottom:0;height:100%;width:100%;z-index:99;transition-property:background}.uagb-slider-container.slider-focus-mode .swiper-slide.swiper-slide-active::before{pointer-events:none}\n.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-90c2c68b .uagb-container__video-wrap video{opacity: 0.7;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-90c2c68b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-90c2c68b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-90c2c68b{min-height: 550px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Pipe-banner.jpg);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-90c2c68b::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-8);opacity: 0.3;}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42e0e8e6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42e0e8e6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42e0e8e6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-42e0e8e6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-42e0e8e6.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-42e0e8e6.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3de41139 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3de41139{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3de41139 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3de41139{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1f746054.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1f746054 .uagb-heading-text{font-size: 48px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-84140f4c .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 16px;text-decoration: !important;line-height: em;color: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-84140f4c .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-84140f4c .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-84140f4c .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 16px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-84140f4c.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-2bc49334.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2bc49334.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b196174a.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b196174a.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-48a7ce62.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-48a7ce62.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ccbe86b2.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-ccbe86b2 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-ccbe86b2 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-ccbe86b2.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-ccbe86b2 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-ccbe86b2 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ccbe86b2.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-ccbe86b2.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 32px;padding-right: 32px;padding-top: 14px;padding-bottom: 14px;color: var(--ast-global-color-5);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{fill: var(--ast-global-color-5);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-ccbe86b2 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-ccbe86b2.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-ccbe86b2 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-ccbe86b2.uagb-modal-wrapper{text-align: left;}.uagb-block-ccbe86b2 .wp-block-button__link{width: unset;}.uagb-block-ccbe86b2 .uagb-modal-trigger{justify-content: flex-start;}.uagb-block-ccbe86b2 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-heading-text{color: #060a12;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d2e6c49 .uagb-heading-text{font-weight: 600;font-size: 22px;}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f0aa5aa3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0aa5aa3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0aa5aa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f0aa5aa3{box-shadow: 0px 0px   #00000070 ;padding-top: 75px;padding-bottom: 65px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f4f6f9;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-421ce500.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-421ce500.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-421ce500.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-421ce500.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-421ce500 .uagb-heading-text{font-size: 40px;}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b31ce7bf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b31ce7bf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b31ce7bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b31ce7bf{box-shadow: 0px 0px   #00000070 ;padding-top: 75px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading {text-align: center;padding-bottom: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3 .uagb-heading-text{font-size: 40px;}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ed0f7e26 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed0f7e26{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed0f7e26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ed0f7e26{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd817a82 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd817a82{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd817a82 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd817a82{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5c073af6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5c073af6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5c073af6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5c073af6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a4d3fb33.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5860e71a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5860e71a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5860e71a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5860e71a{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7c1dd511 .uagb-heading-text{font-size: 18px;}.uagb-block-048f0bfe.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-048f0bfe .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-048f0bfe .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-048f0bfe.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-048f0bfe .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-048f0bfe .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-048f0bfe.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-048f0bfe.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-048f0bfe.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-048f0bfe .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-048f0bfe.uagb-modal-wrapper{text-align: center;}.uagb-block-048f0bfe .wp-block-button__link{width: unset;}.uagb-block-048f0bfe .uagb-modal-trigger{justify-content: center;}.uagb-block-048f0bfe .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8342395 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8342395{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8342395 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e8342395{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5f80ca2c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f80ca2c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f80ca2c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5f80ca2c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1fea2c99.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a1a2f46d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a1a2f46d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a1a2f46d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a1a2f46d{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8b077f06 .uagb-heading-text{font-size: 18px;}.uagb-block-dd0fd90b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-dd0fd90b .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-dd0fd90b .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-dd0fd90b.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-dd0fd90b .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-dd0fd90b .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-dd0fd90b.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-dd0fd90b.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-dd0fd90b.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-dd0fd90b .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-dd0fd90b.uagb-modal-wrapper{text-align: center;}.uagb-block-dd0fd90b .wp-block-button__link{width: unset;}.uagb-block-dd0fd90b .uagb-modal-trigger{justify-content: center;}.uagb-block-dd0fd90b .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8b4134ba .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b4134ba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b4134ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8b4134ba{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c415eb6d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c415eb6d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c415eb6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c415eb6d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-eac8718a.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-eac8718a.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-eac8718a.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-44ca3756 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44ca3756{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44ca3756 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-44ca3756{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-49a103f3 .uagb-heading-text{font-size: 18px;}.uagb-block-fce33136.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-fce33136 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-fce33136 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-fce33136.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-fce33136 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-fce33136 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fce33136.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fce33136.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-fce33136.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-fce33136 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-fce33136.uagb-modal-wrapper{text-align: center;}.uagb-block-fce33136 .wp-block-button__link{width: unset;}.uagb-block-fce33136 .uagb-modal-trigger{justify-content: center;}.uagb-block-fce33136 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-b7caf453 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b7caf453 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b7caf453 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b7caf453 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b7caf453 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b7caf453{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b7caf453 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b7caf453{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9b4749ab .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9b4749ab .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9b4749ab .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9b4749ab .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9b4749ab .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9b4749ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9b4749ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9b4749ab{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6a39079c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a39079c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a39079c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a39079c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a39079c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a39079c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a39079c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6a39079c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-b336b693.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b336b693.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-b336b693.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b336b693.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-b336b693.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-b336b693.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-b336b693.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-b336b693.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-b336b693.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-b336b693.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-b336b693.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-b336b693.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-b336b693.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-b336b693.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b336b693.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-0939215b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0939215b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0939215b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0939215b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0939215b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0939215b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0939215b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0939215b{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-23d928ee.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-23d928ee.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-23d928ee.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-23d928ee.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-23d928ee.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-23d928ee .uagb-heading-text{font-size: 18px;}.uagb-block-fadde365.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-fadde365 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-fadde365 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-fadde365.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-fadde365 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-fadde365 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fadde365.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-fadde365 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fadde365.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-fadde365 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-fadde365 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-fadde365 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-fadde365 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-fadde365 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-fadde365.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-fadde365 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-fadde365.uagb-modal-wrapper{text-align: center;}.uagb-block-fadde365 .wp-block-button__link{width: unset;}.uagb-block-fadde365 .uagb-modal-trigger{justify-content: center;}.uagb-block-fadde365 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-2101e8e0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2101e8e0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2101e8e0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2101e8e0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2101e8e0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2101e8e0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2101e8e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2101e8e0{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-75914977 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75914977 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75914977 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75914977 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75914977 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75914977{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75914977 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-75914977{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f70f66dd.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-f70f66dd.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-f70f66dd.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-f70f66dd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-f70f66dd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f70f66dd.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-73a2f6f7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-73a2f6f7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-73a2f6f7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-73a2f6f7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-73a2f6f7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-73a2f6f7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-73a2f6f7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-73a2f6f7{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-695ce6b8.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-695ce6b8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-695ce6b8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-695ce6b8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-695ce6b8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-695ce6b8 .uagb-heading-text{font-size: 18px;}.uagb-block-6bd32ea0.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-6bd32ea0 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-6bd32ea0 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-6bd32ea0.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-6bd32ea0 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-6bd32ea0 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bd32ea0.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-6bd32ea0 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-6bd32ea0.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-6bd32ea0 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-6bd32ea0 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-6bd32ea0 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-6bd32ea0 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-6bd32ea0 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-6bd32ea0.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-6bd32ea0 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-6bd32ea0.uagb-modal-wrapper{text-align: center;}.uagb-block-6bd32ea0 .wp-block-button__link{width: unset;}.uagb-block-6bd32ea0 .uagb-modal-trigger{justify-content: center;}.uagb-block-6bd32ea0 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-8ad04471 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8ad04471 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8ad04471 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8ad04471 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8ad04471 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8ad04471{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8ad04471 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8ad04471{box-shadow: 0px 2px 5px -1px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-603a8411 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-603a8411 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-603a8411 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-603a8411 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-603a8411 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-603a8411{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-603a8411 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-603a8411{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-33497584.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-33497584.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-33497584.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-33497584.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-33497584.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-33497584.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-33497584.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-33497584.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-33497584.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-33497584.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-33497584.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-33497584.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-33497584.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-33497584.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-33497584.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-96ae324f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-96ae324f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-96ae324f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-96ae324f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-96ae324f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-96ae324f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-96ae324f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-96ae324f{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-4ebc0289.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-4ebc0289.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4ebc0289.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4ebc0289.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4ebc0289.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4ebc0289 .uagb-heading-text{font-size: 18px;}.uagb-block-3dbf021b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-3dbf021b .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-3dbf021b .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-3dbf021b.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-3dbf021b .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-3dbf021b .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3dbf021b.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-3dbf021b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{font-size: 16px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-3dbf021b.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 20px;padding-right: 20px;padding-top: 10px;padding-bottom: 10px;color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-3dbf021b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-3dbf021b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);border-color: var(--ast-global-color-8);}.uagb-block-3dbf021b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;fill: var(--ast-global-color-0);}.uagb-block-3dbf021b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-3dbf021b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-3dbf021b.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-3dbf021b .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-3dbf021b.uagb-modal-wrapper{text-align: center;}.uagb-block-3dbf021b .wp-block-button__link{width: unset;}.uagb-block-3dbf021b .uagb-modal-trigger{justify-content: center;}.uagb-block-3dbf021b .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1e782373 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e782373{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e782373 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1e782373{box-shadow: 0px 0px   #00000070 ;padding-top: 75px;padding-bottom: 75px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-729e4697 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-729e4697{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-729e4697 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-729e4697{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773 .uagb-heading-text{font-size: 30px;}.uagb-block-674e1289.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-674e1289 .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-674e1289 .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-674e1289.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-674e1289 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-674e1289 .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-674e1289.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-674e1289.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 32px;padding-right: 32px;padding-top: 14px;padding-bottom: 14px;color: var(--ast-global-color-5);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{fill: var(--ast-global-color-5);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-674e1289 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-674e1289.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-674e1289 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-674e1289.uagb-modal-wrapper{text-align: left;}.uagb-block-674e1289 .wp-block-button__link{width: unset;}.uagb-block-674e1289 .uagb-modal-trigger{justify-content: flex-start;}.uagb-block-674e1289 .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-heading-text{color: #060a12;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-173df8c8 .uagb-heading-text{font-weight: 600;font-size: 22px;}.wp-block-uagb-container.uagb-block-42c090bc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42c090bc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42c090bc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42c090bc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42c090bc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42c090bc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42c090bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-42c090bc{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8aa82a32.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8aa82a32.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8aa82a32.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-8aa82a32.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8aa82a32.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8aa82a32.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27ec6df1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27ec6df1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27ec6df1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-27ec6df1{box-shadow: 0px 0px   #00000070 ;padding-top: 75px;padding-bottom: 75px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f6f6f6;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d4b3ee1c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4b3ee1c{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4b3ee1c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d4b3ee1c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-da368a29.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-da368a29 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-da368a29.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-da368a29.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-da368a29.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2bd96d48 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bd96d48{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bd96d48 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2bd96d48{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-9855b031.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9855b031.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9855b031.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9855b031.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9855b031 .uagb-heading-text{font-size: 30px;}.uagb-block-f858eb1f.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 600px;max-height: 90vh;border-style: none;border-color: none;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-f858eb1f .uagb-modal-popup-close svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;fill: var(--ast-global-color-5);}.uagb-block-f858eb1f .uagb-modal-popup-close:focus svg{filter: drop-shadow(0 0 1px var(--ast-global-color-5));}.uagb-block-f858eb1f.uagb-modal-popup.active{background: rgba(0,0,0,0.75);z-index: 99999;}.uagb-block-f858eb1f .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-f858eb1f .uagb-modal-trigger svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f858eb1f.uagb-modal-wrapper img.uagb-modal-trigger{border-radius: 0px;}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-f858eb1f.uagb-modal-wrapper .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{padding-left: 32px;padding-right: 32px;padding-top: 14px;padding-bottom: 14px;color: var(--ast-global-color-5);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-8);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger svg{fill: var(--ast-global-color-5);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:hover svg{fill: var(--ast-global-color-5);}.uagb-block-f858eb1f .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger:focus svg{fill: var(--ast-global-color-5);}.uagb-block-f858eb1f.uagb-modal-popup.active .uagb-modal-popup-close{top: -20px;right: -20px;}.uagb-block-f858eb1f .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-f858eb1f.uagb-modal-wrapper{text-align: left;}.uagb-block-f858eb1f .wp-block-button__link{width: unset;}.uagb-block-f858eb1f .uagb-modal-trigger{justify-content: flex-start;}.uagb-block-f858eb1f .uagb-modal-popup-close{background-color: var(--ast-global-color-0);border-radius: 50%;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-heading-text{color: #060a12;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d8acc87 .uagb-heading-text{font-weight: 600;font-size: 22px;}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e3e2b8f2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3e2b8f2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3e2b8f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e3e2b8f2{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7eacc968 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7eacc968{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7eacc968 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7eacc968{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading {text-align: center;padding-bottom: 20px;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6076012b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6076012b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6076012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 50px;}.wp-block-uagb-container.uagb-block-6076012b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 50px;}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1c74a02f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c74a02f{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c74a02f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1c74a02f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-5f66276d.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5f66276d .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-5f66276d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: px;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5f66276d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5f66276d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-435fd273 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-435fd273{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-435fd273 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-435fd273{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-07cc6c1b.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-112d9740 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-112d9740{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-112d9740 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-112d9740{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: ;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bd9af255.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a9f51d0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a9f51d0{max-width: 85%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a9f51d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6a9f51d0{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-3e8de48a .uagb-icon svg{width: 12px;height: 12px;font-size: 12px;fill: var(--ast-global-color-8);}.uagb-block-3e8de48a .uagb-icon-active svg{width: 12px;height: 12px;font-size: 12px;}.uagb-block-3e8de48a .uagb-faq-child__outer-wrap{margin-bottom: 10px;}.uagb-block-3e8de48a .uagb-faq-item{background-color: #f6f6f6;border-top-left-radius: 2px;border-top-right-radius: 2px;border-bottom-left-radius: 2px;border-bottom-right-radius: 2px;border-color: #D2D2D2;border-style: none;}.uagb-block-3e8de48a .uagb-faq-item .uagb-question{color: var(--ast-global-color-8);}.uagb-block-3e8de48a .uagb-faq-questions-button{padding-top: 15px;padding-bottom: 15px;padding-right: 15px;padding-left: 15px;}.uagb-block-3e8de48a .uagb-faq-content{padding-top: 0px;padding-bottom: 15px;padding-right: 15px;padding-left: 15px;}.uagb-block-3e8de48a .uagb-faq-content span{margin-top: 0px;margin-bottom: 15px;margin-right: 15px;margin-left: 15px;}.uagb-block-3e8de48a.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-3e8de48a.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-3e8de48a .uagb-faq-item .uagb-faq-questions-button.uagb-faq-questions{flex-direction: row-reverse;}.uagb-block-3e8de48a .uagb-faq-item .uagb-faq-content{font-size: 14px;color: #858a93;}.uagb-block-3e8de48a .wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-content {display: none;}.uagb-block-3e8de48a .uagb-faq-questions-button .uagb-question{font-weight: 600;font-size: 16px;}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75d67f4d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75d67f4d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75d67f4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-75d67f4d{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9 .uagb-heading-text{font-size: 40px;}.wp-block-uagb-container.uagb-block-0cb7afd2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0cb7afd2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0cb7afd2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0cb7afd2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0cb7afd2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0cb7afd2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0cb7afd2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0cb7afd2{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-slider-container.uagb-block-2eb68df8{box-shadow: 0px 0px 0 #00000070;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-slider-container.uagb-block-2eb68df8.uagb-slider-container{border-color: #4B4F58;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-pagination-bullet{background-color: #333333;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-2eb68df8.uagb-slider-container .swiper-button-prev{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;color: #333333;width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-2eb68df8.uagb-slider-container .swiper-button-next{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;color: #333333;width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-wrapper{align-items: center;min-height: 350px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-pagination{bottom: -10px;}.uagb-slider-container.uagb-block-2eb68df8:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-74d5b89b .swiper-content{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.wp-block-uagb-container.uagb-block-80f374fe .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80f374fe .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80f374fe .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80f374fe .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80f374fe .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80f374fe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80f374fe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-80f374fe{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cb6f0ef5.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-cb6f0ef5.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-cb6f0ef5.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-cb6f0ef5.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-cb6f0ef5.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cb6f0ef5.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-0193fd5c .swiper-content{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.wp-block-uagb-container.uagb-block-b7ac77bc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b7ac77bc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b7ac77bc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b7ac77bc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b7ac77bc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b7ac77bc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b7ac77bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b7ac77bc{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-b0090c05.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b0090c05.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-b0090c05.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b0090c05.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-b0090c05.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-b0090c05.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-b0090c05.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-b0090c05.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-b0090c05.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-b0090c05.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-b0090c05.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-b0090c05.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-b0090c05.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-b0090c05.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b0090c05.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-79e5c090 .swiper-content{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.wp-block-uagb-container.uagb-block-1de8ecd5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1de8ecd5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1de8ecd5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1de8ecd5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1de8ecd5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1de8ecd5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1de8ecd5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1de8ecd5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5bb01e7c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5bb01e7c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5bb01e7c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-5bb01e7c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5bb01e7c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5bb01e7c.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-30324553 .swiper-content{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.wp-block-uagb-container.uagb-block-46079279 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-46079279 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-46079279 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-46079279 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-46079279 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46079279{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46079279 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-46079279{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-75915fab.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-75915fab.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-75915fab.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-75915fab.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-75915fab.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-75915fab.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-75915fab.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-75915fab.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-75915fab.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-75915fab.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-75915fab.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-75915fab.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-75915fab.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-75915fab.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-75915fab.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-90c2c68b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-90c2c68b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-90c2c68b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Pipe-banner.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-90c2c68b::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-8);opacity: 0.3;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42e0e8e6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42e0e8e6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-42e0e8e6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3de41139{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3de41139 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3de41139{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-84140f4c .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-84140f4c .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-84140f4c.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.uagb-block-ccbe86b2.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-ccbe86b2 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-ccbe86b2 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0aa5aa3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0aa5aa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f0aa5aa3{padding-top: 75px;padding-bottom: 65px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f4f6f9;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b31ce7bf{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b31ce7bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b31ce7bf{padding-top: 75px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed0f7e26{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed0f7e26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ed0f7e26{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd817a82{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd817a82 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dd817a82{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5c073af6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5c073af6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5c073af6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5860e71a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5860e71a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5860e71a{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-048f0bfe.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-048f0bfe .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-048f0bfe .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8342395{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8342395 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e8342395{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f80ca2c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f80ca2c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5f80ca2c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a1a2f46d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a1a2f46d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a1a2f46d{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-dd0fd90b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-dd0fd90b .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-dd0fd90b .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b4134ba{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b4134ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8b4134ba{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c415eb6d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c415eb6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c415eb6d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44ca3756{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44ca3756 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-44ca3756{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-fce33136.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fce33136 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-fce33136 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b7caf453{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b7caf453 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b7caf453{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9b4749ab{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9b4749ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9b4749ab{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a39079c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a39079c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6a39079c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b336b693.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0939215b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0939215b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0939215b{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-fadde365.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-fadde365 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fadde365 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-fadde365 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2101e8e0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2101e8e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2101e8e0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75914977{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75914977 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-75914977{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-f70f66dd.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-73a2f6f7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-73a2f6f7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-73a2f6f7{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-6bd32ea0.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-6bd32ea0 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-6bd32ea0 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-6bd32ea0 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8ad04471{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8ad04471 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8ad04471{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-603a8411{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-603a8411 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-603a8411{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-33497584.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-96ae324f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-96ae324f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-96ae324f{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-3dbf021b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-3dbf021b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-3dbf021b .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-3dbf021b .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e782373{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e782373 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1e782373{padding-top: 75px;padding-bottom: 75px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-729e4697{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-729e4697 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-729e4697{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-674e1289.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-674e1289 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-674e1289 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42c090bc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42c090bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-42c090bc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-8aa82a32.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27ec6df1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27ec6df1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-27ec6df1{padding-top: 75px;padding-bottom: 75px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f6f6f6;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4b3ee1c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4b3ee1c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d4b3ee1c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bd96d48{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bd96d48 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2bd96d48{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-f858eb1f.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;border-style: none;border-color: none;}.uagb-block-f858eb1f .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-f858eb1f .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3e2b8f2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3e2b8f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e3e2b8f2{padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7eacc968{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7eacc968 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7eacc968{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6076012b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6076012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6076012b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c74a02f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c74a02f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1c74a02f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-435fd273{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-435fd273 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-435fd273{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-112d9740{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-112d9740 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-112d9740{padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a9f51d0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a9f51d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6a9f51d0{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-3e8de48a.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-3e8de48a.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-3e8de48a .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-3e8de48a .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-3e8de48a .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.uagb-block-3e8de48a .uagb-faq-item{border-style: none;border-color: #D2D2D2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75d67f4d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75d67f4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-75d67f4d{padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0cb7afd2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0cb7afd2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0cb7afd2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-slider-container.uagb-block-2eb68df8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-2eb68df8.uagb-slider-container .swiper-button-prev{width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-2eb68df8.uagb-slider-container .swiper-button-next{width: 46px;height: 46px;line-height: 46px;}.uagb-block-74d5b89b .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80f374fe{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80f374fe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-80f374fe{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-cb6f0ef5.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-0193fd5c .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b7ac77bc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b7ac77bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b7ac77bc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b0090c05.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-79e5c090 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1de8ecd5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1de8ecd5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1de8ecd5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-5bb01e7c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-30324553 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46079279{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46079279 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-46079279{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-75915fab.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-90c2c68b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-90c2c68b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-90c2c68b{padding-top: 0px;padding-bottom: 0px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/05\/Hdpe-Pipe-banner.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-90c2c68b::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-8);opacity: 0.3;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42e0e8e6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42e0e8e6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-42e0e8e6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3de41139{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3de41139 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3de41139{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-1f746054 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-84140f4c .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-84140f4c .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-84140f4c.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.uagb-block-ccbe86b2.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-ccbe86b2 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-ccbe86b2 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-ccbe86b2 .wp-block-button__link{width: unset;}.uagb-block-ccbe86b2 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f0aa5aa3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f0aa5aa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f0aa5aa3{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f4f6f9;;}.wp-block-uagb-advanced-heading.uagb-block-421ce500 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b31ce7bf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b31ce7bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b31ce7bf{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-7499abf3 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed0f7e26{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed0f7e26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ed0f7e26{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd817a82{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd817a82 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dd817a82{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5c073af6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5c073af6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5c073af6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-a4d3fb33.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5860e71a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5860e71a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5860e71a{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-048f0bfe.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-048f0bfe .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-048f0bfe .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-048f0bfe .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-048f0bfe .wp-block-button__link{width: unset;}.uagb-block-048f0bfe .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8342395{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8342395 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e8342395{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f80ca2c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f80ca2c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5f80ca2c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-1fea2c99.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a1a2f46d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a1a2f46d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a1a2f46d{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-dd0fd90b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-dd0fd90b .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-dd0fd90b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-dd0fd90b .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-dd0fd90b .wp-block-button__link{width: unset;}.uagb-block-dd0fd90b .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8b4134ba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8b4134ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8b4134ba{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c415eb6d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c415eb6d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c415eb6d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-eac8718a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44ca3756{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44ca3756 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-44ca3756{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-fce33136.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-fce33136 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-fce33136 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fce33136 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-fce33136 .wp-block-button__link{width: unset;}.uagb-block-fce33136 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b7caf453{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b7caf453 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b7caf453{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9b4749ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9b4749ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9b4749ab{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a39079c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a39079c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6a39079c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-b336b693.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0939215b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0939215b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0939215b{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-fadde365.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-fadde365 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-fadde365 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-fadde365 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-fadde365 .wp-block-button__link{width: unset;}.uagb-block-fadde365 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2101e8e0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2101e8e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2101e8e0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75914977{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75914977 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-75914977{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-f70f66dd.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-73a2f6f7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-73a2f6f7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-73a2f6f7{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-6bd32ea0.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-6bd32ea0 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-6bd32ea0 .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-6bd32ea0 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-6bd32ea0 .wp-block-button__link{width: unset;}.uagb-block-6bd32ea0 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8ad04471{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8ad04471 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8ad04471{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-603a8411{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-603a8411 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-603a8411{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-33497584.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-96ae324f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-96ae324f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-96ae324f{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-3dbf021b.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-3dbf021b .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-3dbf021b .uagb-spectra-button-wrapper .uagb-modal-button-link.uagb-modal-trigger{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-3dbf021b .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-3dbf021b .wp-block-button__link{width: unset;}.uagb-block-3dbf021b .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e782373{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e782373 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1e782373{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-729e4697{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-729e4697 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-729e4697{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-0d76f773 .uagb-heading-text{font-size: 25px;}.uagb-block-674e1289.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-674e1289 .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-674e1289 .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-674e1289 .wp-block-button__link{width: unset;}.uagb-block-674e1289 .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42c090bc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42c090bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-42c090bc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-8aa82a32.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: px;}.uagb-block-8aa82a32.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-8aa82a32 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27ec6df1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27ec6df1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-27ec6df1{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f6f6f6;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4b3ee1c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4b3ee1c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d4b3ee1c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-da368a29.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2bd96d48{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2bd96d48 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2bd96d48{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-9855b031 .uagb-heading-text{font-size: 25px;}.uagb-block-f858eb1f.uagb-modal-popup .uagb-modal-popup-wrap{height: auto;width: 320px;border-style: none;border-color: none;}.uagb-block-f858eb1f .uagb-modal-popup-content{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-f858eb1f .uagb-modal-button-link svg {margin-left: 5px;}.uagb-block-f858eb1f .wp-block-button__link{width: unset;}.uagb-block-f858eb1f .uagb-modal-trigger{justify-content: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3e2b8f2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3e2b8f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e3e2b8f2{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7eacc968{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7eacc968 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7eacc968{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-1ebe5639 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6076012b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6076012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6076012b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c74a02f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c74a02f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1c74a02f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-5f66276d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-435fd273{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-435fd273 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-435fd273{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-07cc6c1b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-112d9740{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-112d9740 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-112d9740{padding-top: 70px;padding-bottom: 70px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a9f51d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a9f51d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6a9f51d0{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-3e8de48a.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-3e8de48a .uagb-faq-item{border-style: none;border-color: #D2D2D2;}.uagb-block-3e8de48a.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-3e8de48a .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-3e8de48a .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-3e8de48a .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75d67f4d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75d67f4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-75d67f4d{padding-top: 75px;padding-bottom: 65px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-0d421be9 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0cb7afd2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0cb7afd2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0cb7afd2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-slider-container.uagb-block-2eb68df8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-2eb68df8 .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-2eb68df8.uagb-slider-container .swiper-button-prev{width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-2eb68df8.uagb-slider-container .swiper-button-next{width: 46px;height: 46px;line-height: 46px;}.uagb-block-74d5b89b .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80f374fe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80f374fe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-80f374fe{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-cb6f0ef5.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-0193fd5c .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b7ac77bc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b7ac77bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b7ac77bc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-b0090c05.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-79e5c090 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1de8ecd5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1de8ecd5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1de8ecd5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-5bb01e7c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-30324553 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-46079279{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-46079279 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-46079279{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-75915fab.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd25c91f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6cdf3e7d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-83d25a5b{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dd25c91f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6cdf3e7d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-83d25a5b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dd25c91f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6cdf3e7d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-83d25a5b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-83d25a5b.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-83d25a5b.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-92b3da43{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2 .uagb-heading-text{font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;font-family: \"Poppins\";text-decoration: !important;line-height: em;color: #727579;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child{font-family: \"Poppins\";text-decoration: !important;font-size: 14px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-32ea5357.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-32ea5357.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-e403deab.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-e403deab.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-767efdcf.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-767efdcf.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c9e2a33c.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c9e2a33c.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0ce47b4.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0ce47b4.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c374f4a6.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c374f4a6.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-92b3da43{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-92b3da43{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-15aa5f8a{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d .uagb-heading-text{font-family: \"Poppins\";font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;text-decoration: !important;line-height: em;color: #727579;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 14px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-2a807afe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2a807afe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4b5bca07.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4b5bca07.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4f7e8fc.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4f7e8fc.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-3899fefe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-3899fefe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-29ce129e.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-29ce129e.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-15aa5f8a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-15aa5f8a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ca12eada{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33 .uagb-heading-text{font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 16px;text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 16px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ca12eada{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ca12eada{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{box-shadow: 0px 4px 12px 0px #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-style: solid;border-color: #dadbdd;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #dadbdd;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #dadbdd;}}\";s:2:\"js\";s:3596:\"document.addEventListener(\"DOMContentLoaded\", function(){ \t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-ccbe86b2', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-048f0bfe', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-dd0fd90b', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-fce33136', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-fadde365', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-6bd32ea0', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-3dbf021b', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-674e1289', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\tUAGBModal.init( '.uagb-block-f858eb1f', false, '{\"modalTrigger\":\"button\",\"cssClass\":\"\",\"cssID\":\"\",\"exitIntent\":false,\"showAfterSeconds\":false,\"noOfSecondsToShow\":5,\"enableCookies\":false,\"setCookiesOn\":\"close-action\",\"hideForDays\":2}' );\n\t\t\t});\n\t\twindow.addEventListener(\"DOMContentLoaded\", function(){\n\tvar swiper = new Swiper( \".uagb-block-2eb68df8 .uagb-swiper\",\n\t\t{\"autoplay\":{\"delay\":3000,\"disableOnInteraction\":false,\"pauseOnMouseEnter\":true,\"stopOnLastSlide\":false},\"loop\":true,\"speed\":800,\"effect\":\"slide\",\"direction\":\"horizontal\",\"flipEffect\":{\"slideShadows\":false},\"fadeEffect\":{\"crossFade\":true},\"pagination\":{\"el\":\".uagb-block-2eb68df8 .swiper-pagination\",\"clickable\":true,\"hideOnClick\":false},\"navigation\":{\"nextEl\":\".uagb-block-2eb68df8 .swiper-button-next\",\"prevEl\":\".uagb-block-2eb68df8 .swiper-button-prev\"},\"breakpoints\":{\"976\":{\"slidesPerView\":3,\"spaceBetween\":10},\"767\":{\"slidesPerView\":3,\"spaceBetween\":10},\"320\":{\"slidesPerView\":1,\"spaceBetween\":10}}}\t);\n});\n\n });\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"uagb\/container\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:14:\"uagb\/icon-list\";i:5;s:20:\"uagb\/icon-list-child\";i:6;s:10:\"uagb\/modal\";i:7;s:21:\"fluentfom\/guten-block\";i:8;s:14:\"core\/paragraph\";i:12;s:10:\"uagb\/image\";i:14;s:8:\"uagb\/faq\";i:15;s:14:\"uagb\/faq-child\";i:17;s:11:\"uagb\/slider\";i:18;s:17:\"uagb\/slider-child\";i:21;s:10:\"core\/image\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1778632085;s:6:\"gfonts\";a:1:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:1;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Hualinpipe","author_link":"https:\/\/fshualinkeji.com\/es\/author\/juntongtechoutlook-com\/"},"uagb_comment_info":0,"uagb_excerpt":"8 Inch Hdpe Pipe 8 Inch Hdpe Pipe Manufacturer in China \u200c8 inch HDPE pipe is a pipe made of [&hellip;]","_links":{"self":[{"href":"https:\/\/fshualinkeji.com\/es\/wp-json\/wp\/v2\/pages\/832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fshualinkeji.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fshualinkeji.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/es\/wp-json\/wp\/v2\/comments?post=832"}],"version-history":[{"count":11,"href":"https:\/\/fshualinkeji.com\/es\/wp-json\/wp\/v2\/pages\/832\/revisions"}],"predecessor-version":[{"id":2045,"href":"https:\/\/fshualinkeji.com\/es\/wp-json\/wp\/v2\/pages\/832\/revisions\/2045"}],"wp:attachment":[{"href":"https:\/\/fshualinkeji.com\/es\/wp-json\/wp\/v2\/media?parent=832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}