{"id":3801,"date":"2025-10-15T20:33:17","date_gmt":"2025-10-16T03:33:17","guid":{"rendered":"https:\/\/fshualinkeji.com\/?p=3801"},"modified":"2025-10-16T02:52:11","modified_gmt":"2025-10-16T09:52:11","slug":"%eb%b9%97%eb%ac%bc-%ec%88%98%ec%a7%91-%eb%b0%8f-%ec%82%ac%ec%9a%a9-%eb%b0%a9%eb%b2%95","status":"publish","type":"post","link":"https:\/\/fshualinkeji.com\/ko\/%eb%b9%97%eb%ac%bc-%ec%88%98%ec%a7%91-%eb%b0%8f-%ec%82%ac%ec%9a%a9-%eb%b0%a9%eb%b2%95\/","title":{"rendered":"\ube57\ubb3c\uc744 \ubaa8\uc73c\uace0 \uc0ac\uc6a9\ud558\ub294 \ubc29\ubc95\uc740 \ubb34\uc5c7\uc778\uac00\uc694?"},"content":{"rendered":"<p style=\"font-size:16px\">\ube57\ubb3c\uc744 \ubaa8\uc73c\ub294 \uac83\uc740 \ud658\uacbd\uc744 \ub3c4\uc6b8 \uc218 \uc788\ub294 \uc88b\uc740 \ubc29\ubc95\uc785\ub2c8\ub2e4. \ube57\ubb3c\uc740 \ud658\uacbd\uc5d0 \ud574\ub97c \ub07c\uce58\uc9c0 \uc54a\uace0 \ubaa8\uc744 \uc218 \uc788\ub294 \ucc9c\uc5f0 \uc790\uc6d0\uc785\ub2c8\ub2e4. \ube57\ubb3c\uc744 \ubaa8\uc73c\ub824\uba74 \uba3c\uc800 \uc591\ub3d9\uc774\ub098 \uc791\uc740 \uc6a9\uae30\ub97c \uc900\ube44\ud558\uc138\uc694. \ud558\ub298\uc5d0 \ub178\ucd9c\ub41c \ubaa8\ub4e0 \ud45c\uba74\uc5d0\uc11c \ube57\ubb3c\uc744 \ubaa8\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ub545\uc5d0\uc11c \ube57\ubb3c\uc744 \ubaa8\uc73c\ub294 \uacbd\uc6b0, \ub545\uc774 \uc624\uc5fc\ub418\uc9c0 \uc54a\uc558\ub294\uc9c0 \ud655\uc778\ud558\uc138\uc694. \ub545\uc774 \uc624\uc5fc\ub41c \uacbd\uc6b0\uc5d0\ub294 \uac00\ub2a5\ud55c \ud55c \uae68\ub057\ud55c \uacf3\uc5d0\uc11c \ube57\ubb3c\uc744 \ubaa8\uc544\uc57c \ud569\ub2c8\ub2e4. \ub610\ud55c \uc0ac\uc6a9\ud558\ub294 \uc6a9\uae30\uac00 \ubc15\ud14c\ub9ac\uc544\uac00 \uc11c\uc2dd\ud558\uc9c0 \uc54a\ub294 \uc7ac\uc9c8\ub85c \ub9cc\ub4e4\uc5b4\uc84c\ub294\uc9c0 \ud655\uc778\ud574\uc57c \ud569\ub2c8\ub2e4. \ub610\ud55c \uc6a9\uae30\uac00 \ub2e8\ub2e8\ud788 \ubc00\ud3d0\ub418\uc5b4 \ub0b4\ubd80\uc758 \uc218\ubd84\uc774 \uc99d\ubc1c\ud558\uc9c0 \uc54a\ub3c4\ub85d \ud574\uc57c \ud569\ub2c8\ub2e4. \ub610\ud55c \uc6a9\uae30\uac00 \ud544\uc694\ud55c \uc591\uc758 \ubb3c\uc744 \ub2f4\uc744 \uc218 \uc788\uc744 \ub9cc\ud07c \ucda9\ubd84\ud788 \ud070\uc9c0 \ud655\uc778\ud558\ub294 \uac83\ub3c4 \uc911\uc694\ud569\ub2c8\ub2e4. \ub610\ud55c \uc6a9\uae30\uac00 \uae68\ub057\ud558\uace0 \uac74\uc870\ud55c \uacf3\uc5d0 \ubcf4\uad00\ud574\uc57c \ud569\ub2c8\ub2e4. \ub610\ud55c \uc6a9\uae30\uc5d0 \ub77c\ubca8\uacfc \ub0a0\uc9dc\uac00 \ud45c\uc2dc\ub418\uc5b4 \uc788\ub294\uc9c0 \ud655\uc778\ud558\ub294 \uac83\uc774 \uc88b\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6fc13759 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater.jpg\" alt=\"\" class=\"wp-image-3814\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater.jpg 750w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-300x200.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4e29c225\"><h2 class=\"uagb-heading-text\">\ube57\ubb3c\uc744 \ubaa8\uc73c\ub294 \ubc29\ubc95?<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">\ud0dc\uc591\uc5f4\ub85c \uc791\ub3d9\ud558\ub294 \ube57\ubb3c\ud1b5 \ud38c\ud504\ub97c \uc0ac\uc6a9\ud558\uc5ec \ube57\ubb3c\uc744 \uc218\ud655\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ube57\ubb3c\uc740 \uc804 \uc138\uacc4\uc5d0 \ud48d\ubd80\ud55c \ubb34\ub8cc \uc790\uc6d0\uc785\ub2c8\ub2e4. \ube57\ubb3c\uc744 \uc218\ud655\ud558\ub294 \ubc29\ubc95\uc740 \uc5ec\ub7ec \uac00\uc9c0\uac00 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<p style=\"font-size:16px\">\ub610\ub294 \ubc30\uc218\ub85c\uc640 \ubc30\uc218\uad6c\ub97c \ud1b5\ud574 \ube57\ubb3c\uc744 \ubaa8\uc73c\uac70\ub098 \uc2a4\ud14c\uc778\ub9ac\uc2a4 \uc2a4\ud2f8 \ube57\ubb3c\ud1b5\uc744 \uc0ac\uc6a9\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ube57\ubb3c\uc740 \ub9ce\uc740 \ub3d9\uc2dd\ubb3c\uc5d0\uac8c \ud544\uc218\uc801\uc778 \uc790\uc6d0\uc774\ub77c\ub294 \uc0ac\uc2e4\uc744 \uae30\uc5b5\ud558\ub294 \uac83\uc774 \uc911\uc694\ud569\ub2c8\ub2e4. \ub610\ud55c \ube57\ubb3c\uc740 \uc778\uac04\uc5d0\uac8c\ub3c4 \ud544\uc218\uc801\uc778 \uc790\uc6d0\uc774\ub77c\ub294 \uc0ac\uc2e4\uc744 \uae30\uc5b5\ud558\ub294 \uac83\ub3c4 \uc911\uc694\ud569\ub2c8\ub2e4. \uac74\uac15\ud55c \uc0dd\ud0dc\uacc4\ub97c \uc720\uc9c0\ud558\uae30 \uc704\ud574 \ube57\ubb3c\uc744 \ud65c\uc6a9\ud558\ub294 \uac83\uc740 \ud544\uc218\uc801\uc785\ub2c8\ub2e4. \ubb3c \uc800\uc7a5 \uc2dc\uc2a4\ud15c\uc744 \ub9cc\ub4e4\ub824\uba74 \ub9c8\ub2f9\uc744 \ub354 \ud30c\uc11c \uc9c0\ub2a5\ud615 \ube57\ubb3c \uc800\uc7a5 \ud0f1\ud06c\ub97c \ubbf8\ub9ac \ub9e4\uc124\ud574\uc57c \ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5073aa8b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"450\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-1.jpg\" alt=\"\" class=\"wp-image-3816\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-1.jpg 750w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-1-300x180.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-caa0de6c\"><h2 class=\"uagb-heading-text\">\ube57\ubb3c\uc744 \uc5b4\ub5bb\uac8c \uc0ac\uc6a9\ud558\ub098\uc694?<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">\ube57\ubb3c\uc744 \ubaa8\uc544 \uc0ac\uc6a9\ud558\ub294 \ubc29\ubc95\uc5d0\ub294 \uc5ec\ub7ec \uac00\uc9c0\uac00 \uc788\uc2b5\ub2c8\ub2e4. \uc591\ub3d9\uc774, \ube57\ubb3c\ud1b5 \ub610\ub294 \ubb3c\ud1b5\uc5d0 \ube57\ubb3c\uc744 \ubaa8\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uc9d1\uc5d0\uc11c \ube57\ubb3c\uc744 \uc0ac\uc6a9\ud558\ub294 \ubc29\ubc95\ub3c4 \ub2e4\uc591\ud569\ub2c8\ub2e4. \uc124\uac70\uc9c0, \uc2dd\ubb3c\uc5d0 \ubb3c\uc8fc\uae30, \uc9d1\uc548 \uccad\uc18c\uc5d0 \ube57\ubb3c\uc744 \uc0ac\uc6a9\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ube57\ubb3c\uc744 \uc2dd\uc218\ub85c \uc0ac\uc6a9\ud558\uae30 \uc804\uc5d0 \uc774\ub7ec\ud55c \uc6a9\ub3c4\ub85c \uc0ac\uc6a9\ud558\ub294 \uac83\uc774 \uac00\uc7a5 \uc88b\uc2b5\ub2c8\ub2e4. \ube57\ubb3c\uc740 \uc9c0\uc18d \uac00\ub2a5\ud558\uac8c \uc0ac\uc6a9\ud574\uc57c \ud558\ub294 \ucc9c\uc5f0 \uc790\uc6d0\uc785\ub2c8\ub2e4. \ub2e4\uc591\ud55c \uc57c\uc678 \uacf5\uac04\uc5d0\uc11c \ube57\ubb3c\uc744 \ubaa8\uc73c\uace0 \uc0ac\uc6a9\ud558\ub294 \ubc29\ubc95\uc744 \ubcf4\uc5ec\uc8fc\ub294 \uac04\ub2e8\ud55c \ud504\ub85c\ud544\uc744 \ud655\uc778\ud558\uc138\uc694.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-54b49cc0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"488\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg\" alt=\"\" class=\"wp-image-3818\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg 750w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2-300x195.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-e8a0e407\"><h2 class=\"uagb-heading-text\">\uacb0\ub860<\/h2><\/div>\n\n\n\n<p style=\"font-size:16px\">\ube57\ubb3c\uc740 \uc790\uc5f0\uc774 \uc6b0\ub9ac\uc5d0\uac8c \uc900 \uc18c\uc911\ud55c \uc790\uc6d0\uc785\ub2c8\ub2e4. \uce5c\ud658\uacbd \uac1c\ub150\uc744 \uc2e4\ucc9c\ud558\uace0 \uc0dd\uba85\uc758 \uadfc\uc6d0\uc744 \ubcf4\ud638\ud560 \ub54c \ube57\ubb3c \uc218\uc9d1 \ubc0f \uc7ac\uc0ac\uc6a9\uc740 \uc218\uc790\uc6d0\uc744 \uac1c\ubc1c\ud558\uace0 \ubb3c\uc744 \ud6a8\uacfc\uc801\uc73c\ub85c \uc808\uc57d, \ubcf4\uc874 \ubc0f \uc870\uc808\ud558\uba70 \uc0dd\ud0dc, \uacbd\uc81c \ubc0f \uc0ac\ud68c\uc758 \uc9c0\uc18d \uac00\ub2a5\ud55c \ubc1c\uc804\uc744 \ucd09\uc9c4\ud558\ub294 \uacbd\uc81c\uc801\uc774\uace0 \uc2e4\uc6a9\uc801\uc778 \ubc29\ubc95\uc774 \ub418\uc5c8\uc2b5\ub2c8\ub2e4.<\/p>","protected":false},"excerpt":{"rendered":"<p>\ube57\ubb3c\uc744 \ubaa8\uc73c\ub294 \uac83\uc740 \ud658\uacbd\uc744 \ubcf4\ud638\ud560 \uc218 \uc788\ub294 \uc88b\uc740 \ubc29\ubc95\uc785\ub2c8\ub2e4. \ube57\ubb3c\uc740 [...] \uc5c6\uc774\ub3c4 \ubaa8\uc744 \uc218 \uc788\ub294 \ucc9c\uc5f0 \uc790\uc6d0\uc785\ub2c8\ub2e4.<\/p>","protected":false},"author":1,"featured_media":3818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"unboxed","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to collect and use rainwater?<\/title>\n<meta name=\"description\" content=\"Collecting rainwater is a great way to help the environment. Rainwater is a natural resource that can be collected without harming the environment.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fshualinkeji.com\/ko\/\ube57\ubb3c-\uc218\uc9d1-\ubc0f-\uc0ac\uc6a9-\ubc29\ubc95\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to collect and use rainwater?\" \/>\n<meta property=\"og:description\" content=\"Collecting rainwater is a great way to help the environment. Rainwater is a natural resource that can be collected without harming the environment.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fshualinkeji.com\/ko\/\ube57\ubb3c-\uc218\uc9d1-\ubc0f-\uc0ac\uc6a9-\ubc29\ubc95\/\" \/>\n<meta property=\"og:site_name\" content=\"Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-16T03:33:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T09:52:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hualinpipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\uae00\uc4f4\uc774\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hualinpipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"\uc608\uc0c1 \ub418\ub294 \ud310\ub3c5 \uc2dc\uac04\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\ubd84\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/\"},\"author\":{\"name\":\"Hualinpipe\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/person\\\/4bfd1194fc41e1e42cf86b4da191fde5\"},\"headline\":\"How to collect and use rainwater?\",\"datePublished\":\"2025-10-16T03:33:17+00:00\",\"dateModified\":\"2025-10-16T09:52:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/\"},\"wordCount\":412,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Collecting-rainwater-2.jpg\",\"articleSection\":[\"BLOG\"],\"inLanguage\":\"ko-KR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/\",\"name\":\"How to collect and use rainwater?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Collecting-rainwater-2.jpg\",\"datePublished\":\"2025-10-16T03:33:17+00:00\",\"dateModified\":\"2025-10-16T09:52:11+00:00\",\"description\":\"Collecting rainwater is a great way to help the environment. Rainwater is a natural resource that can be collected without harming the environment.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/#breadcrumb\"},\"inLanguage\":\"ko-KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Collecting-rainwater-2.jpg\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Collecting-rainwater-2.jpg\",\"width\":750,\"height\":488},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/how-to-collect-and-use-rainwater\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fshualinkeji.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to collect and use rainwater?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#website\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/\",\"name\":\"Hualin Pipe Technology\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fshualinkeji.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko-KR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\",\"name\":\"Hualin Pipe Technology\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-logo-1.png\",\"width\":156,\"height\":40,\"caption\":\"Hualin Pipe Technology\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/person\\\/4bfd1194fc41e1e42cf86b4da191fde5\",\"name\":\"Hualinpipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655\",\"caption\":\"Hualinpipe\"},\"sameAs\":[\"https:\\\/\\\/fshualinkeji.com\"],\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/ko\\\/author\\\/juntongtechoutlook-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ube57\ubb3c\uc744 \ubaa8\uc73c\uace0 \uc0ac\uc6a9\ud558\ub294 \ubc29\ubc95\uc740 \ubb34\uc5c7\uc778\uac00\uc694?","description":"\ube57\ubb3c\uc744 \ubaa8\uc73c\ub294 \uac83\uc740 \ud658\uacbd\uc744 \ub3c4\uc6b8 \uc218 \uc788\ub294 \uc88b\uc740 \ubc29\ubc95\uc785\ub2c8\ub2e4. \ube57\ubb3c\uc740 \ud658\uacbd\uc5d0 \ud574\ub97c \ub07c\uce58\uc9c0 \uc54a\uace0 \uc218\uc9d1\ud560 \uc218 \uc788\ub294 \ucc9c\uc5f0 \uc790\uc6d0\uc785\ub2c8\ub2e4.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fshualinkeji.com\/ko\/\ube57\ubb3c-\uc218\uc9d1-\ubc0f-\uc0ac\uc6a9-\ubc29\ubc95\/","og_locale":"ko_KR","og_type":"article","og_title":"How to collect and use rainwater?","og_description":"Collecting rainwater is a great way to help the environment. Rainwater is a natural resource that can be collected without harming the environment.","og_url":"https:\/\/fshualinkeji.com\/ko\/\ube57\ubb3c-\uc218\uc9d1-\ubc0f-\uc0ac\uc6a9-\ubc29\ubc95\/","og_site_name":"Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology","article_published_time":"2025-10-16T03:33:17+00:00","article_modified_time":"2025-10-16T09:52:11+00:00","og_image":[{"width":750,"height":488,"url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg","type":"image\/jpeg"}],"author":"Hualinpipe","twitter_card":"summary_large_image","twitter_misc":{"\uae00\uc4f4\uc774":"Hualinpipe","\uc608\uc0c1 \ub418\ub294 \ud310\ub3c5 \uc2dc\uac04":"3\ubd84"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/#article","isPartOf":{"@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/"},"author":{"name":"Hualinpipe","@id":"https:\/\/fshualinkeji.com\/#\/schema\/person\/4bfd1194fc41e1e42cf86b4da191fde5"},"headline":"How to collect and use rainwater?","datePublished":"2025-10-16T03:33:17+00:00","dateModified":"2025-10-16T09:52:11+00:00","mainEntityOfPage":{"@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/"},"wordCount":412,"commentCount":0,"publisher":{"@id":"https:\/\/fshualinkeji.com\/#organization"},"image":{"@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/#primaryimage"},"thumbnailUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg","articleSection":["BLOG"],"inLanguage":"ko-KR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/","url":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/","name":"\ube57\ubb3c\uc744 \ubaa8\uc73c\uace0 \uc0ac\uc6a9\ud558\ub294 \ubc29\ubc95\uc740 \ubb34\uc5c7\uc778\uac00\uc694?","isPartOf":{"@id":"https:\/\/fshualinkeji.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/#primaryimage"},"image":{"@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/#primaryimage"},"thumbnailUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg","datePublished":"2025-10-16T03:33:17+00:00","dateModified":"2025-10-16T09:52:11+00:00","description":"\ube57\ubb3c\uc744 \ubaa8\uc73c\ub294 \uac83\uc740 \ud658\uacbd\uc744 \ub3c4\uc6b8 \uc218 \uc788\ub294 \uc88b\uc740 \ubc29\ubc95\uc785\ub2c8\ub2e4. \ube57\ubb3c\uc740 \ud658\uacbd\uc5d0 \ud574\ub97c \ub07c\uce58\uc9c0 \uc54a\uace0 \uc218\uc9d1\ud560 \uc218 \uc788\ub294 \ucc9c\uc5f0 \uc790\uc6d0\uc785\ub2c8\ub2e4.","breadcrumb":{"@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/#breadcrumb"},"inLanguage":"ko-KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/"]}]},{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/#primaryimage","url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg","width":750,"height":488},{"@type":"BreadcrumbList","@id":"https:\/\/fshualinkeji.com\/how-to-collect-and-use-rainwater\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fshualinkeji.com\/"},{"@type":"ListItem","position":2,"name":"How to collect and use rainwater?"}]},{"@type":"WebSite","@id":"https:\/\/fshualinkeji.com\/#website","url":"https:\/\/fshualinkeji.com\/","name":"\ud654\ub9b0 \ud30c\uc774\ud504 \uae30\uc220","description":"","publisher":{"@id":"https:\/\/fshualinkeji.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fshualinkeji.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko-KR"},{"@type":"Organization","@id":"https:\/\/fshualinkeji.com\/#organization","name":"\ud654\ub9b0 \ud30c\uc774\ud504 \uae30\uc220","url":"https:\/\/fshualinkeji.com\/","logo":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/fshualinkeji.com\/#\/schema\/logo\/image\/","url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/cropped-cropped-logo-1.png","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/cropped-cropped-logo-1.png","width":156,"height":40,"caption":"Hualin Pipe Technology"},"image":{"@id":"https:\/\/fshualinkeji.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fshualinkeji.com\/#\/schema\/person\/4bfd1194fc41e1e42cf86b4da191fde5","name":"\ud654\ub9b0\ud30c\uc774\ud504","image":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/fshualinkeji.com\/wp-content\/litespeed\/avatar\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655","url":"https:\/\/fshualinkeji.com\/wp-content\/litespeed\/avatar\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/litespeed\/avatar\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655","caption":"Hualinpipe"},"sameAs":["https:\/\/fshualinkeji.com"],"url":"https:\/\/fshualinkeji.com\/ko\/author\/juntongtechoutlook-com\/"}]}},"spectra_custom_meta":{"_edit_lock":["1760608347:1"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["unboxed"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_edit_last":["1"],"_yoast_wpseo_primary_category":[""],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":["3"],"_yoast_wpseo_focuskw":["How to collect and use rainwater"],"_yoast_wpseo_metadesc":["Collecting rainwater is a great way to help the environment. Rainwater is a natural resource that can be collected without harming the environment."],"_yoast_wpseo_linkdex":["75"],"_yoast_wpseo_title":["%%title%% %%page%%"],"_thumbnail_id":["3818"],"_uag_css_file_name":["uag-css-3801.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:51291:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-container.uagb-block-6fc13759 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6fc13759 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6fc13759 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6fc13759 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6fc13759 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fc13759{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fc13759 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6fc13759{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-4e29c225.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4e29c225.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4e29c225.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4e29c225.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-5073aa8b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5073aa8b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5073aa8b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5073aa8b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5073aa8b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5073aa8b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5073aa8b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5073aa8b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-caa0de6c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-caa0de6c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-caa0de6c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-caa0de6c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-54b49cc0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-54b49cc0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-54b49cc0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-54b49cc0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-54b49cc0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-54b49cc0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-54b49cc0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-54b49cc0{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-e8a0e407.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e8a0e407.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e8a0e407.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e8a0e407.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fc13759{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fc13759 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6fc13759{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5073aa8b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5073aa8b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5073aa8b{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-54b49cc0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-54b49cc0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-54b49cc0{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fc13759{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fc13759 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6fc13759{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5073aa8b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5073aa8b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5073aa8b{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-54b49cc0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-54b49cc0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-54b49cc0{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd25c91f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6cdf3e7d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-83d25a5b{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dd25c91f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6cdf3e7d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-83d25a5b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dd25c91f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6cdf3e7d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-83d25a5b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-83d25a5b.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-83d25a5b.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-92b3da43{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2 .uagb-heading-text{font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;font-family: \"Poppins\";text-decoration: !important;line-height: em;color: #727579;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child{font-family: \"Poppins\";text-decoration: !important;font-size: 14px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-32ea5357.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-32ea5357.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-e403deab.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-e403deab.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-767efdcf.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-767efdcf.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c9e2a33c.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c9e2a33c.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0ce47b4.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0ce47b4.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c374f4a6.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c374f4a6.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-92b3da43{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-92b3da43{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-15aa5f8a{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d .uagb-heading-text{font-family: \"Poppins\";font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;text-decoration: !important;line-height: em;color: #727579;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 14px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-2a807afe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2a807afe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4b5bca07.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4b5bca07.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4f7e8fc.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4f7e8fc.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-3899fefe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-3899fefe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-29ce129e.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-29ce129e.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-15aa5f8a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-15aa5f8a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ca12eada{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33 .uagb-heading-text{font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 16px;text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 16px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ca12eada{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ca12eada{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{box-shadow: 0px 4px 12px 0px #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-style: solid;border-color: #dadbdd;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #dadbdd;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #dadbdd;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:7:{i:0;s:14:\"core\/paragraph\";i:1;s:14:\"uagb\/container\";i:2;s:10:\"core\/image\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:14:\"uagb\/icon-list\";i:5;s:20:\"uagb\/icon-list-child\";i:6;s:21:\"fluentfom\/guten-block\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1778634776;s:6:\"gfonts\";a:1:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg",750,488,false],"thumbnail":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2-150x150.jpg",150,150,true],"medium":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2-300x195.jpg",300,195,true],"medium_large":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg",750,488,false],"large":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg",750,488,false],"1536x1536":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg",750,488,false],"2048x2048":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2.jpg",750,488,false],"trp-custom-language-flag":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Collecting-rainwater-2-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Hualinpipe","author_link":"https:\/\/fshualinkeji.com\/ko\/author\/juntongtechoutlook-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Collecting rainwater is a great way to help the environment. Rainwater is a natural resource that can be collected without [&hellip;]","_links":{"self":[{"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/posts\/3801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/comments?post=3801"}],"version-history":[{"count":12,"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/posts\/3801\/revisions"}],"predecessor-version":[{"id":3822,"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/posts\/3801\/revisions\/3822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/media\/3818"}],"wp:attachment":[{"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/media?parent=3801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/categories?post=3801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fshualinkeji.com\/ko\/wp-json\/wp\/v2\/tags?post=3801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}