{"id":4721,"date":"2025-12-15T00:08:03","date_gmt":"2025-12-15T07:08:03","guid":{"rendered":"https:\/\/fshualinkeji.com\/?p=4721"},"modified":"2025-12-15T01:45:25","modified_gmt":"2025-12-15T08:45:25","slug":"cindeki-en-iyi-10-plastik-yagmur-suyu-toplama-tanki-ureticisi","status":"publish","type":"post","link":"https:\/\/fshualinkeji.com\/tr\/cindeki-en-iyi-10-plastik-yagmur-suyu-toplama-tanki-ureticisi\/","title":{"rendered":"\u00c7in'deki en iyi 10 plastik ya\u011fmur suyu toplama tank\u0131 \u00fcreticisi"},"content":{"rendered":"<p style=\"font-size:16px\">\u00c7in, plastik ya\u011fmur suyu toplama tanklar\u0131 \u00fcreten \u00e7ok say\u0131da \u00fcreticiye sahiptir ve bunlar\u0131n \u00e7o\u011fu \u00e7e\u015fitli end\u00fcstrilerin teknik ve kalite gereksinimlerine a\u015fina ve deneyimlidir. Al\u0131c\u0131lar i\u00e7in as\u0131l zorluk, s\u0131n\u0131rl\u0131 se\u00e7enekler de\u011fil, \u00e7ok say\u0131da \u015firket aras\u0131ndan do\u011fru \u015firketi se\u00e7mektir. Her \u015firketi ayr\u0131 ayr\u0131 do\u011frulamak zaman al\u0131c\u0131, zahmetli ve \u00f6nemli bilgilerin g\u00f6zden ka\u00e7mas\u0131na neden olabilir. Bu nedenle, bu s\u0131ralama \u015firket b\u00fcy\u00fckl\u00fc\u011f\u00fc, nitelikler, \u00fcretim kapasitesi, sat\u0131\u015f sonras\u0131 hizmetler vb. gibi temel bilgileri \u00f6zetlemektedir. T\u00fcm bilgiler a\u00e7\u0131k ve \u00f6zl\u00fcd\u00fcr, tedarik\u00e7ilerin kar\u015f\u0131la\u015ft\u0131r\u0131lmas\u0131n\u0131 kolayla\u015ft\u0131r\u0131r, gereksiz arka plan kontrollerini \u00f6nler ve uygun markalar\u0131 h\u0131zl\u0131 bir \u015fekilde filtreler.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f5c6fd14\"><h2 class=\"uagb-heading-text\">\u00c7in'deki en iyi 10 plastik ya\u011fmur suyu toplama tank\u0131 \u00fcreticisi<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-86d82dab\"><h3 class=\"uagb-heading-text\">1. Juntong\/Hualin Boru Teknolojisi<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: Linjiang Yolu, Sanshui B\u00f6lgesi, Foshan \u015eehri, Guangdong Eyaleti, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2006<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Juntong\/Hualin, ya\u011fmur suyu toplama tanklar\u0131 konusunda uzmanla\u015fm\u0131\u015ft\u0131r. Sipari\u015flerimizin \u00e7o\u011fu ya\u011fmur suyunu depolamak i\u00e7indir.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-00467628 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg\" alt=\"\" class=\"wp-image-3835\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg 750w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T-300x225.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T-16x12.jpg 16w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<p style=\"font-size:16px\">\u015eirket b\u00fcy\u00fckl\u00fc\u011f\u00fc: 20.000 metrekareden fazla<\/p>\n\n\n\n<p style=\"font-size:16px\">\u0130yi \u0130tibar: ISO 9001:2015 kalite y\u00f6netim sistemi sertifikas\u0131na (genellikle end\u00fcstriyel ekipmanlar i\u00e7in gereklidir) ve SGS, CE ve RoHS gibi di\u011fer sertifikalara sahiptir.<\/p>\n\n\n\n<p style=\"font-size:16px\">Konumland\u0131rma: Juntong\/Hualin, \u00f6ncelikle belediye m\u00fchendisli\u011fi ve di\u011fer alanlarda kullan\u0131lan \u00e7e\u015fitli plastik borular ve ya\u011fmur suyu toplama tanklar\u0131 \u00fcretmektedir. \u0130ster tekli \u00f6zel ya\u011fmur suyu toplama tanklar\u0131 ister toplu sipari\u015fler olsun, m\u00fc\u015fteri ihtiya\u00e7lar\u0131n\u0131 kar\u015f\u0131layabiliriz.<\/p>\n\n\n\n<p style=\"font-size:16px\">\u00d6zelle\u015ftirme Hizmeti: Juntong\/Hualin, PP ve HDPE dahil olmak \u00fczere \u00e7e\u015fitli malzemelerden plastik ya\u011fmur suyu toplama tanklar\u0131 sunmaktad\u0131r. Her malzemenin a\u011f\u0131rl\u0131\u011f\u0131, mukavemeti ve korozyon direnci ger\u00e7ek kullan\u0131mda de\u011fi\u015fiklik g\u00f6sterir. Bu nedenle, ya\u011fmur suyu toplama tanklar\u0131n\u0131 se\u00e7erken, uzun vadeli istikrarl\u0131 \u00e7al\u0131\u015fmay\u0131 sa\u011flamak i\u00e7in m\u00fc\u015fterinin ya\u011fmur suyu depolama ve \u00e7al\u0131\u015fma ortam\u0131n\u0131 dikkate al\u0131r\u0131z.<\/p>\n\n\n\n<p style=\"font-size:16px\">\u015eirket web sitesi: <a href=\"https:\/\/fshualinkeji.com\/tr\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>https:\/\/fshualinkeji.com\/<\/strong><\/a><\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8fe91179\"><h3 class=\"uagb-heading-text\">2. Zhengzhou Yayuan S\u00fcnger \u015eehri Ya\u011fmur Suyu Kullan\u0131m Teknolojisi Ltd. \u015eti.<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: Gaomeng K\u00f6y\u00fc, Guodian Kasabas\u0131, Xinzheng \u015eehri, Zhenzhou \u015eehri, Henan Eyaleti, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2013<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Zhengzhou Yayuan, inceleme kuyular\u0131, plastik inceleme kuyular\u0131, ya\u011fmur suyu toplama, ya\u011fmur suyu toplama sistemleri, ya\u011fmur suyu toplama ve kullan\u0131m\u0131, ya\u011fmur suyu toplama mod\u00fclleri konusunda uzmanla\u015fm\u0131\u015ft\u0131r. <\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4a09f600 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"356\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yayuan.jpg\" alt=\"\" class=\"wp-image-4742\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yayuan.jpg 600w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yayuan-300x178.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yayuan-18x12.jpg 18w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a2947c1d\"><h3 class=\"uagb-heading-text\">3. Saint-Teng Teknolojisi<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: Zhuhai \u015eehri, Henan Eyaleti, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2008<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: S\u00fcnger \u015fehir ya\u011fmur suyu toplama ve kullan\u0131m sistemi, \u00fc\u00e7\u00fcnc\u00fc nesil sifon ya\u011fmur suyu drenaj sistemi, ak\u0131ll\u0131 su y\u00f6netim sistemi ve bina zemin drenaj sistemi.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-535eec71 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"531\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/Saint-Teng-Technology.jpg\" alt=\"\" class=\"wp-image-4748\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/Saint-Teng-Technology.jpg 727w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/Saint-Teng-Technology-300x219.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/Saint-Teng-Technology-16x12.jpg 16w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0019f075\"><h3 class=\"uagb-heading-text\">4. Jiangsu Jinchi \u00c7evre M\u00fchendisli\u011fi Ltd. \u015eti.<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: Xiuyu Yolu, Binjiang Geli\u015ftirme B\u00f6lgesi, Jiangning B\u00f6lgesi, Nanjing \u015eehri, Jiangsu Eyaleti, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2013<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Bina \u00e7at\u0131 drenaj\u0131, bina banyo drenaj\u0131, ya\u011fmur suyu toplama ve ar\u0131tma i\u00e7in \u00e7\u00f6z\u00fcm sa\u011flay\u0131c\u0131<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c63291b1\"><h3 class=\"uagb-heading-text\">5. DOKTOR YA\u011eMUR<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: Yanshan Caddesi, Bao'an B\u00f6lgesi, Shenzhen \u015eehri, Guangdong Eyaleti, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2013<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Ya\u011fmur suyu toplama sistemi, drenaj sistemi, s\u0131zma sistemi ve entegre s\u0131zma ve drenaj sistemi<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-405d79b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"439\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/DOCTOR-RAIN.jpg\" alt=\"\" class=\"wp-image-4767\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/DOCTOR-RAIN.jpg 750w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/DOCTOR-RAIN-300x176.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/DOCTOR-RAIN-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-01aa6e48\"><h3 class=\"uagb-heading-text\">6. Weiwen Boru Sistemleri (Foshan) Ltd. \u015eti.<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: Kuzey Bilim ve Teknoloji Yolu, Nanhai B\u00f6lgesi, Foshan \u015eehri, Guangdong Eyaleti, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 1995<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Plastik borular, ba\u011flant\u0131 par\u00e7alar\u0131 ve ya\u011fmur suyu toplama mod\u00fclleri<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-83363d3e\"><h3 class=\"uagb-heading-text\">7. Zhejiang Deli Stone Technology Co., Ltd.<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: Shunfeng Yolu, Linping Caddesi, Linping B\u00f6lgesi, Hangzhou \u015eehri, Zhejiang Eyaleti, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2018<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Ya\u011fmur Suyu Toplama ve Kullan\u0131m Y\u00f6netim Sistemi<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ae7f3e79 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/dls.jpg\" alt=\"\" class=\"wp-image-4783\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/dls.jpg 800w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/dls-300x225.jpg 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/dls-768x576.jpg 768w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/dls-16x12.jpg 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b9a106c9\"><h3 class=\"uagb-heading-text\">8. Hebei Shengshi Jinjing Plastik Ltd. \u015eti.<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: No. 8, Chuangye Road, Langfang Geli\u015ftirme B\u00f6lgesi, Hebei Eyaleti, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2014<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Ya\u011fmur suyu ve kanalizasyon i\u00e7in plastik kontrol kuyular\u0131, ileti\u015fim kablo kuyular\u0131, petrol s\u0131z\u0131nt\u0131s\u0131 \u00f6nleme kuyular\u0131, septik tanklar ve entegre ya\u011fmur suyu toplama ve kullan\u0131m sistemleri.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-60ad718e\"><h3 class=\"uagb-heading-text\">9. Yaco Drenaj Teknolojisi (\u015eangay) Ltd. \u015eti.<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: No. 333 Changye Road, Songjiang District, \u015eanghay \u015eehri, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2010<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Y\u00fczey ya\u011fmur suyu y\u00f6netimi, bina drenaj\u0131 ve yap\u0131 malzemeleri<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-35ba5f68 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"786\" height=\"522\" src=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yake.webp\" alt=\"\" class=\"wp-image-4795\" srcset=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yake.webp 786w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yake-300x199.webp 300w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yake-768x510.webp 768w, https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/12\/yake-18x12.webp 18w\" sizes=\"auto, (max-width: 786px) 100vw, 786px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-aeba93f0\"><h3 class=\"uagb-heading-text\">10. Pekin Taining Bilim ve Teknoloji \u0130novasyon Grubu Ltd. \u015eti.<\/h3><\/div>\n\n\n\n<p style=\"font-size:16px\">Konum: Shuangying Bat\u0131 Yolu, Changping Bilim ve Teknoloji Park\u0131, Pekin \u015eehri, \u00c7in<\/p>\n\n\n\n<p style=\"font-size:16px\">Kurulu\u015f tarihi: 2003<\/p>\n\n\n\n<p style=\"font-size:16px\">Ana \u00dcr\u00fcnler: Ya\u011fmur suyu kontrol\u00fc ve entegre kullan\u0131m hizmetlerimiz, konut topluluklar\u0131, belediye yollar\u0131, kentsel ye\u015fil alanlar ve meydanlar ile kentsel su sistemleri ve nehirlerin kapsaml\u0131 ekolojik y\u00f6netimini kapsamaktad\u0131r.<\/p>","protected":false},"excerpt":{"rendered":"<p>China boasts numerous manufacturers of plastic rainwater harvesting tanks, many of whom are experienced and familiar with the technical and [&hellip;]<\/p>","protected":false},"author":1,"featured_media":3835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"unboxed","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Top 10 Plastic rainwater harvesting tank manufacturers in China - Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology<\/title>\n<meta name=\"description\" content=\"China boasts numerous manufacturers of plastic rainwater harvesting tanks, many of whom are experienced and familiar with the technical and quality requirements of various industries.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fshualinkeji.com\/tr\/cindeki-en-iyi-10-plastik-yagmur-suyu-toplama-tanki-ureticisi\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 10 Plastic rainwater harvesting tank manufacturers in China - Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology\" \/>\n<meta property=\"og:description\" content=\"China boasts numerous manufacturers of plastic rainwater harvesting tanks, many of whom are experienced and familiar with the technical and quality requirements of various industries.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fshualinkeji.com\/tr\/cindeki-en-iyi-10-plastik-yagmur-suyu-toplama-tanki-ureticisi\/\" \/>\n<meta property=\"og:site_name\" content=\"Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-15T07:08:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T08:45:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hualinpipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Yazan:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hualinpipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/\"},\"author\":{\"name\":\"Hualinpipe\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/person\\\/4bfd1194fc41e1e42cf86b4da191fde5\"},\"headline\":\"Top 10 Plastic rainwater harvesting tank manufacturers in China\",\"datePublished\":\"2025-12-15T07:08:03+00:00\",\"dateModified\":\"2025-12-15T08:45:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/\"},\"wordCount\":576,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Rainwater-Harvesting-Tanks-60T.jpg\",\"articleSection\":[\"BLOG\"],\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/\",\"name\":\"Top 10 Plastic rainwater harvesting tank manufacturers in China - Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Rainwater-Harvesting-Tanks-60T.jpg\",\"datePublished\":\"2025-12-15T07:08:03+00:00\",\"dateModified\":\"2025-12-15T08:45:25+00:00\",\"description\":\"China boasts numerous manufacturers of plastic rainwater harvesting tanks, many of whom are experienced and familiar with the technical and quality requirements of various industries.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Rainwater-Harvesting-Tanks-60T.jpg\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Rainwater-Harvesting-Tanks-60T.jpg\",\"width\":750,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fshualinkeji.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 10 Plastic rainwater harvesting tank manufacturers in China\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#website\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/\",\"name\":\"Hualin Pipe Technology\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fshualinkeji.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#organization\",\"name\":\"Hualin Pipe Technology\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-logo-1.png\",\"width\":156,\"height\":40,\"caption\":\"Hualin Pipe Technology\"},\"image\":{\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/#\\\/schema\\\/person\\\/4bfd1194fc41e1e42cf86b4da191fde5\",\"name\":\"Hualinpipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655\",\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655\",\"contentUrl\":\"https:\\\/\\\/fshualinkeji.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655\",\"caption\":\"Hualinpipe\"},\"sameAs\":[\"https:\\\/\\\/fshualinkeji.com\"],\"url\":\"https:\\\/\\\/fshualinkeji.com\\\/tr\\\/author\\\/juntongtechoutlook-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c7in'deki en iyi 10 plastik ya\u011fmur suyu toplama tank\u0131 \u00fcreticisi - \u00c7in'deki \u00f6zel HDPE boru \u00fcreticisi - Hualin Pipe Technology","description":"\u00c7in, plastik ya\u011fmur suyu toplama tanklar\u0131 \u00fcreten \u00e7ok say\u0131da \u00fcreticiye sahiptir ve bunlar\u0131n \u00e7o\u011fu \u00e7e\u015fitli end\u00fcstrilerin teknik ve kalite gereksinimlerine a\u015fina ve deneyimlidir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fshualinkeji.com\/tr\/cindeki-en-iyi-10-plastik-yagmur-suyu-toplama-tanki-ureticisi\/","og_locale":"tr_TR","og_type":"article","og_title":"Top 10 Plastic rainwater harvesting tank manufacturers in China - Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology","og_description":"China boasts numerous manufacturers of plastic rainwater harvesting tanks, many of whom are experienced and familiar with the technical and quality requirements of various industries.","og_url":"https:\/\/fshualinkeji.com\/tr\/cindeki-en-iyi-10-plastik-yagmur-suyu-toplama-tanki-ureticisi\/","og_site_name":"Custom Hdpe Pipe Manufacturer in China-Hualin Pipe Technology","article_published_time":"2025-12-15T07:08:03+00:00","article_modified_time":"2025-12-15T08:45:25+00:00","og_image":[{"width":750,"height":563,"url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg","type":"image\/jpeg"}],"author":"Hualinpipe","twitter_card":"summary_large_image","twitter_misc":{"Yazan:":"Hualinpipe","Tahmini okuma s\u00fcresi":"4 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/#article","isPartOf":{"@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/"},"author":{"name":"Hualinpipe","@id":"https:\/\/fshualinkeji.com\/#\/schema\/person\/4bfd1194fc41e1e42cf86b4da191fde5"},"headline":"Top 10 Plastic rainwater harvesting tank manufacturers in China","datePublished":"2025-12-15T07:08:03+00:00","dateModified":"2025-12-15T08:45:25+00:00","mainEntityOfPage":{"@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/"},"wordCount":576,"commentCount":0,"publisher":{"@id":"https:\/\/fshualinkeji.com\/#organization"},"image":{"@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/#primaryimage"},"thumbnailUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg","articleSection":["BLOG"],"inLanguage":"tr","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/","url":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/","name":"\u00c7in'deki en iyi 10 plastik ya\u011fmur suyu toplama tank\u0131 \u00fcreticisi - \u00c7in'deki \u00f6zel HDPE boru \u00fcreticisi - Hualin Pipe Technology","isPartOf":{"@id":"https:\/\/fshualinkeji.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/#primaryimage"},"image":{"@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/#primaryimage"},"thumbnailUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg","datePublished":"2025-12-15T07:08:03+00:00","dateModified":"2025-12-15T08:45:25+00:00","description":"\u00c7in, plastik ya\u011fmur suyu toplama tanklar\u0131 \u00fcreten \u00e7ok say\u0131da \u00fcreticiye sahiptir ve bunlar\u0131n \u00e7o\u011fu \u00e7e\u015fitli end\u00fcstrilerin teknik ve kalite gereksinimlerine a\u015fina ve deneyimlidir.","breadcrumb":{"@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/#primaryimage","url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg","width":750,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/fshualinkeji.com\/top-10-plastic-rainwater-collection-tank-manufacturers-in-china\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fshualinkeji.com\/"},{"@type":"ListItem","position":2,"name":"Top 10 Plastic rainwater harvesting tank manufacturers in China"}]},{"@type":"WebSite","@id":"https:\/\/fshualinkeji.com\/#website","url":"https:\/\/fshualinkeji.com\/","name":"Hualin Boru Teknolojisi","description":"","publisher":{"@id":"https:\/\/fshualinkeji.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fshualinkeji.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/fshualinkeji.com\/#organization","name":"Hualin Boru Teknolojisi","url":"https:\/\/fshualinkeji.com\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/fshualinkeji.com\/#\/schema\/logo\/image\/","url":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/cropped-cropped-logo-1.png","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/06\/cropped-cropped-logo-1.png","width":156,"height":40,"caption":"Hualin Pipe Technology"},"image":{"@id":"https:\/\/fshualinkeji.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fshualinkeji.com\/#\/schema\/person\/4bfd1194fc41e1e42cf86b4da191fde5","name":"Hualinpipe","image":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/fshualinkeji.com\/wp-content\/litespeed\/avatar\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655","url":"https:\/\/fshualinkeji.com\/wp-content\/litespeed\/avatar\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655","contentUrl":"https:\/\/fshualinkeji.com\/wp-content\/litespeed\/avatar\/18a8a2558afaae9326763e051853121a.jpg?ver=1778582655","caption":"Hualinpipe"},"sameAs":["https:\/\/fshualinkeji.com"],"url":"https:\/\/fshualinkeji.com\/tr\/author\/juntongtechoutlook-com\/"}]}},"spectra_custom_meta":{"_edit_lock":["1775026844:1"],"_edit_last":["1"],"_yoast_wpseo_primary_category":["1"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["4"],"_yoast_wpseo_focuskw":["Plastic rainwater harvesting tank"],"_yoast_wpseo_linkdex":["73"],"_thumbnail_id":["3835"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["unboxed"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_yoast_wpseo_metadesc":["China boasts numerous manufacturers of plastic rainwater harvesting tanks, many of whom are experienced and familiar with the technical and quality requirements of various industries."],"_uag_css_file_name":["uag-css-4721.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:63683:\".wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading.uagb-block-f5c6fd14.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f5c6fd14.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f5c6fd14.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f5c6fd14.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86d82dab.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-86d82dab.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86d82dab.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86d82dab.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-00467628 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-00467628 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-00467628 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-00467628 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-00467628 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-00467628{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-00467628 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-00467628{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-8fe91179.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8fe91179.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8fe91179.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8fe91179.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-4a09f600 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a09f600 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a09f600 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a09f600 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a09f600 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a09f600{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a09f600 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4a09f600{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-a2947c1d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a2947c1d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a2947c1d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a2947c1d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-535eec71 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-535eec71 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-535eec71 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-535eec71 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-535eec71 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-535eec71{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-535eec71 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-535eec71{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-0019f075.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0019f075.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0019f075.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0019f075.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c63291b1.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c63291b1.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c63291b1.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c63291b1.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-405d79b5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-405d79b5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-405d79b5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-405d79b5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-405d79b5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-405d79b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-405d79b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-405d79b5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-01aa6e48.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-01aa6e48.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-01aa6e48.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-01aa6e48.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-83363d3e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-83363d3e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-83363d3e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-83363d3e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ae7f3e79 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ae7f3e79 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ae7f3e79 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ae7f3e79 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ae7f3e79 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ae7f3e79{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ae7f3e79 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ae7f3e79{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-b9a106c9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b9a106c9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b9a106c9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b9a106c9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-60ad718e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-60ad718e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-60ad718e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-60ad718e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-35ba5f68 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-35ba5f68 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-35ba5f68 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-35ba5f68 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-35ba5f68 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-35ba5f68{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-35ba5f68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-35ba5f68{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-aeba93f0.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-aeba93f0.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aeba93f0.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aeba93f0.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-00467628{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-00467628 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-00467628{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a09f600{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a09f600 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4a09f600{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-535eec71{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-535eec71 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-535eec71{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-405d79b5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-405d79b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-405d79b5{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ae7f3e79{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ae7f3e79 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ae7f3e79{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-35ba5f68{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-35ba5f68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-35ba5f68{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-00467628{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-00467628 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-00467628{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a09f600{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a09f600 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4a09f600{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-535eec71{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-535eec71 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-535eec71{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-405d79b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-405d79b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-405d79b5{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ae7f3e79{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ae7f3e79 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ae7f3e79{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-35ba5f68{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-35ba5f68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-35ba5f68{padding-top: 0px;padding-bottom: 0px;padding-left: 60px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd25c91f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd25c91f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6cdf3e7d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6cdf3e7d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83d25a5b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-83d25a5b{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dd25c91f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6cdf3e7d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-83d25a5b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd25c91f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd25c91f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dd25c91f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6cdf3e7d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6cdf3e7d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6cdf3e7d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83d25a5b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83d25a5b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-83d25a5b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-83d25a5b.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-83d25a5b.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92b3da43 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-92b3da43{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2 .uagb-heading-text{font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;font-family: \"Poppins\";text-decoration: !important;line-height: em;color: #727579;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child{font-family: \"Poppins\";text-decoration: !important;font-size: 14px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-32ea5357.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-32ea5357.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-e403deab.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-e403deab.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-767efdcf.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-767efdcf.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c9e2a33c.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c9e2a33c.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0ce47b4.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0ce47b4.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c374f4a6.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c374f4a6.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-92b3da43{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-92b3da43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92b3da43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-92b3da43{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-93c1afa2.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-5a8fcfc0.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15aa5f8a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-15aa5f8a{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d .uagb-heading-text{font-family: \"Poppins\";font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;text-decoration: !important;line-height: em;color: #727579;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 14px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-2a807afe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2a807afe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4b5bca07.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4b5bca07.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4f7e8fc.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4f7e8fc.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-3899fefe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-3899fefe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-29ce129e.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-29ce129e.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-15aa5f8a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-15aa5f8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15aa5f8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-15aa5f8a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-a488e92d.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-1e088060 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-1e088060 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-1e088060.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca12eada .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ca12eada{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33 .uagb-heading-text{font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 16px;text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 16px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dbb24b54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-acb20953.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #727579 !important;color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color: #727579 !important;}.uagb-block-8c7dcd54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ca12eada{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca12eada{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca12eada > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ca12eada{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-e6801e33.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-090ee7be .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-090ee7be .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-090ee7be.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f72d8ab .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1290px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{box-shadow: 0px 4px 12px 0px #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-style: solid;border-color: #dadbdd;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #dadbdd;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f72d8ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f72d8ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f72d8ab.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6f72d8ab{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #dadbdd;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:7:{i:0;s:14:\"core\/paragraph\";i:1;s:21:\"uagb\/advanced-heading\";i:2;s:14:\"uagb\/container\";i:3;s:10:\"core\/image\";i:4;s:14:\"uagb\/icon-list\";i:5;s:20:\"uagb\/icon-list-child\";i:6;s:21:\"fluentfom\/guten-block\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1778649440;s:6:\"gfonts\";a:1:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg",750,563,false],"thumbnail":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T-150x150.jpg",150,150,true],"medium":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T-300x225.jpg",300,225,true],"medium_large":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg",750,563,false],"large":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg",750,563,false],"1536x1536":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg",750,563,false],"2048x2048":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T.jpg",750,563,false],"trp-custom-language-flag":["https:\/\/fshualinkeji.com\/wp-content\/uploads\/2025\/10\/Rainwater-Harvesting-Tanks-60T-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"Hualinpipe","author_link":"https:\/\/fshualinkeji.com\/tr\/author\/juntongtechoutlook-com\/"},"uagb_comment_info":0,"uagb_excerpt":"China boasts numerous manufacturers of plastic rainwater harvesting tanks, many of whom are experienced and familiar with the technical and [&hellip;]","_links":{"self":[{"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/posts\/4721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/comments?post=4721"}],"version-history":[{"count":54,"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/posts\/4721\/revisions"}],"predecessor-version":[{"id":4804,"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/posts\/4721\/revisions\/4804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/media\/3835"}],"wp:attachment":[{"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/media?parent=4721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/categories?post=4721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fshualinkeji.com\/tr\/wp-json\/wp\/v2\/tags?post=4721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}